{"id":186117,"date":"2025-11-25T14:57:09","date_gmt":"2025-11-25T20:57:09","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=186117"},"modified":"2025-11-25T14:57:09","modified_gmt":"2025-11-25T20:57:09","slug":"cordero-hernandez-conquistan-el-tall-pines-en-canada","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/","title":{"rendered":"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Con \u00e9xito se realiz\u00f3 la edici\u00f3n 28 del Rally Tall Pines en donde los paisajes que inicialmente se pretend\u00edan de tierra tomaron por sorpresa a las tripulaciones que participaron en \u00e9l, los \u00e1rboles y los caminos se pintaron de blanco.<\/p>\n<p style=\"text-align: justify;\">Cordero lleg\u00f3 con una meta clara de recuperar la punta del campeonato canadiense de rallismo a tan solo un rally de culminar la temporada 2025.<\/p>\n<p style=\"text-align: justify;\">El comienzo fue bueno para la dupla Cordero-Hern\u00e1ndez en donde r\u00e1pidamente se colocaron detr\u00e1s de Sim\u00f3n Vicente pero al concluir el primer servicio el ritmo mejor\u00f3 y la dupla mexicana gan\u00f3 todos los tramos subsecuentes hasta terminar el rally, algo que es sumamente impresionante puesto que Cordero y Hern\u00e1ndez ven\u00edan mentalizados para competir sobre tierra, pero la nieve fue un factor sorpresa que jug\u00f3 a su favor.<\/p>\n<p style=\"text-align: justify;\">Cordero ha recuperado la punta del campeonato canadiense y todo se definir\u00e1 en el Big White Rally.<\/p>\n<p style=\"text-align: justify;\">Ahora tocar\u00e1 esperar tan solo 10 d\u00edas para llevar a cabo la conclusi\u00f3n de esta temporada 2025 en el CRC en donde el Big White Rally ser\u00e1 el escenario para definir al campe\u00f3n, Cordero y Hern\u00e1ndez tendr\u00e1n que reafirmar sus conocimientos sobre conducci\u00f3n en nieve y perfeccionarlos puesto que esta competencia se identifica por esto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Con \u00e9xito se realiz\u00f3 la edici\u00f3n 28 del Rally Tall Pines en donde los paisajes que inicialmente se pretend\u00edan de tierra tomaron por sorpresa a las tripulaciones que participaron en \u00e9l, los \u00e1rboles y los caminos se pintaron de blanco. Cordero lleg\u00f3 con una meta clara de recuperar la punta del campeonato canadiense de rallismo a tan solo un rally de culminar la temporada 2025. El comienzo fue bueno para la dupla Cordero-Hern\u00e1ndez en donde r\u00e1pidamente se colocaron detr\u00e1s de Sim\u00f3n Vicente pero al concluir el primer servicio el ritmo mejor\u00f3 y la dupla mexicana gan\u00f3 todos los tramos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":186119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-186117","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1 - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1 - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.- Con \u00e9xito se realiz\u00f3 la edici\u00f3n 28 del Rally Tall Pines en donde los paisajes que inicialmente se pretend\u00edan de tierra tomaron por sorpresa a las tripulaciones que participaron en \u00e9l, los \u00e1rboles y los caminos se pintaron de blanco. Cordero lleg\u00f3 con una meta clara de recuperar la punta del campeonato canadiense de rallismo a tan solo un rally de culminar la temporada 2025. El comienzo fue bueno para la dupla Cordero-Hern\u00e1ndez en donde r\u00e1pidamente se colocaron detr\u00e1s de Sim\u00f3n Vicente pero al concluir el primer servicio el ritmo mejor\u00f3 y la dupla mexicana gan\u00f3 todos los tramos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T20:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/11\/Froi01Rally.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1\",\"datePublished\":\"2025-11-25T20:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Froi01Rally.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/\",\"name\":\"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1 - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Froi01Rally.jpg\",\"datePublished\":\"2025-11-25T20:57:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Froi01Rally.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Froi01Rally.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/cordero-hernandez-conquistan-el-tall-pines-en-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1 - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/","og_locale":"es_ES","og_type":"article","og_title":"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1 - Canal 7 SLP - 2025","og_description":"SLP.- Con \u00e9xito se realiz\u00f3 la edici\u00f3n 28 del Rally Tall Pines en donde los paisajes que inicialmente se pretend\u00edan de tierra tomaron por sorpresa a las tripulaciones que participaron en \u00e9l, los \u00e1rboles y los caminos se pintaron de blanco. Cordero lleg\u00f3 con una meta clara de recuperar la punta del campeonato canadiense de rallismo a tan solo un rally de culminar la temporada 2025. El comienzo fue bueno para la dupla Cordero-Hern\u00e1ndez en donde r\u00e1pidamente se colocaron detr\u00e1s de Sim\u00f3n Vicente pero al concluir el primer servicio el ritmo mejor\u00f3 y la dupla mexicana gan\u00f3 todos los tramos [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-11-25T20:57:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/11\/Froi01Rally.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1","datePublished":"2025-11-25T20:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/"},"wordCount":225,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/11\/Froi01Rally.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/","url":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/","name":"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1 - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/11\/Froi01Rally.jpg","datePublished":"2025-11-25T20:57:09+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/11\/Froi01Rally.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/11\/Froi01Rally.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/cordero-hernandez-conquistan-el-tall-pines-en-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Cordero \u2013 Hern\u00e1ndez conquistan el Tall Pines en Canad\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/186117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=186117"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/186117\/revisions"}],"predecessor-version":[{"id":186120,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/186117\/revisions\/186120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/186119"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=186117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=186117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=186117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}