{"id":173115,"date":"2025-07-10T13:26:38","date_gmt":"2025-07-10T19:26:38","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=173115"},"modified":"2025-07-10T13:26:38","modified_gmt":"2025-07-10T19:26:38","slug":"monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/","title":{"rendered":"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- Se prev\u00e9n lluvias muy fuertes en los estados de Sonora, Sinaloa, Chihuahua, Durango y Nayarit debido al monz\u00f3n mexicano que afecta el noroeste del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n se anticipan lluvias aisladas en Baja California y Baja California Sur.<\/p>\n<p style=\"text-align: justify;\">Una circulaci\u00f3n cicl\u00f3nica en el noreste generar\u00e1 lluvias fuertes en San Luis Potos\u00ed, Tamaulipas y Nuevo Le\u00f3n, as\u00ed como chubascos en Coahuila.<\/p>\n<p style=\"text-align: justify;\">Un canal de baja presi\u00f3n en la Mesa del Norte y la Mesa Central, junto con inestabilidad atmosf\u00e9rica, ocasionar\u00e1 lluvias fuertes en Zacatecas, Aguascalientes, Guanajuato, Estado de M\u00e9xico, Puebla, Guerrero, Oaxaca y Veracruz, adem\u00e1s de chubascos en Quer\u00e9taro, Hidalgo, Ciudad de M\u00e9xico, Morelos y Tlaxcala.<\/p>\n<p style=\"text-align: justify;\">La onda tropical n\u00fam. 10, que se desplaza sobre el occidente, provocar\u00e1 lluvias fuertes en Michoac\u00e1n, Colima y Jalisco.<\/p>\n<p style=\"text-align: justify;\">En el sureste, otro canal de baja presi\u00f3n generar\u00e1 lluvias en Chiapas y chubascos en Tabasco.<\/p>\n<p style=\"text-align: justify;\">Se espera que las lluvias vengan acompa\u00f1adas de descargas el\u00e9ctricas, rachas de viento y posibles granizadas, lo que podr\u00eda causar encharcamientos, deslaves e inundaciones.<\/p>\n<p style=\"text-align: justify;\">El ambiente ser\u00e1 c\u00e1lido a caluroso en gran parte del pa\u00eds, con temperaturas que podr\u00edan superar los 45 \u00b0C en zonas de Baja California y Sonora.<\/p>\n<p style=\"text-align: justify;\">Pron\u00f3stico de lluvias:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Lluvias muy fuertes (50 a 75 mm): Sonora, Sinaloa, Chihuahua, Durango, Nayarit.<\/li>\n<li>Lluvias fuertes (25 a 50 mm): Nuevo Le\u00f3n, San Luis Potos\u00ed, Zacatecas, Aguascalientes, Tamaulipas, Veracruz, Jalisco, Colima, Michoac\u00e1n, Guanajuato, Puebla, Estado de M\u00e9xico, Guerrero, Oaxaca, Chiapas, Yucat\u00e1n.<\/li>\n<li>Chubascos (5 a 25 mm): Coahuila, Quer\u00e9taro, Hidalgo, Tlaxcala, Morelos, Ciudad de M\u00e9xico, Tabasco, Campeche, Quintana Roo.<\/li>\n<li>Lluvias aisladas (0.1 a 5 mm): Baja California, Baja California Sur.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Pron\u00f3stico de temperaturas m\u00e1ximas:<\/p>\n<ul style=\"text-align: justify;\">\n<li>M\u00e1s de 45 \u00b0C: Baja California (noreste), Sonora (noroeste).<\/li>\n<li>40 a 45 \u00b0C: Chihuahua (norte).<\/li>\n<li>35 a 40 \u00b0C: Baja California Sur, Sinaloa, Coahuila, Nuevo Le\u00f3n, Nayarit, Colima, Michoac\u00e1n, Guerrero, Oaxaca, Tamaulipas, Tabasco, Campeche, Yucat\u00e1n.<\/li>\n<li>30 a 35 \u00b0C: San Luis Potos\u00ed, Durango, Jalisco, Guanajuato, Quer\u00e9taro, Hidalgo, Puebla, Morelos, Chiapas, Veracruz, Quintana Roo.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Pron\u00f3stico de viento:<\/p>\n<ul style=\"text-align: justify;\">\n<li>30 a 40 km\/h con rachas de 50 a 70 km\/h: Golfo de California, Baja California (costas), Sonora (costa norte), Tamaulipas (noroeste), Oaxaca (istmo y golfo de Tehuantepec).<\/li>\n<li>20 a 30 km\/h con rachas de 40 a 60 km\/h: Sinaloa (noroeste), Chihuahua, Coahuila, Nuevo Le\u00f3n, San Luis Potos\u00ed, Estado de M\u00e9xico (noreste), Hidalgo, Puebla, Tabasco, Chiapas, Campeche, Yucat\u00e1n, Quintana Roo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- Se prev\u00e9n lluvias muy fuertes en los estados de Sonora, Sinaloa, Chihuahua, Durango y Nayarit debido al monz\u00f3n mexicano que afecta el noroeste del pa\u00eds. Tambi\u00e9n se anticipan lluvias aisladas en Baja California y Baja California Sur. Una circulaci\u00f3n cicl\u00f3nica en el noreste generar\u00e1 lluvias fuertes en San Luis Potos\u00ed, Tamaulipas y Nuevo Le\u00f3n, as\u00ed como chubascos en Coahuila. Un canal de baja presi\u00f3n en la Mesa del Norte y la Mesa Central, junto con inestabilidad atmosf\u00e9rica, ocasionar\u00e1 lluvias fuertes en Zacatecas, Aguascalientes, Guanajuato, Estado de M\u00e9xico, Puebla, Guerrero, Oaxaca y Veracruz, adem\u00e1s de chubascos en Quer\u00e9taro, Hidalgo, Ciudad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":173116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-173115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- Se prev\u00e9n lluvias muy fuertes en los estados de Sonora, Sinaloa, Chihuahua, Durango y Nayarit debido al monz\u00f3n mexicano que afecta el noroeste del pa\u00eds. Tambi\u00e9n se anticipan lluvias aisladas en Baja California y Baja California Sur. Una circulaci\u00f3n cicl\u00f3nica en el noreste generar\u00e1 lluvias fuertes en San Luis Potos\u00ed, Tamaulipas y Nuevo Le\u00f3n, as\u00ed como chubascos en Coahuila. Un canal de baja presi\u00f3n en la Mesa del Norte y la Mesa Central, junto con inestabilidad atmosf\u00e9rica, ocasionar\u00e1 lluvias fuertes en Zacatecas, Aguascalientes, Guanajuato, Estado de M\u00e9xico, Puebla, Guerrero, Oaxaca y Veracruz, adem\u00e1s de chubascos en Quer\u00e9taro, Hidalgo, Ciudad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T19:26:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/07\/01-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds\",\"datePublished\":\"2025-07-10T19:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/01-9.jpg\",\"articleSection\":[\"CLIMA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/\",\"name\":\"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/01-9.jpg\",\"datePublished\":\"2025-07-10T19:26:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/01-9.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/01-9.jpg\",\"width\":900,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/","og_locale":"es_ES","og_type":"article","og_title":"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds - Canal 7 SLP - 2025","og_description":"M\u00e9xico.- Se prev\u00e9n lluvias muy fuertes en los estados de Sonora, Sinaloa, Chihuahua, Durango y Nayarit debido al monz\u00f3n mexicano que afecta el noroeste del pa\u00eds. Tambi\u00e9n se anticipan lluvias aisladas en Baja California y Baja California Sur. Una circulaci\u00f3n cicl\u00f3nica en el noreste generar\u00e1 lluvias fuertes en San Luis Potos\u00ed, Tamaulipas y Nuevo Le\u00f3n, as\u00ed como chubascos en Coahuila. Un canal de baja presi\u00f3n en la Mesa del Norte y la Mesa Central, junto con inestabilidad atmosf\u00e9rica, ocasionar\u00e1 lluvias fuertes en Zacatecas, Aguascalientes, Guanajuato, Estado de M\u00e9xico, Puebla, Guerrero, Oaxaca y Veracruz, adem\u00e1s de chubascos en Quer\u00e9taro, Hidalgo, Ciudad [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-07-10T19:26:38+00:00","og_image":[{"width":900,"height":599,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/07\/01-9.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds","datePublished":"2025-07-10T19:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/"},"wordCount":413,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/07\/01-9.jpg","articleSection":["CLIMA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/","url":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/","name":"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/07\/01-9.jpg","datePublished":"2025-07-10T19:26:38+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/07\/01-9.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/07\/01-9.jpg","width":900,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/monzon-mexicano-desata-fuertes-lluvias-en-el-noroeste-del-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Monz\u00f3n mexicano desata fuertes lluvias en el noroeste del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/173115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=173115"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/173115\/revisions"}],"predecessor-version":[{"id":173117,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/173115\/revisions\/173117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/173116"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=173115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=173115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=173115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}