{"id":171956,"date":"2025-06-27T18:09:09","date_gmt":"2025-06-28T00:09:09","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=171956"},"modified":"2025-06-27T18:09:09","modified_gmt":"2025-06-28T00:09:09","slug":"comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/","title":{"rendered":"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS"},"content":{"rendered":"<p style=\"text-align: justify;\">SGS.- De cara al informe de actividades 2025 del Ayuntamiento de Soledad de Graciano S\u00e1nchez la Contralor\u00eda Municipal vigilar\u00e1 las diversas \u00e1reas de la administraci\u00f3n mediante \u201cComit\u00e9s de Control y Desempe\u00f1o Institucional\u201d, as\u00ed lo hizo saber la contralora, Beatriz Carranza Betancourt.<\/p>\n<p style=\"text-align: justify;\">\u201cSe llaman Comit\u00e9s de Control y Desempe\u00f1o Municipal, tenemos conformados 12 comit\u00e9s incluidos el del municipio y pues son comit\u00e9s estrat\u00e9gicos para tener un sistema de control interno en primer lugar y una correcta administraci\u00f3n de riesgos\u201d.<\/p>\n<p style=\"text-align: justify;\">Se vigilar\u00e1 que se cumpla con los planes de desarrollo.<\/p>\n<p style=\"text-align: justify;\">\u201cNuestra base para partir pues es el Plan Municipal de Desarrollo 2024-2027 y tenemos que acciones en cada \u00e1rea programadas y tenemos que dar cumplimiento a estas acciones conforme vayan avanzando los tiempos\u201d.<\/p>\n<p style=\"text-align: justify;\">Se detectar\u00e1n fallas.<\/p>\n<p style=\"text-align: justify;\">\u201cSi hay alguna debilidad, alg\u00fan problema de corrupci\u00f3n, alguna deficiencia o alguna irregularidad pues prevenirla con tiempo, si no se puede prevenir la asumimos y la tratamos de la mejor forma\u201d.<\/p>\n<p style=\"text-align: justify;\">Durante las sesiones se desglosar\u00e1 el trabajo llevado a cabo por cada direcci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cEllos van a presentar avances en su Plan Municipal de Desarrollo, tambi\u00e9n vamos a ver temas en c\u00f3mo van en transparencia, si hay alg\u00fan juicio pendiente que no se haya atendido, c\u00f3mo se est\u00e1 ejerciendo el recurso, si hay alg\u00fan tema grave en el \u00e1rea que tengamos que tratar\u201d.<\/p>\n<p style=\"text-align: justify;\">Los comit\u00e9s estar\u00e1n integrados por un presidente, un vocal ejecutivo y vocales que sesionar\u00e1n a partir de la primera quincena del mes de julio.<\/p>\n<p>Por: Juan Carlos Contreras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SGS.- De cara al informe de actividades 2025 del Ayuntamiento de Soledad de Graciano S\u00e1nchez la Contralor\u00eda Municipal vigilar\u00e1 las diversas \u00e1reas de la administraci\u00f3n mediante \u201cComit\u00e9s de Control y Desempe\u00f1o Institucional\u201d, as\u00ed lo hizo saber la contralora, Beatriz Carranza Betancourt. \u201cSe llaman Comit\u00e9s de Control y Desempe\u00f1o Municipal, tenemos conformados 12 comit\u00e9s incluidos el del municipio y pues son comit\u00e9s estrat\u00e9gicos para tener un sistema de control interno en primer lugar y una correcta administraci\u00f3n de riesgos\u201d. Se vigilar\u00e1 que se cumpla con los planes de desarrollo. \u201cNuestra base para partir pues es el Plan Municipal de Desarrollo 2024-2027 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":171958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[512,5,45],"tags":[],"class_list":["post-171956","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayosgs","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SGS.- De cara al informe de actividades 2025 del Ayuntamiento de Soledad de Graciano S\u00e1nchez la Contralor\u00eda Municipal vigilar\u00e1 las diversas \u00e1reas de la administraci\u00f3n mediante \u201cComit\u00e9s de Control y Desempe\u00f1o Institucional\u201d, as\u00ed lo hizo saber la contralora, Beatriz Carranza Betancourt. \u201cSe llaman Comit\u00e9s de Control y Desempe\u00f1o Municipal, tenemos conformados 12 comit\u00e9s incluidos el del municipio y pues son comit\u00e9s estrat\u00e9gicos para tener un sistema de control interno en primer lugar y una correcta administraci\u00f3n de riesgos\u201d. Se vigilar\u00e1 que se cumpla con los planes de desarrollo. \u201cNuestra base para partir pues es el Plan Municipal de Desarrollo 2024-2027 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-28T00:09:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/06\/Poky03ContraloraInforme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS\",\"datePublished\":\"2025-06-28T00:09:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/\"},\"wordCount\":284,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Poky03ContraloraInforme.jpg\",\"articleSection\":[\"AYOSGS\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/\",\"name\":\"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Poky03ContraloraInforme.jpg\",\"datePublished\":\"2025-06-28T00:09:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Poky03ContraloraInforme.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Poky03ContraloraInforme.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/","og_locale":"es_ES","og_type":"article","og_title":"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS - Canal 7 SLP - 2025","og_description":"SGS.- De cara al informe de actividades 2025 del Ayuntamiento de Soledad de Graciano S\u00e1nchez la Contralor\u00eda Municipal vigilar\u00e1 las diversas \u00e1reas de la administraci\u00f3n mediante \u201cComit\u00e9s de Control y Desempe\u00f1o Institucional\u201d, as\u00ed lo hizo saber la contralora, Beatriz Carranza Betancourt. \u201cSe llaman Comit\u00e9s de Control y Desempe\u00f1o Municipal, tenemos conformados 12 comit\u00e9s incluidos el del municipio y pues son comit\u00e9s estrat\u00e9gicos para tener un sistema de control interno en primer lugar y una correcta administraci\u00f3n de riesgos\u201d. Se vigilar\u00e1 que se cumpla con los planes de desarrollo. \u201cNuestra base para partir pues es el Plan Municipal de Desarrollo 2024-2027 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-06-28T00:09:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/06\/Poky03ContraloraInforme.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS","datePublished":"2025-06-28T00:09:09+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/"},"wordCount":284,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/06\/Poky03ContraloraInforme.jpg","articleSection":["AYOSGS","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/","url":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/","name":"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/06\/Poky03ContraloraInforme.jpg","datePublished":"2025-06-28T00:09:09+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/06\/Poky03ContraloraInforme.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/06\/Poky03ContraloraInforme.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/comites-de-control-y-desempeno-institucional-vigilaran-direcciones-de-cara-al-informe-de-sgs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Comit\u00e9s de Control y Desempe\u00f1o Institucional vigilar\u00e1n direcciones de cara al informe de SGS"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/171956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=171956"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/171956\/revisions"}],"predecessor-version":[{"id":171959,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/171956\/revisions\/171959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/171958"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=171956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=171956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=171956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}