{"id":168507,"date":"2025-05-26T15:09:37","date_gmt":"2025-05-26T21:09:37","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=168507"},"modified":"2025-05-26T15:09:37","modified_gmt":"2025-05-26T21:09:37","slug":"seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/","title":{"rendered":"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- El representativo potosino de gimnasia art\u00edstica participar\u00e1 del 27 de mayo al 3 de junio en el Campeonato Nacional de Gimnasia Art\u00edstica Varonil y Femenil 2025 en Guadalajara, Jalisco.<\/p>\n<p style=\"text-align: justify;\">Este evento es convocado por la Federaci\u00f3n Mexicana de Gimnasia Art\u00edstica y contar\u00e1 con la participaci\u00f3n de los mejores exponentes en todas las pruebas.<\/p>\n<p style=\"text-align: justify;\">En el caso del representativo potosino, dicha delegaci\u00f3n es representada por cinco academias, tal es el caso de Aregym, UNI, Gydman y Kim, totalizando 46 exponentes entre los cuales se encuentran tambi\u00e9n entrenadores y jueces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- El representativo potosino de gimnasia art\u00edstica participar\u00e1 del 27 de mayo al 3 de junio en el Campeonato Nacional de Gimnasia Art\u00edstica Varonil y Femenil 2025 en Guadalajara, Jalisco. Este evento es convocado por la Federaci\u00f3n Mexicana de Gimnasia Art\u00edstica y contar\u00e1 con la participaci\u00f3n de los mejores exponentes en todas las pruebas. En el caso del representativo potosino, dicha delegaci\u00f3n es representada por cinco academias, tal es el caso de Aregym, UNI, Gydman y Kim, totalizando 46 exponentes entre los cuales se encuentran tambi\u00e9n entrenadores y jueces.<\/p>\n","protected":false},"author":2,"featured_media":168518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-168507","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.- El representativo potosino de gimnasia art\u00edstica participar\u00e1 del 27 de mayo al 3 de junio en el Campeonato Nacional de Gimnasia Art\u00edstica Varonil y Femenil 2025 en Guadalajara, Jalisco. Este evento es convocado por la Federaci\u00f3n Mexicana de Gimnasia Art\u00edstica y contar\u00e1 con la participaci\u00f3n de los mejores exponentes en todas las pruebas. En el caso del representativo potosino, dicha delegaci\u00f3n es representada por cinco academias, tal es el caso de Aregym, UNI, Gydman y Kim, totalizando 46 exponentes entre los cuales se encuentran tambi\u00e9n entrenadores y jueces.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-26T21:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Froi03Gimnasia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio\",\"datePublished\":\"2025-05-26T21:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/\"},\"wordCount\":106,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Froi03Gimnasia.jpg\",\"articleSection\":[\"DEPORTES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/\",\"name\":\"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Froi03Gimnasia.jpg\",\"datePublished\":\"2025-05-26T21:09:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Froi03Gimnasia.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Froi03Gimnasia.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/","og_locale":"es_ES","og_type":"article","og_title":"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio - Canal 7 SLP - 2025","og_description":"SLP.- El representativo potosino de gimnasia art\u00edstica participar\u00e1 del 27 de mayo al 3 de junio en el Campeonato Nacional de Gimnasia Art\u00edstica Varonil y Femenil 2025 en Guadalajara, Jalisco. Este evento es convocado por la Federaci\u00f3n Mexicana de Gimnasia Art\u00edstica y contar\u00e1 con la participaci\u00f3n de los mejores exponentes en todas las pruebas. En el caso del representativo potosino, dicha delegaci\u00f3n es representada por cinco academias, tal es el caso de Aregym, UNI, Gydman y Kim, totalizando 46 exponentes entre los cuales se encuentran tambi\u00e9n entrenadores y jueces.","og_url":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-05-26T21:09:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Froi03Gimnasia.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio","datePublished":"2025-05-26T21:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/"},"wordCount":106,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Froi03Gimnasia.jpg","articleSection":["DEPORTES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/","url":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/","name":"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Froi03Gimnasia.jpg","datePublished":"2025-05-26T21:09:37+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Froi03Gimnasia.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Froi03Gimnasia.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/seleccion-de-gimnasia-al-campeonato-nacional-del-27-de-mayo-al-3-de-junio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Selecci\u00f3n de Gimnasia al Campeonato Nacional del 27 de mayo al 3 de junio"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/168507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=168507"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/168507\/revisions"}],"predecessor-version":[{"id":168519,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/168507\/revisions\/168519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/168518"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=168507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=168507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=168507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}