{"id":165063,"date":"2025-05-02T18:30:43","date_gmt":"2025-05-03T00:30:43","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=165063"},"modified":"2025-05-02T18:30:43","modified_gmt":"2025-05-03T00:30:43","slug":"arrancara-en-sgs-programa-de-empleo-temporal","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/","title":{"rendered":"Arrancar\u00e1 en SGS programa de empleo temporal"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SGS.- Durante entrevista con medios de comunicaci\u00f3n, el presidente municipal de Soledad de Graciano S\u00e1nchez, Juan Manuel Navarro Mu\u00f1iz, habl\u00f3 sobre el pr\u00f3ximo arranque del programa de empleo temporal para j\u00f3venes soledenses.<\/span><\/p>\n<p style=\"text-align: justify;\">\u201cMira es un programa que ya lo hicimos en Soledad hace tiempo (\u2026) es remodelar todo el entorno, todas las plazas, pintar los condominios, es decir, se emplea al personal de la colonia\u201d.<\/p>\n<p style=\"text-align: justify;\">La finalidad es poner en acci\u00f3n a las juventudes.<\/p>\n<p style=\"text-align: justify;\">\u201cEmpleas a los chavos banda o no banda de aqu\u00ed de la colonia, les pagas por metro pintado, por metro cuadrado que ellos trabajen, pagamos el fin de semana, empleamos a los chavos (\u2026) esperamos arrancarlo en un mes m\u00e1s o menos\u201d.<\/p>\n<p style=\"text-align: justify;\">Se supervisar\u00e1n las acciones.<\/p>\n<p>\u201cNosotros pensamos en 100 personas aproximadamente, lo queremos hacer pronto, lo queremos hacer r\u00e1pido, lo queremos hacer con supervisi\u00f3n de la Direcci\u00f3n de Infraestructura de Soledad\u201d.<\/p>\n<p style=\"text-align: justify;\">En primera instancia la colonia Hogares Ferrocarrileros ser\u00eda el primer punto a intervenir.<\/p>\n<p style=\"text-align: justify;\">\u201cVamos a arrancar ahorita aqu\u00ed en Hogares, es un compromiso que ya ten\u00edamos con la gente de Hogares (\u2026) ya de ah\u00ed ver\u00edamos la forma de ir a otros lugares\u201d.<\/p>\n<p style=\"text-align: justify;\">Al momento se est\u00e1 en an\u00e1lisis para saber cu\u00e1ntos metros cuadrados se podr\u00e1 alcanzar a remozar en el municipio.<\/p>\n<p style=\"text-align: justify;\">\u201cSin duda les va a beneficiar en el tema de la plusval\u00eda (\u2026) pero tambi\u00e9n les cambias el entorno, les cambias una mejor calidad de vida\u201d.<\/p>\n<p style=\"text-align: justify;\">Por: Juan Carlos Contreras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SGS.- Durante entrevista con medios de comunicaci\u00f3n, el presidente municipal de Soledad de Graciano S\u00e1nchez, Juan Manuel Navarro Mu\u00f1iz, habl\u00f3 sobre el pr\u00f3ximo arranque del programa de empleo temporal para j\u00f3venes soledenses. \u201cMira es un programa que ya lo hicimos en Soledad hace tiempo (\u2026) es remodelar todo el entorno, todas las plazas, pintar los condominios, es decir, se emplea al personal de la colonia\u201d. La finalidad es poner en acci\u00f3n a las juventudes. \u201cEmpleas a los chavos banda o no banda de aqu\u00ed de la colonia, les pagas por metro pintado, por metro cuadrado que ellos trabajen, pagamos el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":165079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[512,5,45],"tags":[],"class_list":["post-165063","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayosgs","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arrancar\u00e1 en SGS programa de empleo temporal - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrancar\u00e1 en SGS programa de empleo temporal - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SGS.- Durante entrevista con medios de comunicaci\u00f3n, el presidente municipal de Soledad de Graciano S\u00e1nchez, Juan Manuel Navarro Mu\u00f1iz, habl\u00f3 sobre el pr\u00f3ximo arranque del programa de empleo temporal para j\u00f3venes soledenses. \u201cMira es un programa que ya lo hicimos en Soledad hace tiempo (\u2026) es remodelar todo el entorno, todas las plazas, pintar los condominios, es decir, se emplea al personal de la colonia\u201d. La finalidad es poner en acci\u00f3n a las juventudes. \u201cEmpleas a los chavos banda o no banda de aqu\u00ed de la colonia, les pagas por metro pintado, por metro cuadrado que ellos trabajen, pagamos el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-03T00:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Poky04EmpleoTemporal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Arrancar\u00e1 en SGS programa de empleo temporal\",\"datePublished\":\"2025-05-03T00:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Poky04EmpleoTemporal.jpg\",\"articleSection\":[\"AYOSGS\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/\",\"name\":\"Arrancar\u00e1 en SGS programa de empleo temporal - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Poky04EmpleoTemporal.jpg\",\"datePublished\":\"2025-05-03T00:30:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Poky04EmpleoTemporal.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Poky04EmpleoTemporal.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/arrancara-en-sgs-programa-de-empleo-temporal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrancar\u00e1 en SGS programa de empleo temporal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrancar\u00e1 en SGS programa de empleo temporal - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/","og_locale":"es_ES","og_type":"article","og_title":"Arrancar\u00e1 en SGS programa de empleo temporal - Canal 7 SLP - 2025","og_description":"SGS.- Durante entrevista con medios de comunicaci\u00f3n, el presidente municipal de Soledad de Graciano S\u00e1nchez, Juan Manuel Navarro Mu\u00f1iz, habl\u00f3 sobre el pr\u00f3ximo arranque del programa de empleo temporal para j\u00f3venes soledenses. \u201cMira es un programa que ya lo hicimos en Soledad hace tiempo (\u2026) es remodelar todo el entorno, todas las plazas, pintar los condominios, es decir, se emplea al personal de la colonia\u201d. La finalidad es poner en acci\u00f3n a las juventudes. \u201cEmpleas a los chavos banda o no banda de aqu\u00ed de la colonia, les pagas por metro pintado, por metro cuadrado que ellos trabajen, pagamos el [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-05-03T00:30:43+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Poky04EmpleoTemporal.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Arrancar\u00e1 en SGS programa de empleo temporal","datePublished":"2025-05-03T00:30:43+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/"},"wordCount":259,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Poky04EmpleoTemporal.jpg","articleSection":["AYOSGS","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/","url":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/","name":"Arrancar\u00e1 en SGS programa de empleo temporal - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Poky04EmpleoTemporal.jpg","datePublished":"2025-05-03T00:30:43+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Poky04EmpleoTemporal.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/05\/Poky04EmpleoTemporal.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/arrancara-en-sgs-programa-de-empleo-temporal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Arrancar\u00e1 en SGS programa de empleo temporal"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/165063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=165063"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/165063\/revisions"}],"predecessor-version":[{"id":165080,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/165063\/revisions\/165080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/165079"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=165063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=165063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=165063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}