{"id":161923,"date":"2025-03-30T14:15:27","date_gmt":"2025-03-30T20:15:27","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=161923"},"modified":"2025-03-30T14:18:26","modified_gmt":"2025-03-30T20:18:26","slug":"varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/","title":{"rendered":"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SGS.- Debido a la temporada de calor que ha comenzado, siete centros educativos han solicitado techado en Soledad de Graciano S\u00e1nchez, as\u00ed lo expuso la directora de Educaci\u00f3n, Velia Guadalupe Castro Granja.<\/span><\/p>\n<p style=\"text-align: justify;\">\u201cEn techados hay algunos que s\u00ed cuentan con techado hay algunas que no por las cuales nos han estado solicitando el apoyo de infraestructura en ese sentido de techado (\u2026) como tal a la Direcci\u00f3n de Educaci\u00f3n \u00fanicamente han llegado siete solicitudes\u201d.<\/p>\n<p style=\"text-align: justify;\">Asever\u00f3 que se visitar\u00e1 la totalidad de las escuelas en Soledad para verificar cu\u00e1ntas requieren de mejora.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos visitando por ah\u00ed las escuelas para levantar todos estos informes que por indicaciones del licenciado Juan Manuel Navarro, el presidente municipal nos est\u00e1 pidiendo que tomemos cartas en el asunto inform\u00e1ndole pues cu\u00e1ntas son las escuelas que s\u00ed cuentan con la infraestructura necesaria\u201d.<\/p>\n<p style=\"text-align: justify;\">Otra carencia es en el suministro de agua potable.<\/p>\n<p style=\"text-align: justify;\">\u201cHasta ahorita s\u00ed tenemos algunas escuelas pero ya va dependiendo, por ejemplo, hay algunas que no contaban con contrato, hay algunas que s\u00ed lo cuentan, pero pues no se est\u00e1 dando el servicio como tal\u201d.<\/p>\n<p style=\"text-align: justify;\">El municipio ha intervenido.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos proporcionando nosotros pipas de agua (\u2026) ahorita en lo que va de la semana pasada surtimos a 26 escuelas, ya esta semana empezamos con siete\u201d.<\/p>\n<p style=\"text-align: justify;\">Para culminar, explic\u00f3 que hay una escuela en la que las autoridades solicitaron contar con bardas perimetrales.<\/p>\n<p style=\"text-align: justify;\">Por: Juan Carlos Contreras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SGS.- Debido a la temporada de calor que ha comenzado, siete centros educativos han solicitado techado en Soledad de Graciano S\u00e1nchez, as\u00ed lo expuso la directora de Educaci\u00f3n, Velia Guadalupe Castro Granja. \u201cEn techados hay algunos que s\u00ed cuentan con techado hay algunas que no por las cuales nos han estado solicitando el apoyo de infraestructura en ese sentido de techado (\u2026) como tal a la Direcci\u00f3n de Educaci\u00f3n \u00fanicamente han llegado siete solicitudes\u201d. Asever\u00f3 que se visitar\u00e1 la totalidad de las escuelas en Soledad para verificar cu\u00e1ntas requieren de mejora. \u201cEstamos visitando por ah\u00ed las escuelas para levantar todos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":161925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[512,5,45],"tags":[],"class_list":["post-161923","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayosgs","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Varias escuelas en SGS solicitaron techado de patios por altas temperaturas - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SGS.- Debido a la temporada de calor que ha comenzado, siete centros educativos han solicitado techado en Soledad de Graciano S\u00e1nchez, as\u00ed lo expuso la directora de Educaci\u00f3n, Velia Guadalupe Castro Granja. \u201cEn techados hay algunos que s\u00ed cuentan con techado hay algunas que no por las cuales nos han estado solicitando el apoyo de infraestructura en ese sentido de techado (\u2026) como tal a la Direcci\u00f3n de Educaci\u00f3n \u00fanicamente han llegado siete solicitudes\u201d. Asever\u00f3 que se visitar\u00e1 la totalidad de las escuelas en Soledad para verificar cu\u00e1ntas requieren de mejora. \u201cEstamos visitando por ah\u00ed las escuelas para levantar todos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-30T20:15:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-30T20:18:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/Poky01Infraestructura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas\",\"datePublished\":\"2025-03-30T20:15:27+00:00\",\"dateModified\":\"2025-03-30T20:18:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Poky01Infraestructura.jpg\",\"articleSection\":[\"AYOSGS\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/\",\"name\":\"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Poky01Infraestructura.jpg\",\"datePublished\":\"2025-03-30T20:15:27+00:00\",\"dateModified\":\"2025-03-30T20:18:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Poky01Infraestructura.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Poky01Infraestructura.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/","og_locale":"es_ES","og_type":"article","og_title":"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas - Canal 7 SLP - 2025","og_description":"SGS.- Debido a la temporada de calor que ha comenzado, siete centros educativos han solicitado techado en Soledad de Graciano S\u00e1nchez, as\u00ed lo expuso la directora de Educaci\u00f3n, Velia Guadalupe Castro Granja. \u201cEn techados hay algunos que s\u00ed cuentan con techado hay algunas que no por las cuales nos han estado solicitando el apoyo de infraestructura en ese sentido de techado (\u2026) como tal a la Direcci\u00f3n de Educaci\u00f3n \u00fanicamente han llegado siete solicitudes\u201d. Asever\u00f3 que se visitar\u00e1 la totalidad de las escuelas en Soledad para verificar cu\u00e1ntas requieren de mejora. \u201cEstamos visitando por ah\u00ed las escuelas para levantar todos [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-03-30T20:15:27+00:00","article_modified_time":"2025-03-30T20:18:26+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/Poky01Infraestructura.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas","datePublished":"2025-03-30T20:15:27+00:00","dateModified":"2025-03-30T20:18:26+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/"},"wordCount":246,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/Poky01Infraestructura.jpg","articleSection":["AYOSGS","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/","url":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/","name":"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/Poky01Infraestructura.jpg","datePublished":"2025-03-30T20:15:27+00:00","dateModified":"2025-03-30T20:18:26+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/Poky01Infraestructura.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/Poky01Infraestructura.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/varias-escuelas-en-sgs-solicitaron-techado-de-patios-por-altas-temperaturas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Varias escuelas en SGS solicitaron techado de patios por altas temperaturas"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/161923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=161923"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/161923\/revisions"}],"predecessor-version":[{"id":161926,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/161923\/revisions\/161926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/161925"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=161923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=161923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=161923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}