{"id":161919,"date":"2025-03-30T14:04:52","date_gmt":"2025-03-30T20:04:52","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=161919"},"modified":"2025-03-30T14:04:52","modified_gmt":"2025-03-30T20:04:52","slug":"fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/","title":{"rendered":"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota"},"content":{"rendered":"<p style=\"text-align: justify;\">Culiac\u00e1n.- En recientes operativos en los municipios de Culiac\u00e1n y Elota, Sinaloa, elementos de la Marina y de la Polic\u00eda Estatal Preventiva recuperaron cinco veh\u00edculos reportados como robados.<\/p>\n<p style=\"text-align: justify;\">Durante una de las acciones, el personal naval fue atacado a balazos, lo que deriv\u00f3 en la detenci\u00f3n de un civil herido, mientras que su c\u00f3mplice logr\u00f3 escapar.<\/p>\n<p style=\"text-align: justify;\">En otro operativo, la Marina, en respuesta a una denuncia ciudadana en la comunidad de Casas Viejas, localiz\u00f3 tres veh\u00edculos robados, junto con cartuchos, cargadores y dos chalecos con placas bal\u00edsticas.<\/p>\n<p style=\"text-align: justify;\">Posteriormente, en el poblado de La Palma, dos individuos armados en motocicleta dispararon contra las fuerzas navales; al repeler la agresi\u00f3n, las autoridades hirieron a uno de los atacantes, quien fue detenido, mientras su c\u00f3mplice huy\u00f3 del lugar.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, se recibi\u00f3 una alerta por el despojo de una camioneta Suburban en la Maxipista Mazatl\u00e1n-Culiac\u00e1n.<\/p>\n<p style=\"text-align: justify;\">Las autoridades de la Polic\u00eda Estatal Preventiva realizaron un operativo en la zona, encontraron el veh\u00edculo abandonado en la comunidad de Pueblos Unidos y lo aseguraron para su traslado a la Fiscal\u00eda General del Estado, a fin de proceder a su devoluci\u00f3n a los propietarios.<\/p>\n<p style=\"text-align: justify;\">Durante patrullajes en El Campo el Diez, tambi\u00e9n se localiz\u00f3 un veh\u00edculo Nissan Versa de color naranja, reportado como robado el 24 de marzo, y fue asegurado tras verificar su matr\u00edcula en la Plataforma M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n.- En recientes operativos en los municipios de Culiac\u00e1n y Elota, Sinaloa, elementos de la Marina y de la Polic\u00eda Estatal Preventiva recuperaron cinco veh\u00edculos reportados como robados. Durante una de las acciones, el personal naval fue atacado a balazos, lo que deriv\u00f3 en la detenci\u00f3n de un civil herido, mientras que su c\u00f3mplice logr\u00f3 escapar. En otro operativo, la Marina, en respuesta a una denuncia ciudadana en la comunidad de Casas Viejas, localiz\u00f3 tres veh\u00edculos robados, junto con cartuchos, cargadores y dos chalecos con placas bal\u00edsticas. Posteriormente, en el poblado de La Palma, dos individuos armados en motocicleta dispararon [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":161920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-161919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"Culiac\u00e1n.- En recientes operativos en los municipios de Culiac\u00e1n y Elota, Sinaloa, elementos de la Marina y de la Polic\u00eda Estatal Preventiva recuperaron cinco veh\u00edculos reportados como robados. Durante una de las acciones, el personal naval fue atacado a balazos, lo que deriv\u00f3 en la detenci\u00f3n de un civil herido, mientras que su c\u00f3mplice logr\u00f3 escapar. En otro operativo, la Marina, en respuesta a una denuncia ciudadana en la comunidad de Casas Viejas, localiz\u00f3 tres veh\u00edculos robados, junto con cartuchos, cargadores y dos chalecos con placas bal\u00edsticas. Posteriormente, en el poblado de La Palma, dos individuos armados en motocicleta dispararon [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-30T20:04:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/10-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"793\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota\",\"datePublished\":\"2025-03-30T20:04:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/\"},\"wordCount\":255,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-22.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/\",\"name\":\"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-22.jpg\",\"datePublished\":\"2025-03-30T20:04:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-22.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-22.jpg\",\"width\":793,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/","og_locale":"es_ES","og_type":"article","og_title":"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota - Canal 7 SLP - 2025","og_description":"Culiac\u00e1n.- En recientes operativos en los municipios de Culiac\u00e1n y Elota, Sinaloa, elementos de la Marina y de la Polic\u00eda Estatal Preventiva recuperaron cinco veh\u00edculos reportados como robados. Durante una de las acciones, el personal naval fue atacado a balazos, lo que deriv\u00f3 en la detenci\u00f3n de un civil herido, mientras que su c\u00f3mplice logr\u00f3 escapar. En otro operativo, la Marina, en respuesta a una denuncia ciudadana en la comunidad de Casas Viejas, localiz\u00f3 tres veh\u00edculos robados, junto con cartuchos, cargadores y dos chalecos con placas bal\u00edsticas. Posteriormente, en el poblado de La Palma, dos individuos armados en motocicleta dispararon [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-03-30T20:04:52+00:00","og_image":[{"width":793,"height":500,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/10-22.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota","datePublished":"2025-03-30T20:04:52+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/"},"wordCount":255,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/10-22.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/","url":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/","name":"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/10-22.jpg","datePublished":"2025-03-30T20:04:52+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/10-22.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/03\/10-22.jpg","width":793,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/fuerzas-navales-y-estatales-recuperan-vehiculos-robados-en-culiacan-y-elota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Fuerzas Navales y Estatales recuperan veh\u00edculos robados en Culiac\u00e1n y Elota"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/161919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=161919"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/161919\/revisions"}],"predecessor-version":[{"id":161921,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/161919\/revisions\/161921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/161920"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=161919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=161919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=161919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}