{"id":159431,"date":"2025-02-26T18:48:53","date_gmt":"2025-02-27T00:48:53","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=159431"},"modified":"2025-02-26T18:48:53","modified_gmt":"2025-02-27T00:48:53","slug":"san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/","title":{"rendered":"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SLP.- Por segunda ocasi\u00f3n San Luis Potos\u00ed ser\u00e1 sede los Juegos Latinoamericanos de Polic\u00edas y Bomberos en un evento que se llevar\u00e1 a cabo del 26 de Octubre al 1\u00b0 de Noviembre del presente a\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\">Habr\u00e1 m\u00e1s de 20 disciplinas que se llevar\u00e1n a cabo en sedes estrat\u00e9gicas para que la ciudadan\u00eda pueda ver las competencias, ya que se espera el arribo de aproximadamente 2 mil polic\u00edas y bomberos de 30 pa\u00edses de Am\u00e9rica Latina y de otras partes del mundo.<\/p>\n<p style=\"text-align: justify;\">Para garantizar la realizaci\u00f3n de este evento se firm\u00f3 una carta compromiso en el sal\u00f3n de Cabildos de Palacio Municipal, en lo que ser\u00e1 la decimosegunda edici\u00f3n de estos juegos.<\/p>\n<p>Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Por segunda ocasi\u00f3n San Luis Potos\u00ed ser\u00e1 sede los Juegos Latinoamericanos de Polic\u00edas y Bomberos en un evento que se llevar\u00e1 a cabo del 26 de Octubre al 1\u00b0 de Noviembre del presente a\u00f1o. Habr\u00e1 m\u00e1s de 20 disciplinas que se llevar\u00e1n a cabo en sedes estrat\u00e9gicas para que la ciudadan\u00eda pueda ver las competencias, ya que se espera el arribo de aproximadamente 2 mil polic\u00edas y bomberos de 30 pa\u00edses de Am\u00e9rica Latina y de otras partes del mundo. Para garantizar la realizaci\u00f3n de este evento se firm\u00f3 una carta compromiso en el sal\u00f3n de Cabildos de Palacio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":159479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[66,5,45],"tags":[],"class_list":["post-159431","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayoslp","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025 - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025 - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.- Por segunda ocasi\u00f3n San Luis Potos\u00ed ser\u00e1 sede los Juegos Latinoamericanos de Polic\u00edas y Bomberos en un evento que se llevar\u00e1 a cabo del 26 de Octubre al 1\u00b0 de Noviembre del presente a\u00f1o. Habr\u00e1 m\u00e1s de 20 disciplinas que se llevar\u00e1n a cabo en sedes estrat\u00e9gicas para que la ciudadan\u00eda pueda ver las competencias, ya que se espera el arribo de aproximadamente 2 mil polic\u00edas y bomberos de 30 pa\u00edses de Am\u00e9rica Latina y de otras partes del mundo. Para garantizar la realizaci\u00f3n de este evento se firm\u00f3 una carta compromiso en el sal\u00f3n de Cabildos de Palacio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-27T00:48:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Claudio04JuegosBomberos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025\",\"datePublished\":\"2025-02-27T00:48:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/\"},\"wordCount\":136,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Claudio04JuegosBomberos.jpg\",\"articleSection\":[\"AYOSLP\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/\",\"name\":\"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025 - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Claudio04JuegosBomberos.jpg\",\"datePublished\":\"2025-02-27T00:48:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Claudio04JuegosBomberos.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Claudio04JuegosBomberos.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025 - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/","og_locale":"es_ES","og_type":"article","og_title":"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025 - Canal 7 SLP - 2025","og_description":"SLP.- Por segunda ocasi\u00f3n San Luis Potos\u00ed ser\u00e1 sede los Juegos Latinoamericanos de Polic\u00edas y Bomberos en un evento que se llevar\u00e1 a cabo del 26 de Octubre al 1\u00b0 de Noviembre del presente a\u00f1o. Habr\u00e1 m\u00e1s de 20 disciplinas que se llevar\u00e1n a cabo en sedes estrat\u00e9gicas para que la ciudadan\u00eda pueda ver las competencias, ya que se espera el arribo de aproximadamente 2 mil polic\u00edas y bomberos de 30 pa\u00edses de Am\u00e9rica Latina y de otras partes del mundo. Para garantizar la realizaci\u00f3n de este evento se firm\u00f3 una carta compromiso en el sal\u00f3n de Cabildos de Palacio [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-02-27T00:48:53+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Claudio04JuegosBomberos.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025","datePublished":"2025-02-27T00:48:53+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/"},"wordCount":136,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Claudio04JuegosBomberos.jpg","articleSection":["AYOSLP","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/","url":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/","name":"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025 - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Claudio04JuegosBomberos.jpg","datePublished":"2025-02-27T00:48:53+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Claudio04JuegosBomberos.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Claudio04JuegosBomberos.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/san-luis-potosi-sera-sede-de-los-juegos-de-policias-y-bomberos-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"San Luis Potos\u00ed ser\u00e1 sede de los Juegos de Polic\u00edas y Bomberos 2025"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/159431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=159431"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/159431\/revisions"}],"predecessor-version":[{"id":159480,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/159431\/revisions\/159480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/159479"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=159431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=159431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=159431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}