{"id":158939,"date":"2025-02-21T16:59:19","date_gmt":"2025-02-21T22:59:19","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=158939"},"modified":"2025-02-21T16:59:19","modified_gmt":"2025-02-21T22:59:19","slug":"oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/","title":{"rendered":"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SLP.- Como parte de las actividades de Capital Americana de la Cultura, nombramiento en 2025 para el Ayuntamiento de San Luis Potos\u00ed, se tendr\u00e1 la presentaci\u00f3n musical del artista Oscar de Le\u00f3n en Plaza de los Fundadores.<\/span><\/p>\n<p style=\"text-align: justify;\">El edil Enrique Galindo Ceballos durante rueda de prensa, dio la bienvenida al referente de la salsa.<\/p>\n<p style=\"text-align: justify;\">\u201cDon Oscar, darle la bienvenida aqu\u00ed todos lo conocemos (\u2026) le quiero compartir que estamos en el a\u00f1o 2025 Capital Americana de la Cultura San Luis Potos\u00ed (\u2026) en febrero Venezuela y Colombia pa\u00edses hermanos, naciones hermanas, culturas hermanas est\u00e1n exponiendo gastron\u00f3micamente, artesanalmente y art\u00edsticamente sus valores (\u2026) yo no quiero dar m\u00e1s pre\u00e1mbulos sino agradecer la presencia de usted aqu\u00ed en San Luis Potos\u00ed\u201d.<\/p>\n<p style=\"text-align: justify;\">A su vez, el s\u00edmbolo de la m\u00fasica latina, Oscar de Le\u00f3n agradeci\u00f3 la recepci\u00f3n que se dio al llegar a tierras potosinas.<\/p>\n<p style=\"text-align: justify;\">\u201cLa verdad que me siento complacido, muy lleno de emociones porque es la primera vez que estoy ac\u00e1 en 52 a\u00f1os de carrera art\u00edstica y veo pues que hay un cari\u00f1o (\u2026) pues estamos siempre prestos al llamado y en esta oportunidad no fue distinto sino con mucha alegr\u00eda recib\u00ed la noticia y aqu\u00ed estamos (\u2026) mi presencia ac\u00e1 pues que sirva de granito de apoyo para lo que est\u00e1n haciendo ahora en celebrando\u201d.<\/p>\n<p style=\"text-align: justify;\">El artista se presentar\u00e1 de manera gratuita el d\u00eda s\u00e1bado 22 de febrero en Plaza de los Fundadores en punto de las 20 horas.<\/p>\n<p style=\"text-align: justify;\">Por: Juan Carlos Contreras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Como parte de las actividades de Capital Americana de la Cultura, nombramiento en 2025 para el Ayuntamiento de San Luis Potos\u00ed, se tendr\u00e1 la presentaci\u00f3n musical del artista Oscar de Le\u00f3n en Plaza de los Fundadores. El edil Enrique Galindo Ceballos durante rueda de prensa, dio la bienvenida al referente de la salsa. \u201cDon Oscar, darle la bienvenida aqu\u00ed todos lo conocemos (\u2026) le quiero compartir que estamos en el a\u00f1o 2025 Capital Americana de la Cultura San Luis Potos\u00ed (\u2026) en febrero Venezuela y Colombia pa\u00edses hermanos, naciones hermanas, culturas hermanas est\u00e1n exponiendo gastron\u00f3micamente, artesanalmente y art\u00edsticamente sus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":158954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[66,5,45],"tags":[],"class_list":["post-158939","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayoslp","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.- Como parte de las actividades de Capital Americana de la Cultura, nombramiento en 2025 para el Ayuntamiento de San Luis Potos\u00ed, se tendr\u00e1 la presentaci\u00f3n musical del artista Oscar de Le\u00f3n en Plaza de los Fundadores. El edil Enrique Galindo Ceballos durante rueda de prensa, dio la bienvenida al referente de la salsa. \u201cDon Oscar, darle la bienvenida aqu\u00ed todos lo conocemos (\u2026) le quiero compartir que estamos en el a\u00f1o 2025 Capital Americana de la Cultura San Luis Potos\u00ed (\u2026) en febrero Venezuela y Colombia pa\u00edses hermanos, naciones hermanas, culturas hermanas est\u00e1n exponiendo gastron\u00f3micamente, artesanalmente y art\u00edsticamente sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T22:59:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Poky03OscarDeLeon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed\",\"datePublished\":\"2025-02-21T22:59:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/\"},\"wordCount\":271,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Poky03OscarDeLeon.jpg\",\"articleSection\":[\"AYOSLP\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/\",\"name\":\"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Poky03OscarDeLeon.jpg\",\"datePublished\":\"2025-02-21T22:59:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Poky03OscarDeLeon.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Poky03OscarDeLeon.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/","og_locale":"es_ES","og_type":"article","og_title":"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed - Canal 7 SLP - 2025","og_description":"SLP.- Como parte de las actividades de Capital Americana de la Cultura, nombramiento en 2025 para el Ayuntamiento de San Luis Potos\u00ed, se tendr\u00e1 la presentaci\u00f3n musical del artista Oscar de Le\u00f3n en Plaza de los Fundadores. El edil Enrique Galindo Ceballos durante rueda de prensa, dio la bienvenida al referente de la salsa. \u201cDon Oscar, darle la bienvenida aqu\u00ed todos lo conocemos (\u2026) le quiero compartir que estamos en el a\u00f1o 2025 Capital Americana de la Cultura San Luis Potos\u00ed (\u2026) en febrero Venezuela y Colombia pa\u00edses hermanos, naciones hermanas, culturas hermanas est\u00e1n exponiendo gastron\u00f3micamente, artesanalmente y art\u00edsticamente sus [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-02-21T22:59:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Poky03OscarDeLeon.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed","datePublished":"2025-02-21T22:59:19+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/"},"wordCount":271,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Poky03OscarDeLeon.jpg","articleSection":["AYOSLP","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/","url":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/","name":"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Poky03OscarDeLeon.jpg","datePublished":"2025-02-21T22:59:19+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Poky03OscarDeLeon.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/Poky03OscarDeLeon.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/oscar-de-leon-dejara-alma-y-corazon-en-concierto-en-la-capital-del-si\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Oscar de Le\u00f3n dejar\u00e1 alma y coraz\u00f3n en concierto en la Capital del S\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/158939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=158939"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/158939\/revisions"}],"predecessor-version":[{"id":158955,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/158939\/revisions\/158955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/158954"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=158939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=158939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=158939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}