{"id":158555,"date":"2025-02-18T16:17:38","date_gmt":"2025-02-18T22:17:38","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=158555"},"modified":"2025-02-18T16:17:38","modified_gmt":"2025-02-18T22:17:38","slug":"el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/","title":{"rendered":"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral"},"content":{"rendered":"<p style=\"text-align: justify;\">El Vaticano.- El Papa Francisco contin\u00faa hospitalizado en el Policl\u00ednico Gemelli de Roma debido a una infecci\u00f3n polimicrobiana respiratoria que ha evolucionado a una neumon\u00eda bilateral. Su cuadro cl\u00ednico se ha calificado como \u00abcomplejo\u00bb por parte del Vaticano.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan los \u00faltimos informes m\u00e9dicos, la infecci\u00f3n polimicrobiana que afecta al Pont\u00edfice, sumada a sus antecedentes de bronquiectasias y bronquitis asm\u00e1tica, ha requerido la modificaci\u00f3n de su tratamiento, incluyendo el uso de antibi\u00f3ticos y corticosteroides. Adicionalmente, los estudios de imagen han revelado la aparici\u00f3n de una neumon\u00eda bilateral, lo que ha obligado a implementar terapia farmacol\u00f3gica adicional.<\/p>\n<p style=\"text-align: justify;\">Como consecuencia de su delicado estado de salud, el Papa Francisco no podr\u00e1 asistir a la audiencia jubilar programada para este s\u00e1bado, ni presidir la misa del Jubileo de los Di\u00e1conos, siendo sustituido en esta \u00faltima por el responsable del dicasterio para la Evangelizaci\u00f3n, Rino Fisichella.<\/p>\n<p style=\"text-align: justify;\">No obstante, a pesar de su hospitalizaci\u00f3n, el Santo Padre ha mantenido contacto con la parroquia de la Sagrada Familia en Gaza, a la que llam\u00f3 personalmente, seg\u00fan inform\u00f3 el p\u00e1rroco argentino Gabriel Romanelli.<\/p>\n<p style=\"text-align: justify;\">El Vaticano ha destacado que, si bien el cuadro cl\u00ednico de Francisco sigue siendo \u00abcomplejo\u00bb, el Pont\u00edfice se encuentra de buen humor, ha recibido la Eucarist\u00eda y ha alternado el descanso con la oraci\u00f3n y la lectura. Asimismo, ha agradecido las muestras de cercan\u00eda y ha solicitado que se siga rezando por \u00e9l.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>El Vaticano.- El Papa Francisco contin\u00faa hospitalizado en el Policl\u00ednico Gemelli de Roma debido a una infecci\u00f3n polimicrobiana respiratoria que ha evolucionado a una neumon\u00eda bilateral. Su cuadro cl\u00ednico se ha calificado como \u00abcomplejo\u00bb por parte del Vaticano. Seg\u00fan los \u00faltimos informes m\u00e9dicos, la infecci\u00f3n polimicrobiana que afecta al Pont\u00edfice, sumada a sus antecedentes de bronquiectasias y bronquitis asm\u00e1tica, ha requerido la modificaci\u00f3n de su tratamiento, incluyendo el uso de antibi\u00f3ticos y corticosteroides. Adicionalmente, los estudios de imagen han revelado la aparici\u00f3n de una neumon\u00eda bilateral, lo que ha obligado a implementar terapia farmacol\u00f3gica adicional. Como consecuencia de su delicado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":158556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-158555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"El Vaticano.- El Papa Francisco contin\u00faa hospitalizado en el Policl\u00ednico Gemelli de Roma debido a una infecci\u00f3n polimicrobiana respiratoria que ha evolucionado a una neumon\u00eda bilateral. Su cuadro cl\u00ednico se ha calificado como \u00abcomplejo\u00bb por parte del Vaticano. Seg\u00fan los \u00faltimos informes m\u00e9dicos, la infecci\u00f3n polimicrobiana que afecta al Pont\u00edfice, sumada a sus antecedentes de bronquiectasias y bronquitis asm\u00e1tica, ha requerido la modificaci\u00f3n de su tratamiento, incluyendo el uso de antibi\u00f3ticos y corticosteroides. Adicionalmente, los estudios de imagen han revelado la aparici\u00f3n de una neumon\u00eda bilateral, lo que ha obligado a implementar terapia farmacol\u00f3gica adicional. Como consecuencia de su delicado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T22:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/10-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"947\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral\",\"datePublished\":\"2025-02-18T22:17:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/\"},\"wordCount\":268,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10-15.jpg\",\"articleSection\":[\"INTERNACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/\",\"name\":\"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10-15.jpg\",\"datePublished\":\"2025-02-18T22:17:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10-15.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10-15.jpg\",\"width\":947,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/","og_locale":"es_ES","og_type":"article","og_title":"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral - Canal 7 SLP - 2025","og_description":"El Vaticano.- El Papa Francisco contin\u00faa hospitalizado en el Policl\u00ednico Gemelli de Roma debido a una infecci\u00f3n polimicrobiana respiratoria que ha evolucionado a una neumon\u00eda bilateral. Su cuadro cl\u00ednico se ha calificado como \u00abcomplejo\u00bb por parte del Vaticano. Seg\u00fan los \u00faltimos informes m\u00e9dicos, la infecci\u00f3n polimicrobiana que afecta al Pont\u00edfice, sumada a sus antecedentes de bronquiectasias y bronquitis asm\u00e1tica, ha requerido la modificaci\u00f3n de su tratamiento, incluyendo el uso de antibi\u00f3ticos y corticosteroides. Adicionalmente, los estudios de imagen han revelado la aparici\u00f3n de una neumon\u00eda bilateral, lo que ha obligado a implementar terapia farmacol\u00f3gica adicional. Como consecuencia de su delicado [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-02-18T22:17:38+00:00","og_image":[{"width":947,"height":500,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/10-15.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral","datePublished":"2025-02-18T22:17:38+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/"},"wordCount":268,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/10-15.jpg","articleSection":["INTERNACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/","url":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/","name":"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/10-15.jpg","datePublished":"2025-02-18T22:17:38+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/10-15.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/10-15.jpg","width":947,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/el-papa-francisco-permanece-en-el-hospital-con-cuadro-de-neumonia-bilateral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"El Papa Francisco permanece en el hospital con cuadro de neumon\u00eda bilateral"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/158555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=158555"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/158555\/revisions"}],"predecessor-version":[{"id":158557,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/158555\/revisions\/158557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/158556"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=158555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=158555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=158555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}