{"id":156391,"date":"2025-02-01T16:26:20","date_gmt":"2025-02-01T22:26:20","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=156391"},"modified":"2025-02-01T16:30:06","modified_gmt":"2025-02-01T22:30:06","slug":"unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/","title":{"rendered":"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0La Unidad Especializada para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda General del Estado de San Luis Potos\u00ed (FGESLP) obtuvo una sentencia condenatoria de 25 a\u00f1os de prisi\u00f3n para Cruz Alfonso \u201cN\u201d, por la desaparici\u00f3n de una mujer y su beb\u00e9 en el barrio de San Sebasti\u00e1n, en la capital potosina.<\/p>\n<p style=\"text-align: justify;\">El caso data de octubre de 2014, cuando se report\u00f3 la desaparici\u00f3n de una perito y su hijo de ocho meses. Las investigaciones identificaron a Cruz Alfonso \u201cN\u201d como presunto responsable, tras encontrar evidencias en su veh\u00edculo, como objetos personales de las v\u00edctimas.<\/p>\n<p style=\"text-align: justify;\">En 2020, la Polic\u00eda de Investigaci\u00f3n (PDI) detuvo al imputado y lo present\u00f3 ante la autoridad judicial. A pesar de los amparos promovidos por su defensa, el proceso continu\u00f3 hasta que, el 30 de enero, un tribunal dict\u00f3 la sentencia condenatoria por el delito de desaparici\u00f3n cometida por particulares. Adem\u00e1s de la prisi\u00f3n, Cruz Alfonso \u201cN\u201d deber\u00e1 cumplir con sanciones econ\u00f3micas.<\/p>\n<p style=\"text-align: justify;\">La FGESLP contin\u00faa con la b\u00fasqueda de las v\u00edctimas, realizando expediciones a nivel estatal y nacional, ya que su paradero sigue sin conocerse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0La Unidad Especializada para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda General del Estado de San Luis Potos\u00ed (FGESLP) obtuvo una sentencia condenatoria de 25 a\u00f1os de prisi\u00f3n para Cruz Alfonso \u201cN\u201d, por la desaparici\u00f3n de una mujer y su beb\u00e9 en el barrio de San Sebasti\u00e1n, en la capital potosina. El caso data de octubre de 2014, cuando se report\u00f3 la desaparici\u00f3n de una perito y su hijo de ocho meses. Las investigaciones identificaron a Cruz Alfonso \u201cN\u201d como presunto responsable, tras encontrar evidencias en su veh\u00edculo, como objetos personales de las v\u00edctimas. En 2020, la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":156398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-156391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reporte7","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0La Unidad Especializada para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda General del Estado de San Luis Potos\u00ed (FGESLP) obtuvo una sentencia condenatoria de 25 a\u00f1os de prisi\u00f3n para Cruz Alfonso \u201cN\u201d, por la desaparici\u00f3n de una mujer y su beb\u00e9 en el barrio de San Sebasti\u00e1n, en la capital potosina. El caso data de octubre de 2014, cuando se report\u00f3 la desaparici\u00f3n de una perito y su hijo de ocho meses. Las investigaciones identificaron a Cruz Alfonso \u201cN\u201d como presunto responsable, tras encontrar evidencias en su veh\u00edculo, como objetos personales de las v\u00edctimas. En 2020, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-01T22:26:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-01T22:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/zz2b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"894\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares\",\"datePublished\":\"2025-02-01T22:26:20+00:00\",\"dateModified\":\"2025-02-01T22:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/\"},\"wordCount\":217,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zz2b.jpg\",\"articleSection\":[\"REPORTE 7\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/\",\"name\":\"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zz2b.jpg\",\"datePublished\":\"2025-02-01T22:26:20+00:00\",\"dateModified\":\"2025-02-01T22:30:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zz2b.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/zz2b.jpg\",\"width\":894,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/","og_locale":"es_ES","og_type":"article","og_title":"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares - Canal 7 SLP - 2025","og_description":"SLP.-\u00a0La Unidad Especializada para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda General del Estado de San Luis Potos\u00ed (FGESLP) obtuvo una sentencia condenatoria de 25 a\u00f1os de prisi\u00f3n para Cruz Alfonso \u201cN\u201d, por la desaparici\u00f3n de una mujer y su beb\u00e9 en el barrio de San Sebasti\u00e1n, en la capital potosina. El caso data de octubre de 2014, cuando se report\u00f3 la desaparici\u00f3n de una perito y su hijo de ocho meses. Las investigaciones identificaron a Cruz Alfonso \u201cN\u201d como presunto responsable, tras encontrar evidencias en su veh\u00edculo, como objetos personales de las v\u00edctimas. En 2020, la [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-02-01T22:26:20+00:00","article_modified_time":"2025-02-01T22:30:06+00:00","og_image":[{"width":894,"height":614,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/zz2b.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares","datePublished":"2025-02-01T22:26:20+00:00","dateModified":"2025-02-01T22:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/"},"wordCount":217,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/zz2b.jpg","articleSection":["REPORTE 7"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/","url":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/","name":"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/zz2b.jpg","datePublished":"2025-02-01T22:26:20+00:00","dateModified":"2025-02-01T22:30:06+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/zz2b.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/02\/zz2b.jpg","width":894,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/unidad-de-personas-desaparecidas-de-fgeslp-logran-primera-sentencia-de-larga-data-por-el-delito-de-desaparicion-por-particulares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Unidad de Personas Desaparecidas de FGESLP logran primera sentencia de larga data por el delito de desaparici\u00f3n por particulares"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/156391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=156391"}],"version-history":[{"count":4,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/156391\/revisions"}],"predecessor-version":[{"id":156404,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/156391\/revisions\/156404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/156398"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=156391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=156391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=156391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}