{"id":155345,"date":"2025-01-24T19:11:30","date_gmt":"2025-01-25T01:11:30","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=155345"},"modified":"2025-01-24T19:14:36","modified_gmt":"2025-01-25T01:14:36","slug":"conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/","title":{"rendered":"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SLP.- En la delegaci\u00f3n de La Pila se llev\u00f3 a cabo una serie de actividades con motivo del vig\u00e9simo noveno aniversario de de la creaci\u00f3n de \u00e9sta demarcaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\">Se destac\u00f3 que \u00e9sta delegaci\u00f3n dejar\u00e1 de ser una comunidad rural para consolidar su desarrollo pues existen en esta demarcaci\u00f3n m\u00e1s de 300 empresas instaladas, y que tiene adem\u00e1s un gran potencial humano.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el presidente municipal capitalino Enrique Galindo en el marco de este evento anunci\u00f3 la ampliaci\u00f3n a dos carriles del eje 140, y la construcci\u00f3n de un puente vehicular que mejorar\u00e1 la movilidad en este sector de la ciudad.<\/p>\n<p style=\"text-align: justify;\">Se\u00f1al\u00f3 que en \u00e9ste cat\u00e1logo de proyectos se contempla el reforzamiento de la infraestructura hidr\u00e1ulica con una inversi\u00f3n inicial de 200 millones de pesos.<\/p>\n<p>Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- En la delegaci\u00f3n de La Pila se llev\u00f3 a cabo una serie de actividades con motivo del vig\u00e9simo noveno aniversario de de la creaci\u00f3n de \u00e9sta demarcaci\u00f3n. Se destac\u00f3 que \u00e9sta delegaci\u00f3n dejar\u00e1 de ser una comunidad rural para consolidar su desarrollo pues existen en esta demarcaci\u00f3n m\u00e1s de 300 empresas instaladas, y que tiene adem\u00e1s un gran potencial humano. Por su parte, el presidente municipal capitalino Enrique Galindo en el marco de este evento anunci\u00f3 la ampliaci\u00f3n a dos carriles del eje 140, y la construcci\u00f3n de un puente vehicular que mejorar\u00e1 la movilidad en este sector de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":155377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[66,5,45],"tags":[],"class_list":["post-155345","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayoslp","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.- En la delegaci\u00f3n de La Pila se llev\u00f3 a cabo una serie de actividades con motivo del vig\u00e9simo noveno aniversario de de la creaci\u00f3n de \u00e9sta demarcaci\u00f3n. Se destac\u00f3 que \u00e9sta delegaci\u00f3n dejar\u00e1 de ser una comunidad rural para consolidar su desarrollo pues existen en esta demarcaci\u00f3n m\u00e1s de 300 empresas instaladas, y que tiene adem\u00e1s un gran potencial humano. Por su parte, el presidente municipal capitalino Enrique Galindo en el marco de este evento anunci\u00f3 la ampliaci\u00f3n a dos carriles del eje 140, y la construcci\u00f3n de un puente vehicular que mejorar\u00e1 la movilidad en este sector de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-25T01:11:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-25T01:14:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Claudio01LaPIla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario\",\"datePublished\":\"2025-01-25T01:11:30+00:00\",\"dateModified\":\"2025-01-25T01:14:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/\"},\"wordCount\":153,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Claudio01LaPIla.jpg\",\"articleSection\":[\"AYOSLP\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/\",\"name\":\"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Claudio01LaPIla.jpg\",\"datePublished\":\"2025-01-25T01:11:30+00:00\",\"dateModified\":\"2025-01-25T01:14:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Claudio01LaPIla.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Claudio01LaPIla.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/","og_locale":"es_ES","og_type":"article","og_title":"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario - Canal 7 SLP - 2025","og_description":"SLP.- En la delegaci\u00f3n de La Pila se llev\u00f3 a cabo una serie de actividades con motivo del vig\u00e9simo noveno aniversario de de la creaci\u00f3n de \u00e9sta demarcaci\u00f3n. Se destac\u00f3 que \u00e9sta delegaci\u00f3n dejar\u00e1 de ser una comunidad rural para consolidar su desarrollo pues existen en esta demarcaci\u00f3n m\u00e1s de 300 empresas instaladas, y que tiene adem\u00e1s un gran potencial humano. Por su parte, el presidente municipal capitalino Enrique Galindo en el marco de este evento anunci\u00f3 la ampliaci\u00f3n a dos carriles del eje 140, y la construcci\u00f3n de un puente vehicular que mejorar\u00e1 la movilidad en este sector de [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-01-25T01:11:30+00:00","article_modified_time":"2025-01-25T01:14:36+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Claudio01LaPIla.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario","datePublished":"2025-01-25T01:11:30+00:00","dateModified":"2025-01-25T01:14:36+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/"},"wordCount":153,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Claudio01LaPIla.jpg","articleSection":["AYOSLP","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/","url":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/","name":"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Claudio01LaPIla.jpg","datePublished":"2025-01-25T01:11:30+00:00","dateModified":"2025-01-25T01:14:36+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Claudio01LaPIla.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Claudio01LaPIla.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/conmemora-la-delegacion-de-la-pila-su-vigesimo-noveno-aniversario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Conmemora la delegaci\u00f3n de La Pila su Vig\u00e9simo Noveno Aniversario"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/155345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=155345"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/155345\/revisions"}],"predecessor-version":[{"id":155383,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/155345\/revisions\/155383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/155377"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=155345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=155345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=155345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}