{"id":155159,"date":"2025-01-23T17:49:29","date_gmt":"2025-01-23T23:49:29","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=155159"},"modified":"2025-01-23T17:49:29","modified_gmt":"2025-01-23T23:49:29","slug":"inegi-presento-los-resultados-de-los-censos-economicos-2024","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/","title":{"rendered":"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SLP.- El Instituto Nacional de Estad\u00edstica y Geograf\u00eda ofreci\u00f3 los resultados de los <\/span>Censos Econ\u00f3micos 2024, esto mediante el coordinador estatal en San Luis Potos\u00ed, Arturo Ramos Miranda.<\/p>\n<p style=\"text-align: justify;\">\u201cSon 114 mil 17 establecimientos con 601 mil personas ocupadas, en adelante los datos que les vamos a presentar se refieren espec\u00edficamente a sector privado y empresas paraestatales\u201d.<\/p>\n<p style=\"text-align: justify;\">Este censo permiten conocer qu\u00e9, cu\u00e1nto, c\u00f3mo, d\u00f3nde y con qu\u00e9 se produce en la econom\u00eda de San Luis Potos\u00ed y de todo el pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">\u201cAplicamos 113 mil 200 cuestionarios a las unidades econ\u00f3micas del sector privado y paraestatal que operan en el estado de San Luis Potos\u00ed (\u2026) a las cuales les aplicamos un cuestionario completo porque operaron en el a\u00f1o de referencia 2023 nos arrojan 593 mil 632 personas ocupadas (\u2026) vemos que existe una tendencia de crecimiento sostenido, que inclusive se pudiera identificar que del 2028 al 2023 la tasa de crecimiento de establecimientos fue mayor que en los periodos censales anteriores\u201d.<\/p>\n<p style=\"text-align: justify;\">Otras cifras ofrecidas fueron:<\/p>\n<p style=\"text-align: justify;\">El 95.4 % de los establecimientos eran micronegocios y emplearon a 40.9 % de las personas ocupadas, las mujeres en las actividades econ\u00f3micas tienen una participaci\u00f3n del 44.3%, 2 mil 748 unidades econ\u00f3micas emplearon a personas con alg\u00fan tipo de discapacidad.<\/p>\n<p style=\"text-align: justify;\">Estos datos contribuyen en la toma de decisiones entre las personas propietarias o encargadas de los establecimientos, as\u00ed como entre los sectores p\u00fablico, privado y acad\u00e9mico. Desde 1930, los Censos Econ\u00f3micos se realizan cada cinco a\u00f1os y la presente es la vig\u00e9sima edici\u00f3n.<\/p>\n<p>Por: Juan Carlos Contreras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- El Instituto Nacional de Estad\u00edstica y Geograf\u00eda ofreci\u00f3 los resultados de los Censos Econ\u00f3micos 2024, esto mediante el coordinador estatal en San Luis Potos\u00ed, Arturo Ramos Miranda. \u201cSon 114 mil 17 establecimientos con 601 mil personas ocupadas, en adelante los datos que les vamos a presentar se refieren espec\u00edficamente a sector privado y empresas paraestatales\u201d. Este censo permiten conocer qu\u00e9, cu\u00e1nto, c\u00f3mo, d\u00f3nde y con qu\u00e9 se produce en la econom\u00eda de San Luis Potos\u00ed y de todo el pa\u00eds. \u201cAplicamos 113 mil 200 cuestionarios a las unidades econ\u00f3micas del sector privado y paraestatal que operan en el estado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":155163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-155159","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024 - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024 - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"SLP.- El Instituto Nacional de Estad\u00edstica y Geograf\u00eda ofreci\u00f3 los resultados de los Censos Econ\u00f3micos 2024, esto mediante el coordinador estatal en San Luis Potos\u00ed, Arturo Ramos Miranda. \u201cSon 114 mil 17 establecimientos con 601 mil personas ocupadas, en adelante los datos que les vamos a presentar se refieren espec\u00edficamente a sector privado y empresas paraestatales\u201d. Este censo permiten conocer qu\u00e9, cu\u00e1nto, c\u00f3mo, d\u00f3nde y con qu\u00e9 se produce en la econom\u00eda de San Luis Potos\u00ed y de todo el pa\u00eds. \u201cAplicamos 113 mil 200 cuestionarios a las unidades econ\u00f3micas del sector privado y paraestatal que operan en el estado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T23:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Poky03INEGIRueda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024\",\"datePublished\":\"2025-01-23T23:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/\"},\"wordCount\":263,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Poky03INEGIRueda.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/\",\"name\":\"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024 - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Poky03INEGIRueda.jpg\",\"datePublished\":\"2025-01-23T23:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Poky03INEGIRueda.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Poky03INEGIRueda.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/inegi-presento-los-resultados-de-los-censos-economicos-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024 - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/","og_locale":"es_ES","og_type":"article","og_title":"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024 - Canal 7 SLP - 2025","og_description":"SLP.- El Instituto Nacional de Estad\u00edstica y Geograf\u00eda ofreci\u00f3 los resultados de los Censos Econ\u00f3micos 2024, esto mediante el coordinador estatal en San Luis Potos\u00ed, Arturo Ramos Miranda. \u201cSon 114 mil 17 establecimientos con 601 mil personas ocupadas, en adelante los datos que les vamos a presentar se refieren espec\u00edficamente a sector privado y empresas paraestatales\u201d. Este censo permiten conocer qu\u00e9, cu\u00e1nto, c\u00f3mo, d\u00f3nde y con qu\u00e9 se produce en la econom\u00eda de San Luis Potos\u00ed y de todo el pa\u00eds. \u201cAplicamos 113 mil 200 cuestionarios a las unidades econ\u00f3micas del sector privado y paraestatal que operan en el estado [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-01-23T23:49:29+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Poky03INEGIRueda.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024","datePublished":"2025-01-23T23:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/"},"wordCount":263,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Poky03INEGIRueda.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/","url":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/","name":"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024 - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Poky03INEGIRueda.jpg","datePublished":"2025-01-23T23:49:29+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Poky03INEGIRueda.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/Poky03INEGIRueda.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/inegi-presento-los-resultados-de-los-censos-economicos-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"INEGI present\u00f3 los resultados de los Censos Econ\u00f3micos 2024"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/155159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=155159"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/155159\/revisions"}],"predecessor-version":[{"id":155164,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/155159\/revisions\/155164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/155163"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=155159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=155159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=155159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}