{"id":154667,"date":"2025-01-18T14:55:54","date_gmt":"2025-01-18T20:55:54","guid":{"rendered":"https:\/\/canal7slp.tv\/2025\/?p=154667"},"modified":"2025-01-18T14:55:54","modified_gmt":"2025-01-18T20:55:54","slug":"sequias-severas-crecen-en-intensidad-y-alcance-global-science","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/","title":{"rendered":"Sequ\u00edas severas crecen en intensidad y alcance global: Science"},"content":{"rendered":"<p style=\"text-align: justify;\">Washington DC.- Un reciente estudio del Instituto Federal Suizo de Investigaci\u00f3n Forestal, de la Nieve y del Paisaje (WSL) y del Instituto de Ciencia y Tecnolog\u00eda de Austria (ISTA), publicado en la revista Science, alerta sobre el preocupante aumento en la duraci\u00f3n, intensidad y frecuencia de las sequ\u00edas graves durante las \u00faltimas cuatro d\u00e9cadas. Este fen\u00f3meno amenaza gravemente los ecosistemas, la agricultura y la producci\u00f3n energ\u00e9tica, con proyecciones que anticipan episodios plurianuales, capaces de extenderse por a\u00f1os o incluso d\u00e9cadas, afectando especialmente a las praderas templadas como las de Estados Unidos.<\/p>\n<p style=\"text-align: justify;\">Las sequ\u00edas han demostrado ser devastadoras, agotando la humedad del suelo, reduciendo el caudal de los r\u00edos y causando da\u00f1os irreversibles como la p\u00e9rdida de cosechas y la mortalidad de \u00e1rboles. Chile es un ejemplo claro, enfrentando desde 2010 su sequ\u00eda m\u00e1s prolongada en mil a\u00f1os, que ha secado casi por completo las reservas de agua del pa\u00eds, impactando severamente la agricultura y la miner\u00eda. Por otro lado, el oeste de Estados Unidos experiment\u00f3 entre 2000 y 2018 una sequ\u00eda severa que tambi\u00e9n dej\u00f3 consecuencias significativas.<\/p>\n<p style=\"text-align: justify;\">El estudio analiz\u00f3 datos meteorol\u00f3gicos globales entre 1980 y 2018, registrando 13 mil 176 sequ\u00edas plurianuales. Este an\u00e1lisis permiti\u00f3 identificar anomal\u00edas en las precipitaciones y la evapotranspiraci\u00f3n, as\u00ed como su impacto en diversos ecosistemas. Seg\u00fan los hallazgos, las \u00e1reas afectadas por sequ\u00edas han crecido a un ritmo promedio de 50 mil kil\u00f3metros cuadrados por a\u00f1o, una superficie comparable a la de Eslovaquia.<\/p>\n<p style=\"text-align: justify;\">Las regiones m\u00e1s impactadas incluyen el oeste de Estados Unidos, el centro y este de Mongolia, y el sureste de Australia. En t\u00e9rminos de recuperaci\u00f3n, los pastizales templados han demostrado ser m\u00e1s resilientes, recuper\u00e1ndose r\u00e1pidamente tras una sequ\u00eda, mientras que los bosques boreales y tropicales requieren mucho m\u00e1s tiempo para superar estos eventos extremos.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Washington DC.- Un reciente estudio del Instituto Federal Suizo de Investigaci\u00f3n Forestal, de la Nieve y del Paisaje (WSL) y del Instituto de Ciencia y Tecnolog\u00eda de Austria (ISTA), publicado en la revista Science, alerta sobre el preocupante aumento en la duraci\u00f3n, intensidad y frecuencia de las sequ\u00edas graves durante las \u00faltimas cuatro d\u00e9cadas. Este fen\u00f3meno amenaza gravemente los ecosistemas, la agricultura y la producci\u00f3n energ\u00e9tica, con proyecciones que anticipan episodios plurianuales, capaces de extenderse por a\u00f1os o incluso d\u00e9cadas, afectando especialmente a las praderas templadas como las de Estados Unidos. Las sequ\u00edas han demostrado ser devastadoras, agotando la humedad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":154668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-154667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sequ\u00edas severas crecen en intensidad y alcance global: Science - Canal 7 SLP - 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sequ\u00edas severas crecen en intensidad y alcance global: Science - Canal 7 SLP - 2025\" \/>\n<meta property=\"og:description\" content=\"Washington DC.- Un reciente estudio del Instituto Federal Suizo de Investigaci\u00f3n Forestal, de la Nieve y del Paisaje (WSL) y del Instituto de Ciencia y Tecnolog\u00eda de Austria (ISTA), publicado en la revista Science, alerta sobre el preocupante aumento en la duraci\u00f3n, intensidad y frecuencia de las sequ\u00edas graves durante las \u00faltimas cuatro d\u00e9cadas. Este fen\u00f3meno amenaza gravemente los ecosistemas, la agricultura y la producci\u00f3n energ\u00e9tica, con proyecciones que anticipan episodios plurianuales, capaces de extenderse por a\u00f1os o incluso d\u00e9cadas, afectando especialmente a las praderas templadas como las de Estados Unidos. Las sequ\u00edas han demostrado ser devastadoras, agotando la humedad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2025\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-18T20:55:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/08-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\"},\"headline\":\"Sequ\u00edas severas crecen en intensidad y alcance global: Science\",\"datePublished\":\"2025-01-18T20:55:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/\"},\"wordCount\":334,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/08-16.jpg\",\"articleSection\":[\"INTERNACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/\",\"name\":\"Sequ\u00edas severas crecen en intensidad y alcance global: Science - Canal 7 SLP - 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/08-16.jpg\",\"datePublished\":\"2025-01-18T20:55:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/08-16.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/08-16.jpg\",\"width\":890,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sequ\u00edas severas crecen en intensidad y alcance global: Science\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos el Medio\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/#\\\/schema\\\/person\\\/271e2b60a96e7cc9d9ac296f4d7e414b\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2025\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sequ\u00edas severas crecen en intensidad y alcance global: Science - Canal 7 SLP - 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/","og_locale":"es_ES","og_type":"article","og_title":"Sequ\u00edas severas crecen en intensidad y alcance global: Science - Canal 7 SLP - 2025","og_description":"Washington DC.- Un reciente estudio del Instituto Federal Suizo de Investigaci\u00f3n Forestal, de la Nieve y del Paisaje (WSL) y del Instituto de Ciencia y Tecnolog\u00eda de Austria (ISTA), publicado en la revista Science, alerta sobre el preocupante aumento en la duraci\u00f3n, intensidad y frecuencia de las sequ\u00edas graves durante las \u00faltimas cuatro d\u00e9cadas. Este fen\u00f3meno amenaza gravemente los ecosistemas, la agricultura y la producci\u00f3n energ\u00e9tica, con proyecciones que anticipan episodios plurianuales, capaces de extenderse por a\u00f1os o incluso d\u00e9cadas, afectando especialmente a las praderas templadas como las de Estados Unidos. Las sequ\u00edas han demostrado ser devastadoras, agotando la humedad [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/","og_site_name":"Canal 7 SLP - 2025","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2025-01-18T20:55:54+00:00","og_image":[{"width":890,"height":500,"url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/08-16.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b"},"headline":"Sequ\u00edas severas crecen en intensidad y alcance global: Science","datePublished":"2025-01-18T20:55:54+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/"},"wordCount":334,"publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/08-16.jpg","articleSection":["INTERNACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/","url":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/","name":"Sequ\u00edas severas crecen en intensidad y alcance global: Science - Canal 7 SLP - 2025","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/08-16.jpg","datePublished":"2025-01-18T20:55:54+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#primaryimage","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/08-16.jpg","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2025\/01\/08-16.jpg","width":890,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2025\/sequias-severas-crecen-en-intensidad-y-alcance-global-science\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2025\/"},{"@type":"ListItem","position":2,"name":"Sequ\u00edas severas crecen en intensidad y alcance global: Science"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2025\/#website","url":"https:\/\/canal7slp.tv\/2025\/","name":"N7 - Noticieros Canal 7","description":"Somos el Medio","publisher":{"@id":"https:\/\/canal7slp.tv\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2025\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2025\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2025\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2025\/#\/schema\/person\/271e2b60a96e7cc9d9ac296f4d7e414b","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2025\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/154667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/comments?post=154667"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/154667\/revisions"}],"predecessor-version":[{"id":154669,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/posts\/154667\/revisions\/154669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media\/154668"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/media?parent=154667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/categories?post=154667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2025\/wp-json\/wp\/v2\/tags?post=154667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}