{"id":147116,"date":"2024-11-01T19:06:01","date_gmt":"2024-11-02T01:06:01","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=147116"},"modified":"2024-11-01T19:06:01","modified_gmt":"2024-11-02T01:06:01","slug":"ciudadanas-limpian-tumbas-abandonadas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/","title":{"rendered":"Ciudadanas limpian tumbas abandonadas"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Como parte de las acciones que definen a las ciudadanas de la familia Castillo, la limpieza de tumbas en el pante\u00f3n del Saucito es importante.<\/p>\n<p style=\"text-align: justify;\">Mar\u00eda Elena Castillo Mata empez\u00f3 la costumbre de dar limpieza a las tumbas aleda\u00f1as a donde se encuentra parte de su familia.<\/p>\n<p style=\"text-align: justify;\">\u201cCada a\u00f1o, ya tenemos como tres a\u00f1os que nos dedicamos en estos d\u00edas a lo que es la limpieza de las tumbas en abandono y les ponemos un detallito que es como este, cada a\u00f1o ya estamos tomando de venir cada a\u00f1o a hacer esta labor\u201d.<\/p>\n<p style=\"text-align: justify;\">Todo empez\u00f3 como un acto de buena fe.<\/p>\n<p style=\"text-align: justify;\">\u201cLo que pasa que bueno aqu\u00ed est\u00e1 mi hermana, all\u00e1 tambi\u00e9n est\u00e1 otra hermana y all\u00e1 est\u00e1 mi pap\u00e1, yo vengo cada semana, cada 15 d\u00edas al pante\u00f3n y yo veo muchas tumbas que est\u00e1n pues ahora s\u00ed que en completo abandono y pues aunque sea una vez al a\u00f1o que sean recordados\u201d.<\/p>\n<p style=\"text-align: justify;\">La familia emul\u00f3 el esfuerzo de inmediato.<\/p>\n<p style=\"text-align: justify;\">\u201cMis hermanas siempre me han apoyado, lo que es mi familia, mi cu\u00f1ada, mis hermanas, mi sobrina, pues yo creo que eso nos lo fomentaron muy chicos nuestro pap\u00e1s de venir\u201d.<\/p>\n<p style=\"text-align: justify;\">La cantidad de tumbas en abandono es amplia.<\/p>\n<p style=\"text-align: justify;\">\u201cHay tumbas que por ejemplo ay est\u00e1n derrumbadas donde hay pues ahora s\u00ed que no tienen ni siquiera un florero donde ponerle flores, gente que a lo mejor t\u00fa las ves y es de 1800 y algo, entonces ya pr\u00e1cticamente nadie viene a verlas, entonces es por eso que pues esta labora para que sigan record\u00e1ndolos y para que vean que no est\u00e1n en el olvido\u201d.<\/p>\n<p style=\"text-align: justify;\">Pidi\u00f3 a la poblaci\u00f3n no olvidarse de sus difuntos y dar la limpieza necesaria en los sitios de su entierro.<\/p>\n<p>Por: Juan Carlos Contreras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Como parte de las acciones que definen a las ciudadanas de la familia Castillo, la limpieza de tumbas en el pante\u00f3n del Saucito es importante. Mar\u00eda Elena Castillo Mata empez\u00f3 la costumbre de dar limpieza a las tumbas aleda\u00f1as a donde se encuentra parte de su familia. \u201cCada a\u00f1o, ya tenemos como tres a\u00f1os que nos dedicamos en estos d\u00edas a lo que es la limpieza de las tumbas en abandono y les ponemos un detallito que es como este, cada a\u00f1o ya estamos tomando de venir cada a\u00f1o a hacer esta labor\u201d. Todo empez\u00f3 como un acto de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":147129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-147116","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciudadanas limpian tumbas abandonadas - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciudadanas limpian tumbas abandonadas - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Como parte de las acciones que definen a las ciudadanas de la familia Castillo, la limpieza de tumbas en el pante\u00f3n del Saucito es importante. Mar\u00eda Elena Castillo Mata empez\u00f3 la costumbre de dar limpieza a las tumbas aleda\u00f1as a donde se encuentra parte de su familia. \u201cCada a\u00f1o, ya tenemos como tres a\u00f1os que nos dedicamos en estos d\u00edas a lo que es la limpieza de las tumbas en abandono y les ponemos un detallito que es como este, cada a\u00f1o ya estamos tomando de venir cada a\u00f1o a hacer esta labor\u201d. Todo empez\u00f3 como un acto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-02T01:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/11\/Poky0BuenaFe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Ciudadanas limpian tumbas abandonadas\",\"datePublished\":\"2024-11-02T01:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/\"},\"wordCount\":314,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Poky0BuenaFe.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/\",\"name\":\"Ciudadanas limpian tumbas abandonadas - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Poky0BuenaFe.jpg\",\"datePublished\":\"2024-11-02T01:06:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Poky0BuenaFe.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Poky0BuenaFe.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ciudadanas-limpian-tumbas-abandonadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciudadanas limpian tumbas abandonadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciudadanas limpian tumbas abandonadas - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/","og_locale":"es_ES","og_type":"article","og_title":"Ciudadanas limpian tumbas abandonadas - Canal 7 SLP - 2024","og_description":"SLP.- Como parte de las acciones que definen a las ciudadanas de la familia Castillo, la limpieza de tumbas en el pante\u00f3n del Saucito es importante. Mar\u00eda Elena Castillo Mata empez\u00f3 la costumbre de dar limpieza a las tumbas aleda\u00f1as a donde se encuentra parte de su familia. \u201cCada a\u00f1o, ya tenemos como tres a\u00f1os que nos dedicamos en estos d\u00edas a lo que es la limpieza de las tumbas en abandono y les ponemos un detallito que es como este, cada a\u00f1o ya estamos tomando de venir cada a\u00f1o a hacer esta labor\u201d. Todo empez\u00f3 como un acto de [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-11-02T01:06:01+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/11\/Poky0BuenaFe.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Ciudadanas limpian tumbas abandonadas","datePublished":"2024-11-02T01:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/"},"wordCount":314,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/11\/Poky0BuenaFe.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/","url":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/","name":"Ciudadanas limpian tumbas abandonadas - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/11\/Poky0BuenaFe.jpg","datePublished":"2024-11-02T01:06:01+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/11\/Poky0BuenaFe.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/11\/Poky0BuenaFe.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/ciudadanas-limpian-tumbas-abandonadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Ciudadanas limpian tumbas abandonadas"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/147116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=147116"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/147116\/revisions"}],"predecessor-version":[{"id":147137,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/147116\/revisions\/147137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/147129"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=147116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=147116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=147116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}