{"id":146906,"date":"2024-10-31T13:19:32","date_gmt":"2024-10-31T19:19:32","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=146906"},"modified":"2024-10-31T13:19:32","modified_gmt":"2024-10-31T19:19:32","slug":"parra-y-santos-protagonistas-en-vuelta-a-guatemala","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/","title":{"rendered":"Parra y Santos protagonistas en Vuelta a Guatemala"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Las acciones de la 63 Vuelta a Guatemala continuaron con la etapa reina, quinto d\u00eda de competencia en donde los integrantes del equipo potosino de ciclismo se enfrentaron a la prueba m\u00e1s dura del trayecto en este recorrido de diez d\u00edas teniendo como sus mejores representantes a Heiner Parra y Efr\u00e9n Santos quienes lucharon por la punta hasta los \u00faltimos kil\u00f3metros.<\/p>\n<p style=\"text-align: justify;\">Recorrido de 155 kil\u00f3metros en total dando inicio en la localidad de Ocos y finalizando en lo alto de Totonicap\u00e1n, nuevamente apareci\u00f3 la monta\u00f1a y lo hizo con seis puertos, siendo el primero de ellos de segunda categor\u00eda sobre los 60,5 km; a partir de all\u00ed se generaron algunas diferencias en el pelot\u00f3n teniendo a Parra y Santos como unos de los principales protagonistas dentro de las escapadas.<\/p>\n<p style=\"text-align: justify;\">El orden de llegada por parte de los integrantes del equipo potosino de ciclismo en la etapa reina fue con Heiner Parra, Efr\u00e9n Santos, Sebasti\u00e1n Brenes, Ignacio Prado, Cormac McGeough y Eduardo Corte, dentro de la clasificaci\u00f3n general Efr\u00e9n Santos se coloca en 14 a 11:36 minutos del l\u00edder un poco m\u00e1s atr\u00e1s Heiner Parra e Ignacio Prado, por equipos lugar ocho, en clasificaci\u00f3n general por puntos Cormac McGeough es d\u00e9cimo con 23 y Santos es quince con 18 unidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Las acciones de la 63 Vuelta a Guatemala continuaron con la etapa reina, quinto d\u00eda de competencia en donde los integrantes del equipo potosino de ciclismo se enfrentaron a la prueba m\u00e1s dura del trayecto en este recorrido de diez d\u00edas teniendo como sus mejores representantes a Heiner Parra y Efr\u00e9n Santos quienes lucharon por la punta hasta los \u00faltimos kil\u00f3metros. Recorrido de 155 kil\u00f3metros en total dando inicio en la localidad de Ocos y finalizando en lo alto de Totonicap\u00e1n, nuevamente apareci\u00f3 la monta\u00f1a y lo hizo con seis puertos, siendo el primero de ellos de segunda categor\u00eda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":146913,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-146906","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parra y Santos protagonistas en Vuelta a Guatemala - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parra y Santos protagonistas en Vuelta a Guatemala - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Las acciones de la 63 Vuelta a Guatemala continuaron con la etapa reina, quinto d\u00eda de competencia en donde los integrantes del equipo potosino de ciclismo se enfrentaron a la prueba m\u00e1s dura del trayecto en este recorrido de diez d\u00edas teniendo como sus mejores representantes a Heiner Parra y Efr\u00e9n Santos quienes lucharon por la punta hasta los \u00faltimos kil\u00f3metros. Recorrido de 155 kil\u00f3metros en total dando inicio en la localidad de Ocos y finalizando en lo alto de Totonicap\u00e1n, nuevamente apareci\u00f3 la monta\u00f1a y lo hizo con seis puertos, siendo el primero de ellos de segunda categor\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T19:19:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Froi02Ciclismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Parra y Santos protagonistas en Vuelta a Guatemala\",\"datePublished\":\"2024-10-31T19:19:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Froi02Ciclismo.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/\",\"name\":\"Parra y Santos protagonistas en Vuelta a Guatemala - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Froi02Ciclismo.jpg\",\"datePublished\":\"2024-10-31T19:19:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Froi02Ciclismo.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Froi02Ciclismo.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parra y Santos protagonistas en Vuelta a Guatemala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parra y Santos protagonistas en Vuelta a Guatemala - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/","og_locale":"es_ES","og_type":"article","og_title":"Parra y Santos protagonistas en Vuelta a Guatemala - Canal 7 SLP - 2024","og_description":"SLP.- Las acciones de la 63 Vuelta a Guatemala continuaron con la etapa reina, quinto d\u00eda de competencia en donde los integrantes del equipo potosino de ciclismo se enfrentaron a la prueba m\u00e1s dura del trayecto en este recorrido de diez d\u00edas teniendo como sus mejores representantes a Heiner Parra y Efr\u00e9n Santos quienes lucharon por la punta hasta los \u00faltimos kil\u00f3metros. Recorrido de 155 kil\u00f3metros en total dando inicio en la localidad de Ocos y finalizando en lo alto de Totonicap\u00e1n, nuevamente apareci\u00f3 la monta\u00f1a y lo hizo con seis puertos, siendo el primero de ellos de segunda categor\u00eda [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-31T19:19:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Froi02Ciclismo.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Parra y Santos protagonistas en Vuelta a Guatemala","datePublished":"2024-10-31T19:19:32+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/"},"wordCount":231,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Froi02Ciclismo.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/","url":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/","name":"Parra y Santos protagonistas en Vuelta a Guatemala - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Froi02Ciclismo.jpg","datePublished":"2024-10-31T19:19:32+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Froi02Ciclismo.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Froi02Ciclismo.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/parra-y-santos-protagonistas-en-vuelta-a-guatemala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Parra y Santos protagonistas en Vuelta a Guatemala"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/146906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=146906"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/146906\/revisions"}],"predecessor-version":[{"id":146917,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/146906\/revisions\/146917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/146913"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=146906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=146906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=146906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}