{"id":145145,"date":"2024-10-16T10:51:46","date_gmt":"2024-10-16T16:51:46","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=145145"},"modified":"2024-10-16T11:03:00","modified_gmt":"2024-10-16T17:03:00","slug":"subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/","title":{"rendered":"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz"},"content":{"rendered":"<ul>\n<li>Im\u00e1genes compartidas advertir\u00edan que supuestamente llevaba un arma y trascendi\u00f3 que ya fue destituido.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">SLP.- Una camioneta del Instituto Potosino del Deporte (INPODE) fue captada en un accidente en Jacarandas.<\/p>\n<div style=\"width: 478px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-145145-1\" width=\"478\" height=\"850\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.mp4?_=1\" \/><a href=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.mp4\">https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.mp4<\/a><\/video><\/div>\n<p style=\"text-align: justify;\">Supuestamente estar\u00eda involucrado quien ocupara la subdirecci\u00f3n de Deporte Social, Roberto Cabrales.<\/p>\n<p style=\"text-align: justify;\">En un video se advirti\u00f3 que al parecer portaba un arma.<\/p>\n<p style=\"text-align: justify;\">Trascendi\u00f3 que la persona fue destituida tras los hechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im\u00e1genes compartidas advertir\u00edan que supuestamente llevaba un arma y trascendi\u00f3 que ya fue destituido. SLP.- Una camioneta del Instituto Potosino del Deporte (INPODE) fue captada en un accidente en Jacarandas. Supuestamente estar\u00eda involucrado quien ocupara la subdirecci\u00f3n de Deporte Social, Roberto Cabrales. En un video se advirti\u00f3 que al parecer portaba un arma. Trascendi\u00f3 que la persona fue destituida tras los hechos.<\/p>\n","protected":false},"author":2,"featured_media":145146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-145145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-localesyregionales","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"Im\u00e1genes compartidas advertir\u00edan que supuestamente llevaba un arma y trascendi\u00f3 que ya fue destituido. SLP.- Una camioneta del Instituto Potosino del Deporte (INPODE) fue captada en un accidente en Jacarandas. Supuestamente estar\u00eda involucrado quien ocupara la subdirecci\u00f3n de Deporte Social, Roberto Cabrales. En un video se advirti\u00f3 que al parecer portaba un arma. Trascendi\u00f3 que la persona fue destituida tras los hechos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-16T16:51:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-16T17:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1303\" \/>\n\t<meta property=\"og:image:height\" content=\"992\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz\",\"datePublished\":\"2024-10-16T16:51:46+00:00\",\"dateModified\":\"2024-10-16T17:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vialidad01.jpeg\",\"articleSection\":[\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/\",\"name\":\"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vialidad01.jpeg\",\"datePublished\":\"2024-10-16T16:51:46+00:00\",\"dateModified\":\"2024-10-16T17:03:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vialidad01.jpeg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vialidad01.jpeg\",\"width\":1303,\"height\":992},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/","og_locale":"es_ES","og_type":"article","og_title":"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz - Canal 7 SLP - 2024","og_description":"Im\u00e1genes compartidas advertir\u00edan que supuestamente llevaba un arma y trascendi\u00f3 que ya fue destituido. SLP.- Una camioneta del Instituto Potosino del Deporte (INPODE) fue captada en un accidente en Jacarandas. Supuestamente estar\u00eda involucrado quien ocupara la subdirecci\u00f3n de Deporte Social, Roberto Cabrales. En un video se advirti\u00f3 que al parecer portaba un arma. Trascendi\u00f3 que la persona fue destituida tras los hechos.","og_url":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-16T16:51:46+00:00","article_modified_time":"2024-10-16T17:03:00+00:00","og_image":[{"width":1303,"height":992,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.jpeg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz","datePublished":"2024-10-16T16:51:46+00:00","dateModified":"2024-10-16T17:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/"},"wordCount":92,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.jpeg","articleSection":["LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/","url":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/","name":"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.jpeg","datePublished":"2024-10-16T16:51:46+00:00","dateModified":"2024-10-16T17:03:00+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.jpeg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vialidad01.jpeg","width":1303,"height":992},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/subdirector-del-inpode-aparentemente-implicado-en-choque-en-prolongacion-munoz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Subdirector del INPODE, aparentemente implicado en choque en Prolongaci\u00f3n Mu\u00f1oz"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/145145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=145145"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/145145\/revisions"}],"predecessor-version":[{"id":145150,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/145145\/revisions\/145150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/145146"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=145145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=145145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=145145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}