{"id":144845,"date":"2024-10-13T15:20:26","date_gmt":"2024-10-13T21:20:26","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=144845"},"modified":"2024-10-14T11:27:35","modified_gmt":"2024-10-14T17:27:35","slug":"secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/","title":{"rendered":"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- El Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) ha instruido a la Secretar\u00eda de Bienestar a proporcionar un desglose detallado sobre el uso de los 2.7 billones de pesos asignados a programas de bienestar entre 2019 y 2024, incluyendo el impacto en 28 millones de beneficiarios. La resoluci\u00f3n se tom\u00f3 tras una solicitud ciudadana presentada en una conferencia matutina de la Presidencia de la Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Un ciudadano pidi\u00f3 un informe sobre el monto y el n\u00famero de beneficiarios, desglosado por entidad federativa y programa. Sin embargo, la Secretar\u00eda respondi\u00f3 que no dispon\u00eda de la informaci\u00f3n solicitada, lo que llev\u00f3 al solicitante a presentar una queja ante el INAI, respaldada por un comunicado oficial que indicaba la existencia de los datos.<\/p>\n<p style=\"text-align: justify;\">La comisionada Norma Julieta del R\u00edo Venegas revis\u00f3 el caso y determin\u00f3 que la Secretar\u00eda de Bienestar no hab\u00eda realizado una b\u00fasqueda exhaustiva en todas sus \u00e1reas competentes, como la Subsecretar\u00eda de Bienestar y otras unidades administrativas relevantes.<\/p>\n<p style=\"text-align: justify;\">Del R\u00edo Venegas subray\u00f3 que, dado el manejo de una suma tan significativa de recursos p\u00fablicos y su responsabilidad en la implementaci\u00f3n de programas sociales, la Secretar\u00eda tiene la obligaci\u00f3n de rendir cuentas de manera clara y accesible.<\/p>\n<p style=\"text-align: justify;\">Por unanimidad, el Pleno del INAI revoc\u00f3 la respuesta inicial de la Secretar\u00eda de Bienestar y le orden\u00f3 realizar una nueva b\u00fasqueda en todas sus unidades administrativas para proporcionar la informaci\u00f3n requerida.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- El Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) ha instruido a la Secretar\u00eda de Bienestar a proporcionar un desglose detallado sobre el uso de los 2.7 billones de pesos asignados a programas de bienestar entre 2019 y 2024, incluyendo el impacto en 28 millones de beneficiarios. La resoluci\u00f3n se tom\u00f3 tras una solicitud ciudadana presentada en una conferencia matutina de la Presidencia de la Rep\u00fablica. Un ciudadano pidi\u00f3 un informe sobre el monto y el n\u00famero de beneficiarios, desglosado por entidad federativa y programa. Sin embargo, la Secretar\u00eda respondi\u00f3 que no dispon\u00eda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-144845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- El Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) ha instruido a la Secretar\u00eda de Bienestar a proporcionar un desglose detallado sobre el uso de los 2.7 billones de pesos asignados a programas de bienestar entre 2019 y 2024, incluyendo el impacto en 28 millones de beneficiarios. La resoluci\u00f3n se tom\u00f3 tras una solicitud ciudadana presentada en una conferencia matutina de la Presidencia de la Rep\u00fablica. Un ciudadano pidi\u00f3 un informe sobre el monto y el n\u00famero de beneficiarios, desglosado por entidad federativa y programa. Sin embargo, la Secretar\u00eda respondi\u00f3 que no dispon\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-13T21:20:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T17:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/03-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI\",\"datePublished\":\"2024-10-13T21:20:26+00:00\",\"dateModified\":\"2024-10-14T17:27:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/\"},\"wordCount\":268,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/03-11.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/\",\"name\":\"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/03-11.jpg\",\"datePublished\":\"2024-10-13T21:20:26+00:00\",\"dateModified\":\"2024-10-14T17:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/03-11.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/03-11.jpg\",\"width\":786,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/","og_locale":"es_ES","og_type":"article","og_title":"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- El Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) ha instruido a la Secretar\u00eda de Bienestar a proporcionar un desglose detallado sobre el uso de los 2.7 billones de pesos asignados a programas de bienestar entre 2019 y 2024, incluyendo el impacto en 28 millones de beneficiarios. La resoluci\u00f3n se tom\u00f3 tras una solicitud ciudadana presentada en una conferencia matutina de la Presidencia de la Rep\u00fablica. Un ciudadano pidi\u00f3 un informe sobre el monto y el n\u00famero de beneficiarios, desglosado por entidad federativa y programa. Sin embargo, la Secretar\u00eda respondi\u00f3 que no dispon\u00eda [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-13T21:20:26+00:00","article_modified_time":"2024-10-14T17:27:35+00:00","og_image":[{"width":786,"height":500,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/03-11.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI","datePublished":"2024-10-13T21:20:26+00:00","dateModified":"2024-10-14T17:27:35+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/"},"wordCount":268,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/03-11.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/","url":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/","name":"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/03-11.jpg","datePublished":"2024-10-13T21:20:26+00:00","dateModified":"2024-10-14T17:27:35+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/03-11.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/03-11.jpg","width":786,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/secretaria-del-bienestar-debe-transparentar-uso-de-2-7-billones-de-pesos-inai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Secretar\u00eda del Bienestar debe transparentar uso de 2.7 billones de pesos: INAI"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=144845"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144845\/revisions"}],"predecessor-version":[{"id":144902,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144845\/revisions\/144902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/144859"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=144845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=144845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=144845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}