{"id":144822,"date":"2024-10-14T06:32:28","date_gmt":"2024-10-14T12:32:28","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=144822"},"modified":"2024-10-14T06:32:28","modified_gmt":"2024-10-14T12:32:28","slug":"se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/","title":{"rendered":"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas"},"content":{"rendered":"<ul>\n<li>Neg\u00f3 que Movimiento Ciudadano sea partido sat\u00e9lite del gallardismo.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">SLP.- El coordinador estatal y diputado local del partido Movimiento Ciudadano Marco Antonio Gama Basarte rechaz\u00f3 tajante que el nombramiento de su suplente como\u00a0 titular de la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, Jorge D\u00edaz Salinas, haya sido una negociaci\u00f3n con el titular del ejecutivo estatal \u00f3 que Movimiento Ciudadano sea un partido sat\u00e9lite del gallardismo.<\/p>\n<p style=\"text-align: justify;\">Como se recordar\u00e1, Jorge D\u00edaz Salinas form\u00f3 parte de la llamada Ecuaci\u00f3n Corrupta un caso que se destap\u00f3 el 17 de Junio de 2017 en la Sexag\u00e9sima Primera Legislatura trav\u00e9s de la difusi\u00f3n de un video, protagonizado por el exdiputado Enrique Flores y en donde se\u00f1ala a los exdiputados Jos\u00e9 Guadalupe Torres S\u00e1nchez, \u00d3scar Bautista Villegas y Manuel Barrera Guill\u00e9n, de pedir una comisi\u00f3n a presidentes municipales a cambio de limpiar sus cuentas.<\/p>\n<p style=\"text-align: justify;\">En otro orden de ideas, el coordinador estatal de Movimiento Ciudadano neg\u00f3 que haya recomendado a su esposa para darle un cargo en el \u00e1rea de seguridad, al decir que estos se\u00f1alamientos \u201cson fuego amigo naranja\u201d y que dijo, investigar\u00e1 su origen.<\/p>\n<p>Por: Claudio IBarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neg\u00f3 que Movimiento Ciudadano sea partido sat\u00e9lite del gallardismo. SLP.- El coordinador estatal y diputado local del partido Movimiento Ciudadano Marco Antonio Gama Basarte rechaz\u00f3 tajante que el nombramiento de su suplente como\u00a0 titular de la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, Jorge D\u00edaz Salinas, haya sido una negociaci\u00f3n con el titular del ejecutivo estatal \u00f3 que Movimiento Ciudadano sea un partido sat\u00e9lite del gallardismo. Como se recordar\u00e1, Jorge D\u00edaz Salinas form\u00f3 parte de la llamada Ecuaci\u00f3n Corrupta un caso que se destap\u00f3 el 17 de Junio de 2017 en la Sexag\u00e9sima Primera Legislatura trav\u00e9s de la difusi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-144822","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"Neg\u00f3 que Movimiento Ciudadano sea partido sat\u00e9lite del gallardismo. SLP.- El coordinador estatal y diputado local del partido Movimiento Ciudadano Marco Antonio Gama Basarte rechaz\u00f3 tajante que el nombramiento de su suplente como\u00a0 titular de la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, Jorge D\u00edaz Salinas, haya sido una negociaci\u00f3n con el titular del ejecutivo estatal \u00f3 que Movimiento Ciudadano sea un partido sat\u00e9lite del gallardismo. Como se recordar\u00e1, Jorge D\u00edaz Salinas form\u00f3 parte de la llamada Ecuaci\u00f3n Corrupta un caso que se destap\u00f3 el 17 de Junio de 2017 en la Sexag\u00e9sima Primera Legislatura trav\u00e9s de la difusi\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T12:32:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Claudio0MarcoGama.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas\",\"datePublished\":\"2024-10-14T12:32:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/\"},\"wordCount\":210,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Claudio0MarcoGama.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/\",\"name\":\"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Claudio0MarcoGama.jpg\",\"datePublished\":\"2024-10-14T12:32:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Claudio0MarcoGama.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Claudio0MarcoGama.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/","og_locale":"es_ES","og_type":"article","og_title":"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas - Canal 7 SLP - 2024","og_description":"Neg\u00f3 que Movimiento Ciudadano sea partido sat\u00e9lite del gallardismo. SLP.- El coordinador estatal y diputado local del partido Movimiento Ciudadano Marco Antonio Gama Basarte rechaz\u00f3 tajante que el nombramiento de su suplente como\u00a0 titular de la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, Jorge D\u00edaz Salinas, haya sido una negociaci\u00f3n con el titular del ejecutivo estatal \u00f3 que Movimiento Ciudadano sea un partido sat\u00e9lite del gallardismo. Como se recordar\u00e1, Jorge D\u00edaz Salinas form\u00f3 parte de la llamada Ecuaci\u00f3n Corrupta un caso que se destap\u00f3 el 17 de Junio de 2017 en la Sexag\u00e9sima Primera Legislatura trav\u00e9s de la difusi\u00f3n de [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-14T12:32:28+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Claudio0MarcoGama.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas","datePublished":"2024-10-14T12:32:28+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/"},"wordCount":210,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Claudio0MarcoGama.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/","url":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/","name":"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Claudio0MarcoGama.jpg","datePublished":"2024-10-14T12:32:28+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Claudio0MarcoGama.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Claudio0MarcoGama.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/se-desmarca-marco-gama-de-su-suplente-jorge-luis-diaz-salinas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Se desmarca Marco Gama de su suplente, Jorge Luis D\u00edaz Salinas"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=144822"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144822\/revisions"}],"predecessor-version":[{"id":144893,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144822\/revisions\/144893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/144892"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=144822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=144822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=144822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}