{"id":144760,"date":"2024-10-13T19:11:08","date_gmt":"2024-10-14T01:11:08","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=144760"},"modified":"2024-10-13T19:11:08","modified_gmt":"2024-10-14T01:11:08","slug":"es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/","title":{"rendered":"\u00abEs un tema m\u00e1s personal de ellos, no institucional\u00bb, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Una presunta agresi\u00f3n entre el titular del Instituto Potosino del Deporte (INPODE) y la titular del Instituto Potosino de la Juventud (INPOJUVE) ha generado controversia en el \u00e1mbito pol\u00edtico estatal.<\/p>\n<p style=\"text-align: justify;\">El gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, se pronunci\u00f3 sobre el incidente y lo calific\u00f3 como un asunto personal entre los involucrados, sin relaci\u00f3n directa con la gesti\u00f3n institucional.<\/p>\n<p style=\"text-align: justify;\">\u00abPero es un tema diferente a lo del Charro, no tiene nada que ver, el tema del Charro que comentan por ah\u00ed es circunstancial, fue despu\u00e9s de los cambios que se estaban anunciando, eso es con anterioridad y se obedece a los enroques que se est\u00e1n haciendo\u00bb, declar\u00f3<\/p>\n<p style=\"text-align: justify;\">Por otro lado, mencion\u00f3 que la salida de la titular del Inpojuve a\u00fan no estaba definida y aclar\u00f3 que la decisi\u00f3n fue parte de un movimiento interno en la administraci\u00f3n estatal.<\/p>\n<p style=\"text-align: justify;\">\u00abIncluso todav\u00eda no se ten\u00eda prevista la salida de la directora del Inpojuve, posiblemente iba a ser un cambio a un enroque que es lo que tratamos de hacer\u00bb, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">De esa forma, Gallardo Cardona reconoci\u00f3 que la relaci\u00f3n entre ambos funcionarios pareciera estar marcada por temas personales.<\/p>\n<p style=\"text-align: justify;\">\u00abAhorita vamos a ver en qu\u00e9 condiciones est\u00e1 ella tambi\u00e9n porque pareciera que est\u00e1n como perros y gatos los dos, los dos personajes. Es un tema m\u00e1s personal de ellos, no es un tema institucional\u00bb, afirm\u00f3.<\/p>\n<p style=\"text-align: justify;\">Fue as\u00ed como subray\u00f3 la importancia de preservar la integridad de las instituciones del estado, es decir, que este conflicto se resuelva entre las partes involucradas y no afectar el desempe\u00f1o de las entidades gubernamentales.<\/p>\n<p style=\"text-align: justify;\">\u00abLa instituci\u00f3n se debe de respetar y se debe de cuidar, por eso estamos cuidando las instituciones y es un tema que ellos en su momento van a tener que ver entre ellos; es un tema que a la novia, que el compadre\u00bb, concluy\u00f3.<\/p>\n<p>Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Una presunta agresi\u00f3n entre el titular del Instituto Potosino del Deporte (INPODE) y la titular del Instituto Potosino de la Juventud (INPOJUVE) ha generado controversia en el \u00e1mbito pol\u00edtico estatal. El gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, se pronunci\u00f3 sobre el incidente y lo calific\u00f3 como un asunto personal entre los involucrados, sin relaci\u00f3n directa con la gesti\u00f3n institucional. \u00abPero es un tema diferente a lo del Charro, no tiene nada que ver, el tema del Charro que comentan por ah\u00ed es circunstancial, fue despu\u00e9s de los cambios que se estaban anunciando, eso es con anterioridad y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-144760","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Es un tema m\u00e1s personal de ellos, no institucional&quot;, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Es un tema m\u00e1s personal de ellos, no institucional&quot;, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Una presunta agresi\u00f3n entre el titular del Instituto Potosino del Deporte (INPODE) y la titular del Instituto Potosino de la Juventud (INPOJUVE) ha generado controversia en el \u00e1mbito pol\u00edtico estatal. El gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, se pronunci\u00f3 sobre el incidente y lo calific\u00f3 como un asunto personal entre los involucrados, sin relaci\u00f3n directa con la gesti\u00f3n institucional. \u00abPero es un tema diferente a lo del Charro, no tiene nada que ver, el tema del Charro que comentan por ah\u00ed es circunstancial, fue despu\u00e9s de los cambios que se estaban anunciando, eso es con anterioridad y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T01:11:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0Gabinete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"\u00abEs un tema m\u00e1s personal de ellos, no institucional\u00bb, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE\",\"datePublished\":\"2024-10-14T01:11:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/\"},\"wordCount\":349,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0Gabinete.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/\",\"name\":\"\\\"Es un tema m\u00e1s personal de ellos, no institucional\\\", se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0Gabinete.jpg\",\"datePublished\":\"2024-10-14T01:11:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0Gabinete.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0Gabinete.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Es un tema m\u00e1s personal de ellos, no institucional&#8221;, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Es un tema m\u00e1s personal de ellos, no institucional\", se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/","og_locale":"es_ES","og_type":"article","og_title":"\"Es un tema m\u00e1s personal de ellos, no institucional\", se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE - Canal 7 SLP - 2024","og_description":"SLP.- Una presunta agresi\u00f3n entre el titular del Instituto Potosino del Deporte (INPODE) y la titular del Instituto Potosino de la Juventud (INPOJUVE) ha generado controversia en el \u00e1mbito pol\u00edtico estatal. El gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, se pronunci\u00f3 sobre el incidente y lo calific\u00f3 como un asunto personal entre los involucrados, sin relaci\u00f3n directa con la gesti\u00f3n institucional. \u00abPero es un tema diferente a lo del Charro, no tiene nada que ver, el tema del Charro que comentan por ah\u00ed es circunstancial, fue despu\u00e9s de los cambios que se estaban anunciando, eso es con anterioridad y [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-14T01:11:08+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0Gabinete.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"\u00abEs un tema m\u00e1s personal de ellos, no institucional\u00bb, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE","datePublished":"2024-10-14T01:11:08+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/"},"wordCount":349,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0Gabinete.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/","url":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/","name":"\"Es un tema m\u00e1s personal de ellos, no institucional\", se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0Gabinete.jpg","datePublished":"2024-10-14T01:11:08+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0Gabinete.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0Gabinete.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/es-un-tema-mas-personal-de-ellos-no-institucional-senala-gallardo-respecto-conflicto-entre-titulares-del-inpode-y-del-inpojuve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"&#8220;Es un tema m\u00e1s personal de ellos, no institucional&#8221;, se\u00f1ala Gallardo respecto conflicto entre titulares del INPODE y del INPOJUVE"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=144760"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144760\/revisions"}],"predecessor-version":[{"id":144865,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144760\/revisions\/144865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/144790"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=144760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=144760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=144760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}