{"id":144640,"date":"2024-10-11T11:08:28","date_gmt":"2024-10-11T17:08:28","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=144640"},"modified":"2024-10-11T11:08:28","modified_gmt":"2024-10-11T17:08:28","slug":"bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/","title":{"rendered":"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles"},"content":{"rendered":"<ul>\n<li>En la zona se hab\u00edan reportado aullidos insistentes; aunque la gente busc\u00f3 al animalito, cuando le encontr\u00f3 ya hab\u00eda muerto.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">SLP.- De acuerdo con el jefe del ejecutivo local, Ricardo Gallardo Cardona, la Fiscal\u00eda General de San Luis Potos\u00ed ya investiga un caso de maltrato animal en el municipio de Ciudad Valles.<\/p>\n<p style=\"text-align: justify;\">Los hechos se registraron en la colonia Praderas del R\u00edo, ah\u00ed fue localizado un cachorro enterrado en un campo de f\u00fatbol con la cabeza expuesta al exterior.<\/p>\n<p style=\"text-align: justify;\">\u00abYa lo va a atraer, ya lo est\u00e1 analizando, todo lo que sea maltrato animal en San Luis Potos\u00ed ya est\u00e1 bien penado no tiene por qu\u00e9 existir\u00bb, dijo.<\/p>\n<p style=\"text-align: justify;\">El funcionario aprovech\u00f3 para asegurar que los delitos de esa \u00edndole en la entidad potosina han ido en decremento.<\/p>\n<p style=\"text-align: justify;\">\u00abSe ha hecho una reducci\u00f3n muy grande en esos delitos, antes ni siquiera estaban catalogados como delitos, antes pasaba todos los d\u00edas a diestra y siniestra\u00bb, apunt\u00f3.<\/p>\n<p style=\"text-align: justify;\">Prosigui\u00f3: \u00abPasa uno y luego luego se detecta, luego luego se manda la fiscal\u00eda, se ejecutan \u00f3rdenes de presentaci\u00f3n o de aprehensi\u00f3n para el caso sea necesario\u00bb.<\/p>\n<p style=\"text-align: justify;\">De esa forma, reconoci\u00f3 el trabajo que se realiza desde los diferentes \u00f3rdenes para sancionar a quienes incurren en estos actos.<\/p>\n<p style=\"text-align: justify;\">\u00abLa verdad que ha ayudado mucho en que se endurezca y que hoy tenga un castigo el maltrato animal\u00bb, culmin\u00f3.<\/p>\n<p>Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la zona se hab\u00edan reportado aullidos insistentes; aunque la gente busc\u00f3 al animalito, cuando le encontr\u00f3 ya hab\u00eda muerto. SLP.- De acuerdo con el jefe del ejecutivo local, Ricardo Gallardo Cardona, la Fiscal\u00eda General de San Luis Potos\u00ed ya investiga un caso de maltrato animal en el municipio de Ciudad Valles. Los hechos se registraron en la colonia Praderas del R\u00edo, ah\u00ed fue localizado un cachorro enterrado en un campo de f\u00fatbol con la cabeza expuesta al exterior. \u00abYa lo va a atraer, ya lo est\u00e1 analizando, todo lo que sea maltrato animal en San Luis Potos\u00ed ya est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,510,45],"tags":[],"class_list":["post-144640","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-gobedoslp","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"En la zona se hab\u00edan reportado aullidos insistentes; aunque la gente busc\u00f3 al animalito, cuando le encontr\u00f3 ya hab\u00eda muerto. SLP.- De acuerdo con el jefe del ejecutivo local, Ricardo Gallardo Cardona, la Fiscal\u00eda General de San Luis Potos\u00ed ya investiga un caso de maltrato animal en el municipio de Ciudad Valles. Los hechos se registraron en la colonia Praderas del R\u00edo, ah\u00ed fue localizado un cachorro enterrado en un campo de f\u00fatbol con la cabeza expuesta al exterior. \u00abYa lo va a atraer, ya lo est\u00e1 analizando, todo lo que sea maltrato animal en San Luis Potos\u00ed ya est\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-11T17:08:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0PerritoRGC-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles\",\"datePublished\":\"2024-10-11T17:08:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/\"},\"wordCount\":250,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0PerritoRGC-1.jpg\",\"articleSection\":[\"DESTACADAS\",\"GOBEDOSLP\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/\",\"name\":\"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0PerritoRGC-1.jpg\",\"datePublished\":\"2024-10-11T17:08:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0PerritoRGC-1.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Vazquez0PerritoRGC-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/","og_locale":"es_ES","og_type":"article","og_title":"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles - Canal 7 SLP - 2024","og_description":"En la zona se hab\u00edan reportado aullidos insistentes; aunque la gente busc\u00f3 al animalito, cuando le encontr\u00f3 ya hab\u00eda muerto. SLP.- De acuerdo con el jefe del ejecutivo local, Ricardo Gallardo Cardona, la Fiscal\u00eda General de San Luis Potos\u00ed ya investiga un caso de maltrato animal en el municipio de Ciudad Valles. Los hechos se registraron en la colonia Praderas del R\u00edo, ah\u00ed fue localizado un cachorro enterrado en un campo de f\u00fatbol con la cabeza expuesta al exterior. \u00abYa lo va a atraer, ya lo est\u00e1 analizando, todo lo que sea maltrato animal en San Luis Potos\u00ed ya est\u00e1 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-11T17:08:28+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0PerritoRGC-1.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles","datePublished":"2024-10-11T17:08:28+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/"},"wordCount":250,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0PerritoRGC-1.jpg","articleSection":["DESTACADAS","GOBEDOSLP","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/","url":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/","name":"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0PerritoRGC-1.jpg","datePublished":"2024-10-11T17:08:28+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0PerritoRGC-1.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/Vazquez0PerritoRGC-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/bajo-investigacion-caso-de-perrito-semi-enterrado-vivo-en-ciudad-valles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Bajo investigaci\u00f3n, caso de perrito semi enterrado vivo en Ciudad Valles"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=144640"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144640\/revisions"}],"predecessor-version":[{"id":144700,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144640\/revisions\/144700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/144674"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=144640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=144640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=144640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}