{"id":144485,"date":"2024-10-09T15:10:08","date_gmt":"2024-10-09T21:10:08","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=144485"},"modified":"2024-10-09T19:45:08","modified_gmt":"2024-10-10T01:45:08","slug":"panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/","title":{"rendered":"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h"},"content":{"rendered":"<p style=\"text-align: justify;\">Florida.- El gobernador de Florida, Ron DeSantis, ha emitido una advertencia urgente para que la poblaci\u00f3n evac\u00fae ante la inminente llegada del hurac\u00e1n \u00abMilton\u00bb, que se espera toque tierra esta medianoche en la costa occidental del estado. Actualmente, el hurac\u00e1n ha sido reclasificado como categor\u00eda 4, con vientos m\u00e1ximos sostenidos de 250 km\/h.<\/p>\n<p style=\"text-align: justify;\">DeSantis subray\u00f3 que, aunque los refugios est\u00e1n disponibles, la decisi\u00f3n de evacuar debe tomarse inmediatamente. Advirti\u00f3 sobre los peligros que representan los fuertes vientos y escombros voladores, sugiriendo que la poblaci\u00f3n trate la situaci\u00f3n como si fuera un tornado.<\/p>\n<p style=\"text-align: justify;\">El gobernador inform\u00f3 que, aunque las condiciones en las carreteras son complicadas, se han eliminado los peajes para facilitar el proceso de evacuaci\u00f3n. Tambi\u00e9n recomend\u00f3 a los residentes evacuar hacia refugios dentro de sus propios condados para evitar congesti\u00f3n en las carreteras.<\/p>\n<p style=\"text-align: justify;\">En su actualizaci\u00f3n, se\u00f1al\u00f3 que \u00abMilton\u00bb se encuentra a 340 km al suroeste de Tampa y a 185 km al noroeste de Dry Tortugas. Adem\u00e1s, alert\u00f3 sobre marejadas cicl\u00f3nicas de hasta 3 metros en \u00e1reas vulnerables como Sarasota y Charlotte, enfatizando que la evacuaci\u00f3n en estas zonas es crucial.<\/p>\n<p style=\"text-align: justify;\">Aunque se espera que el hurac\u00e1n se debilite antes de tocar tierra, DeSantis expres\u00f3 su preocupaci\u00f3n por el potencial da\u00f1o que podr\u00eda causar. Las autoridades han implementado medidas preventivas como la construcci\u00f3n de sistemas contra inundaciones y el env\u00edo de generadores a refugios para garantizar el bienestar de los evacuados.<\/p>\n<p style=\"text-align: justify;\">Finalmente, a pesar de que no hay escasez de combustible, la alta demanda ha dejado temporalmente sin suministro a algunas estaciones de servicio.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Florida.- El gobernador de Florida, Ron DeSantis, ha emitido una advertencia urgente para que la poblaci\u00f3n evac\u00fae ante la inminente llegada del hurac\u00e1n \u00abMilton\u00bb, que se espera toque tierra esta medianoche en la costa occidental del estado. Actualmente, el hurac\u00e1n ha sido reclasificado como categor\u00eda 4, con vientos m\u00e1ximos sostenidos de 250 km\/h. DeSantis subray\u00f3 que, aunque los refugios est\u00e1n disponibles, la decisi\u00f3n de evacuar debe tomarse inmediatamente. Advirti\u00f3 sobre los peligros que representan los fuertes vientos y escombros voladores, sugiriendo que la poblaci\u00f3n trate la situaci\u00f3n como si fuera un tornado. El gobernador inform\u00f3 que, aunque las condiciones en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-144485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"Florida.- El gobernador de Florida, Ron DeSantis, ha emitido una advertencia urgente para que la poblaci\u00f3n evac\u00fae ante la inminente llegada del hurac\u00e1n \u00abMilton\u00bb, que se espera toque tierra esta medianoche en la costa occidental del estado. Actualmente, el hurac\u00e1n ha sido reclasificado como categor\u00eda 4, con vientos m\u00e1ximos sostenidos de 250 km\/h. DeSantis subray\u00f3 que, aunque los refugios est\u00e1n disponibles, la decisi\u00f3n de evacuar debe tomarse inmediatamente. Advirti\u00f3 sobre los peligros que representan los fuertes vientos y escombros voladores, sugiriendo que la poblaci\u00f3n trate la situaci\u00f3n como si fuera un tornado. El gobernador inform\u00f3 que, aunque las condiciones en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-09T21:10:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-10T01:45:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/02-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"749\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\\\/h\",\"datePublished\":\"2024-10-09T21:10:08+00:00\",\"dateModified\":\"2024-10-10T01:45:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/\"},\"wordCount\":293,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/02-8.jpg\",\"articleSection\":[\"INTERNACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/\",\"name\":\"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\\\/h - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/02-8.jpg\",\"datePublished\":\"2024-10-09T21:10:08+00:00\",\"dateModified\":\"2024-10-10T01:45:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/02-8.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/02-8.jpg\",\"width\":749,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\\\/h\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/","og_locale":"es_ES","og_type":"article","og_title":"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h - Canal 7 SLP - 2024","og_description":"Florida.- El gobernador de Florida, Ron DeSantis, ha emitido una advertencia urgente para que la poblaci\u00f3n evac\u00fae ante la inminente llegada del hurac\u00e1n \u00abMilton\u00bb, que se espera toque tierra esta medianoche en la costa occidental del estado. Actualmente, el hurac\u00e1n ha sido reclasificado como categor\u00eda 4, con vientos m\u00e1ximos sostenidos de 250 km\/h. DeSantis subray\u00f3 que, aunque los refugios est\u00e1n disponibles, la decisi\u00f3n de evacuar debe tomarse inmediatamente. Advirti\u00f3 sobre los peligros que representan los fuertes vientos y escombros voladores, sugiriendo que la poblaci\u00f3n trate la situaci\u00f3n como si fuera un tornado. El gobernador inform\u00f3 que, aunque las condiciones en [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-09T21:10:08+00:00","article_modified_time":"2024-10-10T01:45:08+00:00","og_image":[{"width":749,"height":500,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/02-8.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h","datePublished":"2024-10-09T21:10:08+00:00","dateModified":"2024-10-10T01:45:08+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/"},"wordCount":293,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/02-8.jpg","articleSection":["INTERNACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/","url":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/","name":"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/02-8.jpg","datePublished":"2024-10-09T21:10:08+00:00","dateModified":"2024-10-10T01:45:08+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/02-8.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/02-8.jpg","width":749,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/panico-se-aduena-de-florida-por-llegada-de-milton-con-viento-a-200-km-h\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"P\u00e1nico se adue\u00f1a de Florida por llegada de Milton, con viento a 200 km\/h"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=144485"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144485\/revisions"}],"predecessor-version":[{"id":144563,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144485\/revisions\/144563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/144499"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=144485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=144485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=144485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}