{"id":144484,"date":"2024-10-09T15:00:59","date_gmt":"2024-10-09T21:00:59","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=144484"},"modified":"2024-10-09T19:39:28","modified_gmt":"2024-10-10T01:39:28","slug":"no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/","title":{"rendered":"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- La presidenta de M\u00e9xico, Claudia Sheinbaum, est\u00e1 impulsando una reforma energ\u00e9tica que busca reclasificar a Petr\u00f3leos Mexicanos (PEMEX) y la Comisi\u00f3n Federal de Electricidad (CFE) como \u00abempresas p\u00fablicas\u00bb. La discusi\u00f3n de esta reforma se llevar\u00e1 a cabo en la C\u00e1mara de Diputados el 9 de octubre.<\/p>\n<p style=\"text-align: justify;\">Sheinbaum sostiene que es necesario revertir la reforma energ\u00e9tica implementada por Enrique Pe\u00f1a Nieto, que permiti\u00f3 la inversi\u00f3n privada en el sector y defini\u00f3 a Pemex y CFE como \u00abempresas productivas del Estado\u00bb. La presidenta argumenta que su nueva reforma tiene como objetivo enfocar a estas compa\u00f1\u00edas en el servicio p\u00fablico en lugar de hacerlas competir directamente con empresas privadas.<\/p>\n<p style=\"text-align: justify;\">La propuesta tambi\u00e9n establece que la CFE controle el 54% de la generaci\u00f3n el\u00e9ctrica, mientras que el 46% restante quedar\u00eda en manos de privados. Adem\u00e1s, se plantea que el Centro Nacional de Control de Energ\u00eda (CENACE) priorice la energ\u00eda generada por la CFE sobre la de empresas privadas, incluso si estas \u00faltimas utilizan fuentes m\u00e1s limpias.<\/p>\n<p style=\"text-align: justify;\">A pesar de las cr\u00edticas de la oposici\u00f3n y la incertidumbre generada entre inversionistas, Sheinbaum asegura que las empresas del Estado ser\u00e1n m\u00e1s productivas y eficientes. Tambi\u00e9n promete una planificaci\u00f3n energ\u00e9tica clara y reglas definidas para la participaci\u00f3n del sector privado.<\/p>\n<p style=\"text-align: justify;\">Finalmente, la presidenta reafirm\u00f3 su compromiso de rescatar a Pemex, que enfrenta una deuda significativa y p\u00e9rdidas financieras, al igual que la CFE, que tambi\u00e9n ha reportado p\u00e9rdidas en el primer semestre de 2024.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- La presidenta de M\u00e9xico, Claudia Sheinbaum, est\u00e1 impulsando una reforma energ\u00e9tica que busca reclasificar a Petr\u00f3leos Mexicanos (PEMEX) y la Comisi\u00f3n Federal de Electricidad (CFE) como \u00abempresas p\u00fablicas\u00bb. La discusi\u00f3n de esta reforma se llevar\u00e1 a cabo en la C\u00e1mara de Diputados el 9 de octubre. Sheinbaum sostiene que es necesario revertir la reforma energ\u00e9tica implementada por Enrique Pe\u00f1a Nieto, que permiti\u00f3 la inversi\u00f3n privada en el sector y defini\u00f3 a Pemex y CFE como \u00abempresas productivas del Estado\u00bb. La presidenta argumenta que su nueva reforma tiene como objetivo enfocar a estas compa\u00f1\u00edas en el servicio p\u00fablico en lugar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":144498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-144484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- La presidenta de M\u00e9xico, Claudia Sheinbaum, est\u00e1 impulsando una reforma energ\u00e9tica que busca reclasificar a Petr\u00f3leos Mexicanos (PEMEX) y la Comisi\u00f3n Federal de Electricidad (CFE) como \u00abempresas p\u00fablicas\u00bb. La discusi\u00f3n de esta reforma se llevar\u00e1 a cabo en la C\u00e1mara de Diputados el 9 de octubre. Sheinbaum sostiene que es necesario revertir la reforma energ\u00e9tica implementada por Enrique Pe\u00f1a Nieto, que permiti\u00f3 la inversi\u00f3n privada en el sector y defini\u00f3 a Pemex y CFE como \u00abempresas productivas del Estado\u00bb. La presidenta argumenta que su nueva reforma tiene como objetivo enfocar a estas compa\u00f1\u00edas en el servicio p\u00fablico en lugar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-09T21:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-10T01:39:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/01-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"911\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica\",\"datePublished\":\"2024-10-09T21:00:59+00:00\",\"dateModified\":\"2024-10-10T01:39:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/\"},\"wordCount\":279,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/01-7.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/\",\"name\":\"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/01-7.jpg\",\"datePublished\":\"2024-10-09T21:00:59+00:00\",\"dateModified\":\"2024-10-10T01:39:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/01-7.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/01-7.jpg\",\"width\":911,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/","og_locale":"es_ES","og_type":"article","og_title":"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- La presidenta de M\u00e9xico, Claudia Sheinbaum, est\u00e1 impulsando una reforma energ\u00e9tica que busca reclasificar a Petr\u00f3leos Mexicanos (PEMEX) y la Comisi\u00f3n Federal de Electricidad (CFE) como \u00abempresas p\u00fablicas\u00bb. La discusi\u00f3n de esta reforma se llevar\u00e1 a cabo en la C\u00e1mara de Diputados el 9 de octubre. Sheinbaum sostiene que es necesario revertir la reforma energ\u00e9tica implementada por Enrique Pe\u00f1a Nieto, que permiti\u00f3 la inversi\u00f3n privada en el sector y defini\u00f3 a Pemex y CFE como \u00abempresas productivas del Estado\u00bb. La presidenta argumenta que su nueva reforma tiene como objetivo enfocar a estas compa\u00f1\u00edas en el servicio p\u00fablico en lugar [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-10-09T21:00:59+00:00","article_modified_time":"2024-10-10T01:39:28+00:00","og_image":[{"width":911,"height":450,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/01-7.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica","datePublished":"2024-10-09T21:00:59+00:00","dateModified":"2024-10-10T01:39:28+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/"},"wordCount":279,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/01-7.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/","url":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/","name":"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/01-7.jpg","datePublished":"2024-10-09T21:00:59+00:00","dateModified":"2024-10-10T01:39:28+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/01-7.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/10\/01-7.jpg","width":911,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/no-buscamos-pelear-con-la-ip-claudia-sheinbaum-respecto-reforma-energetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"No buscamos pelear con la IP: Claudia Sheinbaum respecto reforma energ\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=144484"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144484\/revisions"}],"predecessor-version":[{"id":144561,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/144484\/revisions\/144561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/144498"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=144484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=144484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=144484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}