{"id":142412,"date":"2024-09-17T17:53:26","date_gmt":"2024-09-17T23:53:26","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=142412"},"modified":"2024-09-17T17:53:57","modified_gmt":"2024-09-17T23:53:57","slug":"impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/","title":{"rendered":"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- La Secretar\u00eda de Educaci\u00f3n ha decidido que los puestos de intendencia en instituciones de nivel preescolar, como kinders y guarder\u00edas, ser\u00e1n ocupados exclusivamente por mujeres.<\/p>\n<p style=\"text-align: justify;\">Esta medida busca prevenir incidentes de acoso sexual y brindar mayor tranquilidad a la comunidad educativa, seg\u00fan declar\u00f3 el titular de la dependencia, Juan Carlos Torres Cedillo.<\/p>\n<p style=\"text-align: justify;\">\u00abNormalmente, el sindicato presenta propuestas cuando hay espacios de intendencia o administrativos en kinders y guarder\u00edas, pero hemos tenido problemas en estas instituciones de violaciones, tocamientos y situaciones de acoso sexual\u00bb, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">La decisi\u00f3n de restringir estos puestos a mujeres, de acuerdo con el funcionario, obedece a la necesidad de aumentar y garantizar la seguridad de los peque\u00f1os que exigen los padres de familia.<\/p>\n<p style=\"text-align: justify;\">\u00abNosotros decidimos que estas propuestas deben ser para mujeres, de alguna manera nos da un poco m\u00e1s de seguridad a nosotros y a los padres de familia, y as\u00ed es como lo estamos procurando\u00bb, a\u00f1adi\u00f3.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, esta medida ha generado la oposici\u00f3n del sindicato, que ha solicitado igualdad de oportunidades para los hombres.<\/p>\n<p style=\"text-align: justify;\">\u00abEl sindicato, bueno, nos ha exigido que tambi\u00e9n le demos la oportunidad a los hombres, que no los discriminemos, pero nosotros ya estamos pidiendo a la Secretar\u00eda de Gobierno que a trav\u00e9s de nuestra normativa se defina y que as\u00ed sea de aqu\u00ed en adelante para poder evitar ese tipo de problemas\u00bb, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Torres Cedillo aclar\u00f3 que los hombres pueden fungir como docentes, dado que en ese rol tienen m\u00e1s interacci\u00f3n con los padres de familia; adem\u00e1s, reconoci\u00f3 que se han tenido dos casos de acoso en este nivel educativo.<\/p>\n<p style=\"text-align: justify;\">\u00abDocentes s\u00ed se permiten, tienen m\u00e1s contacto con los padres de familia, en el caso de los intendentes son los que desgraciadamente nos dice que son los que han cometido alg\u00fan error en este sentido entonces procuraremos que seas mujeres&#8230; En nuestra gesti\u00f3n van dos, fuertes\u00bb, termin\u00f3.<\/p>\n<p>Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- La Secretar\u00eda de Educaci\u00f3n ha decidido que los puestos de intendencia en instituciones de nivel preescolar, como kinders y guarder\u00edas, ser\u00e1n ocupados exclusivamente por mujeres. Esta medida busca prevenir incidentes de acoso sexual y brindar mayor tranquilidad a la comunidad educativa, seg\u00fan declar\u00f3 el titular de la dependencia, Juan Carlos Torres Cedillo. \u00abNormalmente, el sindicato presenta propuestas cuando hay espacios de intendencia o administrativos en kinders y guarder\u00edas, pero hemos tenido problemas en estas instituciones de violaciones, tocamientos y situaciones de acoso sexual\u00bb, explic\u00f3. La decisi\u00f3n de restringir estos puestos a mujeres, de acuerdo con el funcionario, obedece a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":142468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,510,45],"tags":[],"class_list":["post-142412","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-gobedoslp","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- La Secretar\u00eda de Educaci\u00f3n ha decidido que los puestos de intendencia en instituciones de nivel preescolar, como kinders y guarder\u00edas, ser\u00e1n ocupados exclusivamente por mujeres. Esta medida busca prevenir incidentes de acoso sexual y brindar mayor tranquilidad a la comunidad educativa, seg\u00fan declar\u00f3 el titular de la dependencia, Juan Carlos Torres Cedillo. \u00abNormalmente, el sindicato presenta propuestas cuando hay espacios de intendencia o administrativos en kinders y guarder\u00edas, pero hemos tenido problemas en estas instituciones de violaciones, tocamientos y situaciones de acoso sexual\u00bb, explic\u00f3. La decisi\u00f3n de restringir estos puestos a mujeres, de acuerdo con el funcionario, obedece a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T23:53:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T23:53:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Vazquez0KindersHombres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os\",\"datePublished\":\"2024-09-17T23:53:26+00:00\",\"dateModified\":\"2024-09-17T23:53:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/\"},\"wordCount\":354,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vazquez0KindersHombres.jpg\",\"articleSection\":[\"DESTACADAS\",\"GOBEDOSLP\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/\",\"name\":\"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vazquez0KindersHombres.jpg\",\"datePublished\":\"2024-09-17T23:53:26+00:00\",\"dateModified\":\"2024-09-17T23:53:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vazquez0KindersHombres.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vazquez0KindersHombres.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os - Canal 7 SLP - 2024","og_description":"SLP.- La Secretar\u00eda de Educaci\u00f3n ha decidido que los puestos de intendencia en instituciones de nivel preescolar, como kinders y guarder\u00edas, ser\u00e1n ocupados exclusivamente por mujeres. Esta medida busca prevenir incidentes de acoso sexual y brindar mayor tranquilidad a la comunidad educativa, seg\u00fan declar\u00f3 el titular de la dependencia, Juan Carlos Torres Cedillo. \u00abNormalmente, el sindicato presenta propuestas cuando hay espacios de intendencia o administrativos en kinders y guarder\u00edas, pero hemos tenido problemas en estas instituciones de violaciones, tocamientos y situaciones de acoso sexual\u00bb, explic\u00f3. La decisi\u00f3n de restringir estos puestos a mujeres, de acuerdo con el funcionario, obedece a [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-09-17T23:53:26+00:00","article_modified_time":"2024-09-17T23:53:57+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Vazquez0KindersHombres.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os","datePublished":"2024-09-17T23:53:26+00:00","dateModified":"2024-09-17T23:53:57+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/"},"wordCount":354,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Vazquez0KindersHombres.jpg","articleSection":["DESTACADAS","GOBEDOSLP","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/","url":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/","name":"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Vazquez0KindersHombres.jpg","datePublished":"2024-09-17T23:53:26+00:00","dateModified":"2024-09-17T23:53:57+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Vazquez0KindersHombres.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Vazquez0KindersHombres.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/impedir-a-hombres-ocupar-plazas-de-intendencia-alternativa-de-autoridades-educativas-para-contrarrestar-abuso-sexual-en-jardines-de-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Impedir a hombres ocupar plazas de intendencia, alternativa de autoridades educativas para contrarrestar abuso sexual en jardines de ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/142412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=142412"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/142412\/revisions"}],"predecessor-version":[{"id":142589,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/142412\/revisions\/142589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/142468"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=142412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=142412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=142412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}