{"id":141186,"date":"2024-09-04T12:58:25","date_gmt":"2024-09-04T18:58:25","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=141186"},"modified":"2024-09-04T12:58:25","modified_gmt":"2024-09-04T18:58:25","slug":"el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/","title":{"rendered":"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- El joven potosino C\u00e9sar Morales Monreal, quedo debidamente registrado para tomar parte dentro de los III FISU Am\u00e9rica Games 2024, a celebrarse del 5 al 14 de noviembre en Cali, Colombia.<\/p>\n<p style=\"text-align: justify;\">Morales ya se encuentra preparando para tomar parte en este importante evento Panamericano, en donde tomar\u00e1 parte dentro de la prueba de los 3 mil metros con obst\u00e1culos.<\/p>\n<p style=\"text-align: justify;\">C\u00e9sar Daniel, fue notificado por parte del CONDDE que luego del proceso selectivo a cargo del CONDDE y con base en el reglamento y lineamientos para conformar las selecciones nacionales que representar\u00e1n a M\u00e9xico en estos III FISU Am\u00e9rica Games 2024 fue elegido para formar parte de esta selecci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- El joven potosino C\u00e9sar Morales Monreal, quedo debidamente registrado para tomar parte dentro de los III FISU Am\u00e9rica Games 2024, a celebrarse del 5 al 14 de noviembre en Cali, Colombia. Morales ya se encuentra preparando para tomar parte en este importante evento Panamericano, en donde tomar\u00e1 parte dentro de la prueba de los 3 mil metros con obst\u00e1culos. C\u00e9sar Daniel, fue notificado por parte del CONDDE que luego del proceso selectivo a cargo del CONDDE y con base en el reglamento y lineamientos para conformar las selecciones nacionales que representar\u00e1n a M\u00e9xico en estos III FISU Am\u00e9rica Games [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":141192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-141186","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024 - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024 - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- El joven potosino C\u00e9sar Morales Monreal, quedo debidamente registrado para tomar parte dentro de los III FISU Am\u00e9rica Games 2024, a celebrarse del 5 al 14 de noviembre en Cali, Colombia. Morales ya se encuentra preparando para tomar parte en este importante evento Panamericano, en donde tomar\u00e1 parte dentro de la prueba de los 3 mil metros con obst\u00e1culos. C\u00e9sar Daniel, fue notificado por parte del CONDDE que luego del proceso selectivo a cargo del CONDDE y con base en el reglamento y lineamientos para conformar las selecciones nacionales que representar\u00e1n a M\u00e9xico en estos III FISU Am\u00e9rica Games [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-04T18:58:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Froi01Atletismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024\",\"datePublished\":\"2024-09-04T18:58:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/\"},\"wordCount\":127,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Froi01Atletismo.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/\",\"name\":\"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024 - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Froi01Atletismo.jpg\",\"datePublished\":\"2024-09-04T18:58:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Froi01Atletismo.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Froi01Atletismo.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024 - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/","og_locale":"es_ES","og_type":"article","og_title":"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024 - Canal 7 SLP - 2024","og_description":"SLP.- El joven potosino C\u00e9sar Morales Monreal, quedo debidamente registrado para tomar parte dentro de los III FISU Am\u00e9rica Games 2024, a celebrarse del 5 al 14 de noviembre en Cali, Colombia. Morales ya se encuentra preparando para tomar parte en este importante evento Panamericano, en donde tomar\u00e1 parte dentro de la prueba de los 3 mil metros con obst\u00e1culos. C\u00e9sar Daniel, fue notificado por parte del CONDDE que luego del proceso selectivo a cargo del CONDDE y con base en el reglamento y lineamientos para conformar las selecciones nacionales que representar\u00e1n a M\u00e9xico en estos III FISU Am\u00e9rica Games [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-09-04T18:58:25+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Froi01Atletismo.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024","datePublished":"2024-09-04T18:58:25+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/"},"wordCount":127,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Froi01Atletismo.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/","url":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/","name":"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024 - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Froi01Atletismo.jpg","datePublished":"2024-09-04T18:58:25+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Froi01Atletismo.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/09\/Froi01Atletismo.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/el-potosino-cesar-morales-monreal-participara-en-los-iii-fisu-america-games-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"El potosino C\u00e9sar Morales Monreal participar\u00e1 en los III Fisu Am\u00e9rica Games 2024"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/141186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=141186"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/141186\/revisions"}],"predecessor-version":[{"id":141195,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/141186\/revisions\/141195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/141192"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=141186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=141186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=141186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}