{"id":138414,"date":"2024-08-05T10:36:56","date_gmt":"2024-08-05T16:36:56","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=138414"},"modified":"2024-08-05T10:36:56","modified_gmt":"2024-08-05T16:36:56","slug":"aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/","title":{"rendered":"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0Fuerte accidente entre cami\u00f3n de volteo y un autom\u00f3vil Atos se registr\u00f3 este fin de semana.<\/p>\n<p style=\"text-align: justify;\">El veh\u00edculo qued\u00f3 aplastado contra el talud -sobre Circuito Potos\u00ed, en el tramo del Laberinto de las Ciencias y las Artes y la avenida Coronel Romero-.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con reportes oficiales iniciales, en el coche se encontraba un hombre de 28 a\u00f1os, que perdi\u00f3 la vida.<\/p>\n<p style=\"text-align: justify;\">Autoridades y el H. Cuerpo de Bomberos efectuaron labores de primer respondiente.<\/p>\n<p style=\"text-align: justify;\">Acudi\u00f3 personal de Guardia Civil Estatal, Polic\u00eda de Investigaci\u00f3n y Servicios Periciales -entre otros-.<\/p>\n<p>Por: Paulina Rodr\u00edguez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0Fuerte accidente entre cami\u00f3n de volteo y un autom\u00f3vil Atos se registr\u00f3 este fin de semana. El veh\u00edculo qued\u00f3 aplastado contra el talud -sobre Circuito Potos\u00ed, en el tramo del Laberinto de las Ciencias y las Artes y la avenida Coronel Romero-. De acuerdo con reportes oficiales iniciales, en el coche se encontraba un hombre de 28 a\u00f1os, que perdi\u00f3 la vida. Autoridades y el H. Cuerpo de Bomberos efectuaron labores de primer respondiente. Acudi\u00f3 personal de Guardia Civil Estatal, Polic\u00eda de Investigaci\u00f3n y Servicios Periciales -entre otros-. Por: Paulina Rodr\u00edguez<\/p>\n","protected":false},"author":2,"featured_media":138416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-138414","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0Fuerte accidente entre cami\u00f3n de volteo y un autom\u00f3vil Atos se registr\u00f3 este fin de semana. El veh\u00edculo qued\u00f3 aplastado contra el talud -sobre Circuito Potos\u00ed, en el tramo del Laberinto de las Ciencias y las Artes y la avenida Coronel Romero-. De acuerdo con reportes oficiales iniciales, en el coche se encontraba un hombre de 28 a\u00f1os, que perdi\u00f3 la vida. Autoridades y el H. Cuerpo de Bomberos efectuaron labores de primer respondiente. Acudi\u00f3 personal de Guardia Civil Estatal, Polic\u00eda de Investigaci\u00f3n y Servicios Periciales -entre otros-. Por: Paulina Rodr\u00edguez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-05T16:36:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/08\/Pau01Prensado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida\",\"datePublished\":\"2024-08-05T16:36:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/\"},\"wordCount\":115,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pau01Prensado.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/\",\"name\":\"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pau01Prensado.jpg\",\"datePublished\":\"2024-08-05T16:36:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pau01Prensado.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pau01Prensado.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/","og_locale":"es_ES","og_type":"article","og_title":"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida - Canal 7 SLP - 2024","og_description":"SLP.-\u00a0Fuerte accidente entre cami\u00f3n de volteo y un autom\u00f3vil Atos se registr\u00f3 este fin de semana. El veh\u00edculo qued\u00f3 aplastado contra el talud -sobre Circuito Potos\u00ed, en el tramo del Laberinto de las Ciencias y las Artes y la avenida Coronel Romero-. De acuerdo con reportes oficiales iniciales, en el coche se encontraba un hombre de 28 a\u00f1os, que perdi\u00f3 la vida. Autoridades y el H. Cuerpo de Bomberos efectuaron labores de primer respondiente. Acudi\u00f3 personal de Guardia Civil Estatal, Polic\u00eda de Investigaci\u00f3n y Servicios Periciales -entre otros-. Por: Paulina Rodr\u00edguez","og_url":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-08-05T16:36:56+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/08\/Pau01Prensado.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida","datePublished":"2024-08-05T16:36:56+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/"},"wordCount":115,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/08\/Pau01Prensado.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/","url":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/","name":"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/08\/Pau01Prensado.jpg","datePublished":"2024-08-05T16:36:56+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/08\/Pau01Prensado.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/08\/Pau01Prensado.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/aparatoso-accidente-entre-camion-de-volteo-y-automovil-deja-a-una-persona-sin-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Aparatoso accidente entre cami\u00f3n de volteo y autom\u00f3vil deja a una persona sin vida"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/138414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=138414"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/138414\/revisions"}],"predecessor-version":[{"id":138417,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/138414\/revisions\/138417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/138416"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=138414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=138414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=138414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}