{"id":137275,"date":"2024-07-23T10:02:19","date_gmt":"2024-07-23T16:02:19","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=137275"},"modified":"2024-07-23T10:03:11","modified_gmt":"2024-07-23T16:03:11","slug":"concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/","title":{"rendered":"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Con 21 votos a favor y una abstenci\u00f3n, este lunes se declar\u00f3 a Villa de Pozos el municipio 59 de San Luis Potos\u00ed, con la aprobaci\u00f3n de un decreto.<\/p>\n<p style=\"text-align: justify;\">Una vez que el tribunal colegiado desech\u00f3 la \u00faltima impugnaci\u00f3n que promovieron particulares, el Poder Legislativo vot\u00f3 el dictamen.<\/p>\n<p style=\"text-align: justify;\">Fue explicado que se introdujo una modificaci\u00f3n a art\u00edculos transitorios, contemplados en el proyecto -y otros cu\u00e1ntos se adicionaron-.<\/p>\n<p style=\"text-align: justify;\">Con ello, un Concejo Municipal entrar\u00e1 en funciones el primero de octubre y su permanencia podr\u00eda ser hasta el 30 de septiembre de 2027.<\/p>\n<p style=\"text-align: justify;\">Ser\u00eda ese a\u00f1o cuando deba contemplarse la convocatoria a elecciones constitucionales.<\/p>\n<p style=\"text-align: justify;\">En el marco de la decisi\u00f3n, en Plaza de Armas se congregaron habitantes de Villa de Pozos, como Leticia Lara Hern\u00e1ndez -espec\u00edficamente de Misi\u00f3n del Palmar- consider\u00f3 que habr\u00e1 un cambio en la ejecuci\u00f3n de obras de infraestructura -tanto de pavimentaci\u00f3n como drenaje-, instalaci\u00f3n de alumbrado y fortalecimiento a estrategias de seguridad.<\/p>\n<p style=\"text-align: justify;\">De manera previa, descart\u00f3 que se hubiese inyectado recurso en los temas prioritarios.<\/p>\n<p style=\"text-align: justify;\">La ciudadana asever\u00f3 que existe mayor certeza y se esperar\u00e1 el desahogo de las etapas que corresponden a la consolidaci\u00f3n del municipio.<\/p>\n<p style=\"text-align: justify;\">Por: Paulina Rodr\u00edguez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Con 21 votos a favor y una abstenci\u00f3n, este lunes se declar\u00f3 a Villa de Pozos el municipio 59 de San Luis Potos\u00ed, con la aprobaci\u00f3n de un decreto. Una vez que el tribunal colegiado desech\u00f3 la \u00faltima impugnaci\u00f3n que promovieron particulares, el Poder Legislativo vot\u00f3 el dictamen. Fue explicado que se introdujo una modificaci\u00f3n a art\u00edculos transitorios, contemplados en el proyecto -y otros cu\u00e1ntos se adicionaron-. Con ello, un Concejo Municipal entrar\u00e1 en funciones el primero de octubre y su permanencia podr\u00eda ser hasta el 30 de septiembre de 2027. Ser\u00eda ese a\u00f1o cuando deba contemplarse la convocatoria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":137300,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3,5,45],"tags":[],"class_list":["post-137275","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-congreso","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59 - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59 - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Con 21 votos a favor y una abstenci\u00f3n, este lunes se declar\u00f3 a Villa de Pozos el municipio 59 de San Luis Potos\u00ed, con la aprobaci\u00f3n de un decreto. Una vez que el tribunal colegiado desech\u00f3 la \u00faltima impugnaci\u00f3n que promovieron particulares, el Poder Legislativo vot\u00f3 el dictamen. Fue explicado que se introdujo una modificaci\u00f3n a art\u00edculos transitorios, contemplados en el proyecto -y otros cu\u00e1ntos se adicionaron-. Con ello, un Concejo Municipal entrar\u00e1 en funciones el primero de octubre y su permanencia podr\u00eda ser hasta el 30 de septiembre de 2027. Ser\u00eda ese a\u00f1o cuando deba contemplarse la convocatoria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T16:02:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T16:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/07\/Pau01Pozos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59\",\"datePublished\":\"2024-07-23T16:02:19+00:00\",\"dateModified\":\"2024-07-23T16:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Pau01Pozos.jpg\",\"articleSection\":[\"CONGRESO\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/\",\"name\":\"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59 - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Pau01Pozos.jpg\",\"datePublished\":\"2024-07-23T16:02:19+00:00\",\"dateModified\":\"2024-07-23T16:03:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Pau01Pozos.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Pau01Pozos.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59 - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/","og_locale":"es_ES","og_type":"article","og_title":"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59 - Canal 7 SLP - 2024","og_description":"SLP.- Con 21 votos a favor y una abstenci\u00f3n, este lunes se declar\u00f3 a Villa de Pozos el municipio 59 de San Luis Potos\u00ed, con la aprobaci\u00f3n de un decreto. Una vez que el tribunal colegiado desech\u00f3 la \u00faltima impugnaci\u00f3n que promovieron particulares, el Poder Legislativo vot\u00f3 el dictamen. Fue explicado que se introdujo una modificaci\u00f3n a art\u00edculos transitorios, contemplados en el proyecto -y otros cu\u00e1ntos se adicionaron-. Con ello, un Concejo Municipal entrar\u00e1 en funciones el primero de octubre y su permanencia podr\u00eda ser hasta el 30 de septiembre de 2027. Ser\u00eda ese a\u00f1o cuando deba contemplarse la convocatoria [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-07-23T16:02:19+00:00","article_modified_time":"2024-07-23T16:03:11+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/07\/Pau01Pozos.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59","datePublished":"2024-07-23T16:02:19+00:00","dateModified":"2024-07-23T16:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/"},"wordCount":222,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/07\/Pau01Pozos.jpg","articleSection":["CONGRESO","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/","url":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/","name":"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59 - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/07\/Pau01Pozos.jpg","datePublished":"2024-07-23T16:02:19+00:00","dateModified":"2024-07-23T16:03:11+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/07\/Pau01Pozos.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/07\/Pau01Pozos.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/concejo-entrara-en-funciones-el-primero-de-octubre-con-villa-de-pozos-como-municipio-59\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Concejo entrar\u00e1 en funciones el primero de octubre con Villa de Pozos como municipio 59"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/137275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=137275"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/137275\/revisions"}],"predecessor-version":[{"id":137282,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/137275\/revisions\/137282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/137300"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=137275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=137275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=137275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}