{"id":131759,"date":"2024-05-27T14:03:35","date_gmt":"2024-05-27T20:03:35","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=131759"},"modified":"2024-05-27T14:03:35","modified_gmt":"2024-05-27T20:03:35","slug":"atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/","title":{"rendered":"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Despu\u00e9s de la p\u00e9sima temporada de Atl\u00e9tico de San Luis, el conjunto se comienza a reestructurar de cara al siguiente torneo, por lo que la directiva dio a conocer las bajas del equipo Femenil.<\/p>\n<p style=\"text-align: justify;\">Las jugadoras que causaron baja son Daniela Mendoza, Salma Ventura, Mayra Santana, Trudi Carter, Jaqueline Garc\u00eda, Justina Morcillo, Luz Duarte, Zellyka Arce, Marina Delgado, Vanessa Gonz\u00e1lez, Julissa D\u00e1vila y Mariela Garc\u00eda.<\/p>\n<p style=\"text-align: justify;\">Por lo que la instituci\u00f3n les agradeci\u00f3 por su entrega y dedicaci\u00f3n durante su estancia y les, deseo el mayor de los \u00e9xitos en sus futuros proyectos.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Despu\u00e9s de la p\u00e9sima temporada de Atl\u00e9tico de San Luis, el conjunto se comienza a reestructurar de cara al siguiente torneo, por lo que la directiva dio a conocer las bajas del equipo Femenil. Las jugadoras que causaron baja son Daniela Mendoza, Salma Ventura, Mayra Santana, Trudi Carter, Jaqueline Garc\u00eda, Justina Morcillo, Luz Duarte, Zellyka Arce, Marina Delgado, Vanessa Gonz\u00e1lez, Julissa D\u00e1vila y Mariela Garc\u00eda. Por lo que la instituci\u00f3n les agradeci\u00f3 por su entrega y dedicaci\u00f3n durante su estancia y les, deseo el mayor de los \u00e9xitos en sus futuros proyectos.<\/p>\n","protected":false},"author":2,"featured_media":131767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-131759","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Despu\u00e9s de la p\u00e9sima temporada de Atl\u00e9tico de San Luis, el conjunto se comienza a reestructurar de cara al siguiente torneo, por lo que la directiva dio a conocer las bajas del equipo Femenil. Las jugadoras que causaron baja son Daniela Mendoza, Salma Ventura, Mayra Santana, Trudi Carter, Jaqueline Garc\u00eda, Justina Morcillo, Luz Duarte, Zellyka Arce, Marina Delgado, Vanessa Gonz\u00e1lez, Julissa D\u00e1vila y Mariela Garc\u00eda. Por lo que la instituci\u00f3n les agradeci\u00f3 por su entrega y dedicaci\u00f3n durante su estancia y les, deseo el mayor de los \u00e9xitos en sus futuros proyectos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-27T20:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Froi03AtletiFem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo\",\"datePublished\":\"2024-05-27T20:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/\"},\"wordCount\":118,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Froi03AtletiFem.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/\",\"name\":\"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Froi03AtletiFem.jpg\",\"datePublished\":\"2024-05-27T20:03:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Froi03AtletiFem.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Froi03AtletiFem.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/","og_locale":"es_ES","og_type":"article","og_title":"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo - Canal 7 SLP - 2024","og_description":"SLP.- Despu\u00e9s de la p\u00e9sima temporada de Atl\u00e9tico de San Luis, el conjunto se comienza a reestructurar de cara al siguiente torneo, por lo que la directiva dio a conocer las bajas del equipo Femenil. Las jugadoras que causaron baja son Daniela Mendoza, Salma Ventura, Mayra Santana, Trudi Carter, Jaqueline Garc\u00eda, Justina Morcillo, Luz Duarte, Zellyka Arce, Marina Delgado, Vanessa Gonz\u00e1lez, Julissa D\u00e1vila y Mariela Garc\u00eda. Por lo que la instituci\u00f3n les agradeci\u00f3 por su entrega y dedicaci\u00f3n durante su estancia y les, deseo el mayor de los \u00e9xitos en sus futuros proyectos.","og_url":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-05-27T20:03:35+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Froi03AtletiFem.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo","datePublished":"2024-05-27T20:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/"},"wordCount":118,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Froi03AtletiFem.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/","url":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/","name":"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Froi03AtletiFem.jpg","datePublished":"2024-05-27T20:03:35+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Froi03AtletiFem.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Froi03AtletiFem.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-anuncio-las-bajas-de-cara-al-arranque-del-torneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Atl\u00e9tico de San Luis Femenil anunci\u00f3 las bajas de cara al arranque del torneo"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/131759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=131759"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/131759\/revisions"}],"predecessor-version":[{"id":131768,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/131759\/revisions\/131768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/131767"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=131759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=131759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=131759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}