{"id":129340,"date":"2024-05-03T15:35:54","date_gmt":"2024-05-03T21:35:54","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=129340"},"modified":"2024-05-05T15:36:42","modified_gmt":"2024-05-05T21:36:42","slug":"senadores-analizan-ley-de-empleo-temporal-para-desplazados","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/","title":{"rendered":"Senadores analizan Ley de Empleo Temporal para desplazados"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- Senadores del Partido Revolucionario Institucional (PRI) han presentado una iniciativa de ley para crear un instrumento que atienda a las personas en situaci\u00f3n de desocupaci\u00f3n, ya sea forzada o voluntaria, con el objetivo de mejorar su situaci\u00f3n econ\u00f3mica a trav\u00e9s de ingresos y esquemas de seguridad social.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con cifras del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), en noviembre de 2023, la poblaci\u00f3n desocupada a nivel nacional fue de 1.6 millones de personas, de las cuales 948 mil son hombres y 674 mil son mujeres.<\/p>\n<p style=\"text-align: justify;\">La propuesta legislativa, denominada Ley de Empleo Temporal, est\u00e1 dirigida a la poblaci\u00f3n que no cuenta con un empleo formal, priorizando a aquellas personas que residen en zonas marginadas o con altas tasas de desempleo.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, busca regular el Programa de Empleo Temporal como una medida ante los impactos econ\u00f3micos y sociales causados por diversas crisis, emergencias o desastres naturales.<\/p>\n<p style=\"text-align: justify;\">Los legisladores explicaron que el objetivo es proporcionar a la poblaci\u00f3n desempleada y en situaci\u00f3n de pobreza o pobreza extrema, una fuente de ingresos y esquemas de seguridad social que protejan su bienestar socioecon\u00f3mico.<\/p>\n<p style=\"text-align: justify;\">El programa de empleo temporal estar\u00e1 dirigido a personas mayores de 18 a\u00f1os que no cuenten con una relaci\u00f3n laboral formal, dando prioridad a quienes habiten en zonas marginadas o afectadas por desastres naturales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- Senadores del Partido Revolucionario Institucional (PRI) han presentado una iniciativa de ley para crear un instrumento que atienda a las personas en situaci\u00f3n de desocupaci\u00f3n, ya sea forzada o voluntaria, con el objetivo de mejorar su situaci\u00f3n econ\u00f3mica a trav\u00e9s de ingresos y esquemas de seguridad social. De acuerdo con cifras del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), en noviembre de 2023, la poblaci\u00f3n desocupada a nivel nacional fue de 1.6 millones de personas, de las cuales 948 mil son hombres y 674 mil son mujeres. La propuesta legislativa, denominada Ley de Empleo Temporal, est\u00e1 dirigida a la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":129357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-129340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senadores analizan Ley de Empleo Temporal para desplazados - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senadores analizan Ley de Empleo Temporal para desplazados - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- Senadores del Partido Revolucionario Institucional (PRI) han presentado una iniciativa de ley para crear un instrumento que atienda a las personas en situaci\u00f3n de desocupaci\u00f3n, ya sea forzada o voluntaria, con el objetivo de mejorar su situaci\u00f3n econ\u00f3mica a trav\u00e9s de ingresos y esquemas de seguridad social. De acuerdo con cifras del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), en noviembre de 2023, la poblaci\u00f3n desocupada a nivel nacional fue de 1.6 millones de personas, de las cuales 948 mil son hombres y 674 mil son mujeres. La propuesta legislativa, denominada Ley de Empleo Temporal, est\u00e1 dirigida a la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T21:35:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-05T21:36:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/08-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Senadores analizan Ley de Empleo Temporal para desplazados\",\"datePublished\":\"2024-05-03T21:35:54+00:00\",\"dateModified\":\"2024-05-05T21:36:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/\"},\"wordCount\":237,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/08-scaled.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/\",\"name\":\"Senadores analizan Ley de Empleo Temporal para desplazados - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/08-scaled.jpg\",\"datePublished\":\"2024-05-03T21:35:54+00:00\",\"dateModified\":\"2024-05-05T21:36:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/08-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/08-scaled.jpg\",\"width\":2560,\"height\":1168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senadores analizan Ley de Empleo Temporal para desplazados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senadores analizan Ley de Empleo Temporal para desplazados - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/","og_locale":"es_ES","og_type":"article","og_title":"Senadores analizan Ley de Empleo Temporal para desplazados - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- Senadores del Partido Revolucionario Institucional (PRI) han presentado una iniciativa de ley para crear un instrumento que atienda a las personas en situaci\u00f3n de desocupaci\u00f3n, ya sea forzada o voluntaria, con el objetivo de mejorar su situaci\u00f3n econ\u00f3mica a trav\u00e9s de ingresos y esquemas de seguridad social. De acuerdo con cifras del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), en noviembre de 2023, la poblaci\u00f3n desocupada a nivel nacional fue de 1.6 millones de personas, de las cuales 948 mil son hombres y 674 mil son mujeres. La propuesta legislativa, denominada Ley de Empleo Temporal, est\u00e1 dirigida a la [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-05-03T21:35:54+00:00","article_modified_time":"2024-05-05T21:36:42+00:00","og_image":[{"width":2560,"height":1168,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/08-scaled.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Senadores analizan Ley de Empleo Temporal para desplazados","datePublished":"2024-05-03T21:35:54+00:00","dateModified":"2024-05-05T21:36:42+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/"},"wordCount":237,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/08-scaled.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/","url":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/","name":"Senadores analizan Ley de Empleo Temporal para desplazados - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/08-scaled.jpg","datePublished":"2024-05-03T21:35:54+00:00","dateModified":"2024-05-05T21:36:42+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/08-scaled.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/08-scaled.jpg","width":2560,"height":1168},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/senadores-analizan-ley-de-empleo-temporal-para-desplazados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Senadores analizan Ley de Empleo Temporal para desplazados"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/129340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=129340"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/129340\/revisions"}],"predecessor-version":[{"id":129534,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/129340\/revisions\/129534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/129357"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=129340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=129340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=129340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}