{"id":129315,"date":"2024-05-04T11:21:01","date_gmt":"2024-05-04T17:21:01","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=129315"},"modified":"2024-05-04T11:21:56","modified_gmt":"2024-05-04T17:21:56","slug":"reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/","title":{"rendered":"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario"},"content":{"rendered":"<p style=\"text-align: justify;\">Villa de la Paz.-\u00a0A trav\u00e9s de las redes sociales, familiares de un adulto mayor de 80 a\u00f1os de edad, denunciaron que hab\u00eda sido golpeado por elementos de la polic\u00eda municipal de Villa de La Paz.<\/p>\n<p style=\"text-align: justify;\">De acuerdo a informaci\u00f3n extra oficial, la familia hab\u00eda acudido a dar una caminata por la serran\u00eda perteneciente al municipio, algo que es habitual entre los ciudadanos, cuando una patrulla perteneciente a la Direcci\u00f3n de Seguridad P\u00fablica Municipal, se acerc\u00f3 a la familia, en ese momento compuesta por el mencionado adulto mayor, un hijo y un nieto de apenas cuatro a\u00f1os de edad.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan informaci\u00f3n recabada por Noticieros Canal Siete, los elementos habr\u00edan intentado detener a los paseantes, ya que presuntamente se encontraban en propiedad privada, por lo que al sostener un fuerte di\u00e1logo con el hijo del adulto mayor, este fue golpeado por los polic\u00edas, mientras que el octagenario al intentar apoyar a su familiar, fue v\u00edctima de los golpes, a pesar de tener una amputaci\u00f3n en su pierna izquierda, todo esto ante la presencia del menor de edad.<\/p>\n<p style=\"text-align: justify;\">Trascendi\u00f3 que el hijo del adulto mayor, fue llevado detenido con presunto abuso de violencia f\u00edsica, mientras que el octagenario y el menor de edad, fueron abandonados por los elementos de seguridad en las inmediaciones de un lugar conocido como tiro al blanco, ubicado en las faldas del Cerro del Fraile.<\/p>\n<p style=\"text-align: justify;\">Tras el hecho violento, los familiares acudieron a solicitar el apoyo a la Presidencia Municipal de Villa de La Paz, quienes ya tienen conocimiento del hecho y se espera que tomen medidas en contra de los elementos en los pr\u00f3ximos d\u00edas.<\/p>\n<p>Por: Jes\u00fas Valencia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villa de la Paz.-\u00a0A trav\u00e9s de las redes sociales, familiares de un adulto mayor de 80 a\u00f1os de edad, denunciaron que hab\u00eda sido golpeado por elementos de la polic\u00eda municipal de Villa de La Paz. De acuerdo a informaci\u00f3n extra oficial, la familia hab\u00eda acudido a dar una caminata por la serran\u00eda perteneciente al municipio, algo que es habitual entre los ciudadanos, cuando una patrulla perteneciente a la Direcci\u00f3n de Seguridad P\u00fablica Municipal, se acerc\u00f3 a la familia, en ese momento compuesta por el mencionado adulto mayor, un hijo y un nieto de apenas cuatro a\u00f1os de edad. Seg\u00fan informaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":129319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,43],"tags":[],"class_list":["post-129315","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-interior","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"Villa de la Paz.-\u00a0A trav\u00e9s de las redes sociales, familiares de un adulto mayor de 80 a\u00f1os de edad, denunciaron que hab\u00eda sido golpeado por elementos de la polic\u00eda municipal de Villa de La Paz. De acuerdo a informaci\u00f3n extra oficial, la familia hab\u00eda acudido a dar una caminata por la serran\u00eda perteneciente al municipio, algo que es habitual entre los ciudadanos, cuando una patrulla perteneciente a la Direcci\u00f3n de Seguridad P\u00fablica Municipal, se acerc\u00f3 a la familia, en ese momento compuesta por el mencionado adulto mayor, un hijo y un nieto de apenas cuatro a\u00f1os de edad. Seg\u00fan informaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-04T17:21:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-04T17:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Valencia0Octogeneario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario\",\"datePublished\":\"2024-05-04T17:21:01+00:00\",\"dateModified\":\"2024-05-04T17:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Valencia0Octogeneario.jpg\",\"articleSection\":[\"DESTACADAS\",\"INTERIOR DEL ESTADO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/\",\"name\":\"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Valencia0Octogeneario.jpg\",\"datePublished\":\"2024-05-04T17:21:01+00:00\",\"dateModified\":\"2024-05-04T17:21:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Valencia0Octogeneario.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Valencia0Octogeneario.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/","og_locale":"es_ES","og_type":"article","og_title":"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario - Canal 7 SLP - 2024","og_description":"Villa de la Paz.-\u00a0A trav\u00e9s de las redes sociales, familiares de un adulto mayor de 80 a\u00f1os de edad, denunciaron que hab\u00eda sido golpeado por elementos de la polic\u00eda municipal de Villa de La Paz. De acuerdo a informaci\u00f3n extra oficial, la familia hab\u00eda acudido a dar una caminata por la serran\u00eda perteneciente al municipio, algo que es habitual entre los ciudadanos, cuando una patrulla perteneciente a la Direcci\u00f3n de Seguridad P\u00fablica Municipal, se acerc\u00f3 a la familia, en ese momento compuesta por el mencionado adulto mayor, un hijo y un nieto de apenas cuatro a\u00f1os de edad. Seg\u00fan informaci\u00f3n [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-05-04T17:21:01+00:00","article_modified_time":"2024-05-04T17:21:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Valencia0Octogeneario.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario","datePublished":"2024-05-04T17:21:01+00:00","dateModified":"2024-05-04T17:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/"},"wordCount":305,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Valencia0Octogeneario.jpg","articleSection":["DESTACADAS","INTERIOR DEL ESTADO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/","url":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/","name":"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Valencia0Octogeneario.jpg","datePublished":"2024-05-04T17:21:01+00:00","dateModified":"2024-05-04T17:21:56+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Valencia0Octogeneario.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/05\/Valencia0Octogeneario.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/reportan-aparentes-agresiones-y-presuntos-actos-de-arbitrariedad-de-policias-contra-octagenario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Reportan aparentes agresiones y presuntos actos de arbitrariedad de polic\u00edas contra octagenario"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/129315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=129315"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/129315\/revisions"}],"predecessor-version":[{"id":129389,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/129315\/revisions\/129389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/129319"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=129315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=129315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=129315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}