{"id":128509,"date":"2024-04-26T12:44:38","date_gmt":"2024-04-26T18:44:38","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=128509"},"modified":"2024-04-26T12:44:38","modified_gmt":"2024-04-26T18:44:38","slug":"reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/","title":{"rendered":"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0 Se mantiene la postura por parte del Poder Ejecutivo del Estado de San Luis Potos\u00ed de no retomar ning\u00fan plan que signifique dotar de recurso de agua a otras zonas del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Esto luego de que el gobernador, Ricardo Gallardo Cardona, externar\u00e1 nuevamente una negativa en cuanto al proyecto de Monterrey VI, ante la candidata de Morena a la presidencia de la rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">\u00abQued\u00f3 claro que no, no vamos a retomar ning\u00fan tema de proyecto para llevar agua a Monterrey, lo dej\u00e9 claro, ella misma me dijo que estaba perfecto, es m\u00e1s, va a defender la postura de San Luis Potos\u00ed, se suma a la postura\u00bb, dijo.<\/p>\n<p style=\"text-align: justify;\">Explic\u00f3 que para que se concrete un proyecto como el mencionado, se requiere que todas las partes involucradas coincidan, y en este caso no es as\u00ed.<\/p>\n<p style=\"text-align: justify;\">\u00abCada quien tiene que arreglar su tema del agua, yo creo que para poder llevarlo a cargo ambas entidades federativas tienen que estar de acuerdo\u00bb, extern\u00f3.<\/p>\n<p style=\"text-align: justify;\">Una situaci\u00f3n similar se presenta entre los estados de Tamaulipas y Veracruz.<\/p>\n<p style=\"text-align: justify;\">\u00abLo coment\u00f3 igual en Tamaulipas, a Tamaulipas llevar agua del P\u00e1nuco en Veracruz,&#8230; fue muy expl\u00edcita al decir que tiene que haber un consenso por los dos mandatarios, lo mismo ella piensa en San Luis Potos\u00ed\u00bb, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0 Se mantiene la postura por parte del Poder Ejecutivo del Estado de San Luis Potos\u00ed de no retomar ning\u00fan plan que signifique dotar de recurso de agua a otras zonas del pa\u00eds. Esto luego de que el gobernador, Ricardo Gallardo Cardona, externar\u00e1 nuevamente una negativa en cuanto al proyecto de Monterrey VI, ante la candidata de Morena a la presidencia de la rep\u00fablica. \u00abQued\u00f3 claro que no, no vamos a retomar ning\u00fan tema de proyecto para llevar agua a Monterrey, lo dej\u00e9 claro, ella misma me dijo que estaba perfecto, es m\u00e1s, va a defender la postura de San [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":128531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,510,45],"tags":[],"class_list":["post-128509","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-gobedoslp","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0 Se mantiene la postura por parte del Poder Ejecutivo del Estado de San Luis Potos\u00ed de no retomar ning\u00fan plan que signifique dotar de recurso de agua a otras zonas del pa\u00eds. Esto luego de que el gobernador, Ricardo Gallardo Cardona, externar\u00e1 nuevamente una negativa en cuanto al proyecto de Monterrey VI, ante la candidata de Morena a la presidencia de la rep\u00fablica. \u00abQued\u00f3 claro que no, no vamos a retomar ning\u00fan tema de proyecto para llevar agua a Monterrey, lo dej\u00e9 claro, ella misma me dijo que estaba perfecto, es m\u00e1s, va a defender la postura de San [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T18:44:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AguaMonterrey.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI\",\"datePublished\":\"2024-04-26T18:44:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AguaMonterrey.jpg\",\"articleSection\":[\"DESTACADAS\",\"GOBEDOSLP\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/\",\"name\":\"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AguaMonterrey.jpg\",\"datePublished\":\"2024-04-26T18:44:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AguaMonterrey.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AguaMonterrey.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/","og_locale":"es_ES","og_type":"article","og_title":"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI - Canal 7 SLP - 2024","og_description":"SLP.-\u00a0 Se mantiene la postura por parte del Poder Ejecutivo del Estado de San Luis Potos\u00ed de no retomar ning\u00fan plan que signifique dotar de recurso de agua a otras zonas del pa\u00eds. Esto luego de que el gobernador, Ricardo Gallardo Cardona, externar\u00e1 nuevamente una negativa en cuanto al proyecto de Monterrey VI, ante la candidata de Morena a la presidencia de la rep\u00fablica. \u00abQued\u00f3 claro que no, no vamos a retomar ning\u00fan tema de proyecto para llevar agua a Monterrey, lo dej\u00e9 claro, ella misma me dijo que estaba perfecto, es m\u00e1s, va a defender la postura de San [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-26T18:44:38+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AguaMonterrey.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI","datePublished":"2024-04-26T18:44:38+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/"},"wordCount":235,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AguaMonterrey.jpg","articleSection":["DESTACADAS","GOBEDOSLP","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/","url":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/","name":"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AguaMonterrey.jpg","datePublished":"2024-04-26T18:44:38+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AguaMonterrey.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AguaMonterrey.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/reiteran-autoridades-estatales-negativa-a-aplicacion-de-proyecto-monterrey-vi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Reiteran autoridades estatales negativa a aplicaci\u00f3n de proyecto Monterrey VI"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/128509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=128509"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/128509\/revisions"}],"predecessor-version":[{"id":128580,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/128509\/revisions\/128580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/128531"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=128509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=128509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=128509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}