{"id":128114,"date":"2024-04-22T18:40:30","date_gmt":"2024-04-23T00:40:30","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=128114"},"modified":"2024-04-22T18:40:49","modified_gmt":"2024-04-23T00:40:49","slug":"deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/","title":{"rendered":"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0La Alianza Empresarial de San Luis Potos\u00ed inici\u00f3 con el Foro de Impuestos Ambientales: Reglamentaci\u00f3n en San Luis Potos\u00ed, con el objetivo de aclarar y discutir lo referente al impuesto verde que se aplicar\u00e1 en el estado a partir del mes de junio.<\/p>\n<p style=\"text-align: justify;\">Juan Marcos Fierro, panelista y experto en relaciones institucionales con congresos locales y consejero de Coparmex, habl\u00f3 sobre la importancia de los impuestos verdes para combatir la contaminaci\u00f3n ambiental.<\/p>\n<p style=\"text-align: justify;\">\u00abConociendo o leyendo las iniciativas y las exposiciones de motivo, ellos los que est\u00e1n buscando es justamente que el gobierno se haga de recursos para remediar el tema de los da\u00f1os causados por la contaminaci\u00f3n de las empresas, pero tambi\u00e9n para incentivar a las empresas a que vayan por unos procesos verdes\u00bb, coment\u00f3.<\/p>\n<p style=\"text-align: justify;\">Explic\u00f3 que uno de los objetivos de este tipo de impuestos es impulsar a las empresas a la implementaci\u00f3n de procesos m\u00e1s amigables con el medio ambiente, aunado al tema de poder introducir una econom\u00eda circular en el estado.<\/p>\n<p style=\"text-align: justify;\">\u00abNo nada m\u00e1s es contaminas y pagas, no contaminas y no pagas, entonces a ra\u00edz de eso, hemos venido viendo c\u00f3mo se han presentando y aprobando los impuestos y este foro justamente quiere que los panelistas y que ustedes tambi\u00e9n con sus preguntas hagamos una interacci\u00f3n para saber cu\u00e1l es la mejor forma de regular estos impuestos\u00bb, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">Explic\u00f3 que dentro de la reglamentaci\u00f3n se deben tomar en cuenta una serie de beneficios o deducciones fiscales, as\u00ed como facilidades administrativas, que a la par, impactar\u00e1 en la reducci\u00f3n de emisiones de gas y contaminantes.<\/p>\n<p style=\"text-align: justify;\">Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0La Alianza Empresarial de San Luis Potos\u00ed inici\u00f3 con el Foro de Impuestos Ambientales: Reglamentaci\u00f3n en San Luis Potos\u00ed, con el objetivo de aclarar y discutir lo referente al impuesto verde que se aplicar\u00e1 en el estado a partir del mes de junio. Juan Marcos Fierro, panelista y experto en relaciones institucionales con congresos locales y consejero de Coparmex, habl\u00f3 sobre la importancia de los impuestos verdes para combatir la contaminaci\u00f3n ambiental. \u00abConociendo o leyendo las iniciativas y las exposiciones de motivo, ellos los que est\u00e1n buscando es justamente que el gobierno se haga de recursos para remediar el tema [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":128137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-128114","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0La Alianza Empresarial de San Luis Potos\u00ed inici\u00f3 con el Foro de Impuestos Ambientales: Reglamentaci\u00f3n en San Luis Potos\u00ed, con el objetivo de aclarar y discutir lo referente al impuesto verde que se aplicar\u00e1 en el estado a partir del mes de junio. Juan Marcos Fierro, panelista y experto en relaciones institucionales con congresos locales y consejero de Coparmex, habl\u00f3 sobre la importancia de los impuestos verdes para combatir la contaminaci\u00f3n ambiental. \u00abConociendo o leyendo las iniciativas y las exposiciones de motivo, ellos los que est\u00e1n buscando es justamente que el gobierno se haga de recursos para remediar el tema [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T00:40:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T00:40:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez01ForosAmbientales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales\",\"datePublished\":\"2024-04-23T00:40:30+00:00\",\"dateModified\":\"2024-04-23T00:40:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/\"},\"wordCount\":296,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez01ForosAmbientales.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/\",\"name\":\"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez01ForosAmbientales.jpg\",\"datePublished\":\"2024-04-23T00:40:30+00:00\",\"dateModified\":\"2024-04-23T00:40:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez01ForosAmbientales.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez01ForosAmbientales.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/","og_locale":"es_ES","og_type":"article","og_title":"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales - Canal 7 SLP - 2024","og_description":"SLP.-\u00a0La Alianza Empresarial de San Luis Potos\u00ed inici\u00f3 con el Foro de Impuestos Ambientales: Reglamentaci\u00f3n en San Luis Potos\u00ed, con el objetivo de aclarar y discutir lo referente al impuesto verde que se aplicar\u00e1 en el estado a partir del mes de junio. Juan Marcos Fierro, panelista y experto en relaciones institucionales con congresos locales y consejero de Coparmex, habl\u00f3 sobre la importancia de los impuestos verdes para combatir la contaminaci\u00f3n ambiental. \u00abConociendo o leyendo las iniciativas y las exposiciones de motivo, ellos los que est\u00e1n buscando es justamente que el gobierno se haga de recursos para remediar el tema [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-23T00:40:30+00:00","article_modified_time":"2024-04-23T00:40:49+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez01ForosAmbientales.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales","datePublished":"2024-04-23T00:40:30+00:00","dateModified":"2024-04-23T00:40:49+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/"},"wordCount":296,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez01ForosAmbientales.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/","url":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/","name":"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez01ForosAmbientales.jpg","datePublished":"2024-04-23T00:40:30+00:00","dateModified":"2024-04-23T00:40:49+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez01ForosAmbientales.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez01ForosAmbientales.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/deducciones-fiscales-y-facilidades-administrativas-puntos-a-considerar-en-reglamentacion-de-impuestos-ambientales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Deducciones fiscales y facilidades administrativas; puntos a considerar en reglamentaci\u00f3n de impuestos ambientales"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/128114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=128114"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/128114\/revisions"}],"predecessor-version":[{"id":128138,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/128114\/revisions\/128138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/128137"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=128114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=128114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=128114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}