{"id":127272,"date":"2024-04-15T19:38:20","date_gmt":"2024-04-16T01:38:20","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=127272"},"modified":"2024-04-15T19:38:20","modified_gmt":"2024-04-16T01:38:20","slug":"entregan-autoridades-rehabilitacion-de-la-avenida-cfe","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/","title":{"rendered":"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE"},"content":{"rendered":"<ul>\n<li>A la par, fueron destacados proyectos de movilidad en SLP, como la v\u00eda alterna.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">SLP.-\u00a0Autoridades estatales y empresariado potosino estuvieron presentes en la entrega de rehabilitaci\u00f3n de la Avenida CFE que se ubica en la Zona Industrial de San Luis Potos\u00ed.<\/p>\n<p style=\"text-align: justify;\">La titular de la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas, Leticia Vargas Tinajero, destac\u00f3 los avances que se han concretado en este punto de la ciudad.<\/p>\n<p style=\"text-align: justify;\">\u00abAvenida CFE era otra arteria abandonada con encharcamientos que inhabilitaban su tr\u00e1nsito y que volv\u00edan inseguros los trayectos hacia las empresas aleda\u00f1as\u00bb, dijo al inicio de su intervenci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con la informaci\u00f3n proporcionada, las obras concluidas forman parte del rescate de la movilidad que se tienen en la zona metropolitana.<\/p>\n<p style=\"text-align: justify;\">\u00abLa rehabilitaci\u00f3n de esta avenida incluy\u00f3 labores de demolici\u00f3n de pavimento da\u00f1ado, tendido de base hidr\u00e1ulica, base asf\u00e1ltica y tendido de una nueva carpeta asf\u00e1ltica de 10 cent\u00edmetros, son m\u00e1s de 45,000 metros cuadrados renovados en casi 3.5 km de longitud en ambos sentidos\u00bb, detall\u00f3.<\/p>\n<p style=\"text-align: justify;\">Aunado a ello, anunci\u00f3 que se tienen m\u00e1s obras y acciones programadas para el impulso y atracci\u00f3n de nuevas oportunidades de inversi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00abVamos a continuar la ruta alterna que vendr\u00e1 a comunicar mediante un puente que cruza las v\u00edas y salir al eje 122, esto ya est\u00e1 en marcha y en poco tiempo el recuerdo de que ten\u00edamos de la avenida industria con sus baches de m\u00e1s de 2 metros, ser\u00e1 como una pesadilla que no queremos repetir\u00bb, a\u00f1adi\u00f3.<\/p>\n<p style=\"text-align: justify;\">Continu\u00f3: \u00abCuidemos la infraestructura urbana que hoy se entrega, la se\u00f1al\u00e9tica, las guarniciones y banquetas son trabajos que han costado mucho a todos\u00bb.<\/p>\n<p style=\"text-align: justify;\">Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la par, fueron destacados proyectos de movilidad en SLP, como la v\u00eda alterna. SLP.-\u00a0Autoridades estatales y empresariado potosino estuvieron presentes en la entrega de rehabilitaci\u00f3n de la Avenida CFE que se ubica en la Zona Industrial de San Luis Potos\u00ed. La titular de la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas, Leticia Vargas Tinajero, destac\u00f3 los avances que se han concretado en este punto de la ciudad. \u00abAvenida CFE era otra arteria abandonada con encharcamientos que inhabilitaban su tr\u00e1nsito y que volv\u00edan inseguros los trayectos hacia las empresas aleda\u00f1as\u00bb, dijo al inicio de su intervenci\u00f3n. De acuerdo con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":127311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,510,45],"tags":[],"class_list":["post-127272","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-gobedoslp","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entregan autoridades rehabilitaci\u00f3n de la avenida CFE - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"A la par, fueron destacados proyectos de movilidad en SLP, como la v\u00eda alterna. SLP.-\u00a0Autoridades estatales y empresariado potosino estuvieron presentes en la entrega de rehabilitaci\u00f3n de la Avenida CFE que se ubica en la Zona Industrial de San Luis Potos\u00ed. La titular de la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas, Leticia Vargas Tinajero, destac\u00f3 los avances que se han concretado en este punto de la ciudad. \u00abAvenida CFE era otra arteria abandonada con encharcamientos que inhabilitaban su tr\u00e1nsito y que volv\u00edan inseguros los trayectos hacia las empresas aleda\u00f1as\u00bb, dijo al inicio de su intervenci\u00f3n. De acuerdo con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T01:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AvCFE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE\",\"datePublished\":\"2024-04-16T01:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AvCFE.jpg\",\"articleSection\":[\"DESTACADAS\",\"GOBEDOSLP\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/\",\"name\":\"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AvCFE.jpg\",\"datePublished\":\"2024-04-16T01:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AvCFE.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Vazquez0AvCFE.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/","og_locale":"es_ES","og_type":"article","og_title":"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE - Canal 7 SLP - 2024","og_description":"A la par, fueron destacados proyectos de movilidad en SLP, como la v\u00eda alterna. SLP.-\u00a0Autoridades estatales y empresariado potosino estuvieron presentes en la entrega de rehabilitaci\u00f3n de la Avenida CFE que se ubica en la Zona Industrial de San Luis Potos\u00ed. La titular de la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas, Leticia Vargas Tinajero, destac\u00f3 los avances que se han concretado en este punto de la ciudad. \u00abAvenida CFE era otra arteria abandonada con encharcamientos que inhabilitaban su tr\u00e1nsito y que volv\u00edan inseguros los trayectos hacia las empresas aleda\u00f1as\u00bb, dijo al inicio de su intervenci\u00f3n. De acuerdo con [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-16T01:38:20+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AvCFE.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE","datePublished":"2024-04-16T01:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/"},"wordCount":303,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AvCFE.jpg","articleSection":["DESTACADAS","GOBEDOSLP","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/","url":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/","name":"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AvCFE.jpg","datePublished":"2024-04-16T01:38:20+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AvCFE.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Vazquez0AvCFE.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/entregan-autoridades-rehabilitacion-de-la-avenida-cfe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Entregan autoridades rehabilitaci\u00f3n de la avenida CFE"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/127272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=127272"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/127272\/revisions"}],"predecessor-version":[{"id":127316,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/127272\/revisions\/127316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/127311"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=127272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=127272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=127272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}