{"id":126915,"date":"2024-04-11T13:26:42","date_gmt":"2024-04-11T19:26:42","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=126915"},"modified":"2024-04-11T13:26:42","modified_gmt":"2024-04-11T19:26:42","slug":"ricardo-cordero-listo-para-el-rally-aguascalientes","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/","title":{"rendered":"Ricardo Cordero listo para el Rally Aguascalientes"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Todo listo para la segunda edici\u00f3n del rally Aguascalientes, en donde el piloto potosino Ricardo Cordero tendr\u00e1 acci\u00f3n en el rally celebrado en el marco de la feria de San Marco.<\/p>\n<p style=\"text-align: justify;\">La segunda edici\u00f3n del rally Aguascalientes se desarrollar\u00e1 los d\u00edas viernes 12 y s\u00e1bado 13 de abril en los caminos hidroc\u00e1lidos, el viernes la arrancada ceremonial se efectuar\u00e1 con la salida ceremonial en la plaza de Armas de Aguascalientes, la meta tendr\u00e1 verificativo en el Ovalo Aguascalientes M\u00e9xico el s\u00e1bado 13.<\/p>\n<p style=\"text-align: justify;\">Mientras tanto el programa social primero por San Luis sigue en marcha, la atleta Montserrat Rodr\u00edguez ser\u00e1 la beneficiada en su participaci\u00f3n en el encuentro FMAA de relevos de pista y campo a efectuarse en el comit\u00e9 ol\u00edmpico mexicano, ah\u00ed Montse buscara su boleto a juegos Ol\u00edmpicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Todo listo para la segunda edici\u00f3n del rally Aguascalientes, en donde el piloto potosino Ricardo Cordero tendr\u00e1 acci\u00f3n en el rally celebrado en el marco de la feria de San Marco. La segunda edici\u00f3n del rally Aguascalientes se desarrollar\u00e1 los d\u00edas viernes 12 y s\u00e1bado 13 de abril en los caminos hidroc\u00e1lidos, el viernes la arrancada ceremonial se efectuar\u00e1 con la salida ceremonial en la plaza de Armas de Aguascalientes, la meta tendr\u00e1 verificativo en el Ovalo Aguascalientes M\u00e9xico el s\u00e1bado 13. Mientras tanto el programa social primero por San Luis sigue en marcha, la atleta Montserrat Rodr\u00edguez ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-126915","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ricardo Cordero listo para el Rally Aguascalientes - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricardo Cordero listo para el Rally Aguascalientes - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Todo listo para la segunda edici\u00f3n del rally Aguascalientes, en donde el piloto potosino Ricardo Cordero tendr\u00e1 acci\u00f3n en el rally celebrado en el marco de la feria de San Marco. La segunda edici\u00f3n del rally Aguascalientes se desarrollar\u00e1 los d\u00edas viernes 12 y s\u00e1bado 13 de abril en los caminos hidroc\u00e1lidos, el viernes la arrancada ceremonial se efectuar\u00e1 con la salida ceremonial en la plaza de Armas de Aguascalientes, la meta tendr\u00e1 verificativo en el Ovalo Aguascalientes M\u00e9xico el s\u00e1bado 13. Mientras tanto el programa social primero por San Luis sigue en marcha, la atleta Montserrat Rodr\u00edguez ser\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T19:26:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi01Rally.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Ricardo Cordero listo para el Rally Aguascalientes\",\"datePublished\":\"2024-04-11T19:26:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi01Rally.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/\",\"name\":\"Ricardo Cordero listo para el Rally Aguascalientes - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi01Rally.jpg\",\"datePublished\":\"2024-04-11T19:26:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi01Rally.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi01Rally.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/ricardo-cordero-listo-para-el-rally-aguascalientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricardo Cordero listo para el Rally Aguascalientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricardo Cordero listo para el Rally Aguascalientes - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/","og_locale":"es_ES","og_type":"article","og_title":"Ricardo Cordero listo para el Rally Aguascalientes - Canal 7 SLP - 2024","og_description":"SLP.- Todo listo para la segunda edici\u00f3n del rally Aguascalientes, en donde el piloto potosino Ricardo Cordero tendr\u00e1 acci\u00f3n en el rally celebrado en el marco de la feria de San Marco. La segunda edici\u00f3n del rally Aguascalientes se desarrollar\u00e1 los d\u00edas viernes 12 y s\u00e1bado 13 de abril en los caminos hidroc\u00e1lidos, el viernes la arrancada ceremonial se efectuar\u00e1 con la salida ceremonial en la plaza de Armas de Aguascalientes, la meta tendr\u00e1 verificativo en el Ovalo Aguascalientes M\u00e9xico el s\u00e1bado 13. Mientras tanto el programa social primero por San Luis sigue en marcha, la atleta Montserrat Rodr\u00edguez ser\u00e1 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-11T19:26:42+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi01Rally.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Ricardo Cordero listo para el Rally Aguascalientes","datePublished":"2024-04-11T19:26:42+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/"},"wordCount":147,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi01Rally.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/","url":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/","name":"Ricardo Cordero listo para el Rally Aguascalientes - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi01Rally.jpg","datePublished":"2024-04-11T19:26:42+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi01Rally.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi01Rally.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/ricardo-cordero-listo-para-el-rally-aguascalientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Ricardo Cordero listo para el Rally Aguascalientes"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=126915"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126915\/revisions"}],"predecessor-version":[{"id":126922,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126915\/revisions\/126922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/126921"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=126915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=126915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=126915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}