{"id":126583,"date":"2024-04-08T15:05:53","date_gmt":"2024-04-08T21:05:53","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=126583"},"modified":"2024-04-08T17:13:26","modified_gmt":"2024-04-08T23:13:26","slug":"debate-en-el-ine-costo-10-mdp","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/","title":{"rendered":"Debate en el INE cost\u00f3 10 mdp"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- El debate presidencial inaugural, celebrado en las instalaciones del Instituto Nacional Electoral (INE), tuvo un costo preliminar de 10 millones de pesos, pero enfrent\u00f3 desaf\u00edos operativos.<\/p>\n<p style=\"text-align: justify;\">El gasto abarc\u00f3 la producci\u00f3n y montaje del set para el debate en el sal\u00f3n de sesiones, as\u00ed como los dispositivos de seguridad tanto dentro como fuera del INE, entre otros elementos.<\/p>\n<p style=\"text-align: justify;\">Durante el evento, el reloj utilizado por los candidatos para controlar el tiempo de sus intervenciones present\u00f3 fallas en varias ocasiones.<\/p>\n<p style=\"text-align: justify;\">Esto llev\u00f3 a que los participantes tuvieran que comunicarse desde la cabina con la moderaci\u00f3n para verificar el tiempo restante de sus participaciones.<\/p>\n<p style=\"text-align: justify;\">Estas incidencias generaron reclamos por parte de los candidatos, quienes solicitaban que se respetara el tiempo asignado de hasta cinco minutos para sus intervenciones.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, se reportaron otras dificultades, como problemas con la se\u00f1al de internet en la sala de prensa ubicada en la explanada del INE, as\u00ed como la ausencia de Wi-Fi proporcionado por el instituto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- El debate presidencial inaugural, celebrado en las instalaciones del Instituto Nacional Electoral (INE), tuvo un costo preliminar de 10 millones de pesos, pero enfrent\u00f3 desaf\u00edos operativos. El gasto abarc\u00f3 la producci\u00f3n y montaje del set para el debate en el sal\u00f3n de sesiones, as\u00ed como los dispositivos de seguridad tanto dentro como fuera del INE, entre otros elementos. Durante el evento, el reloj utilizado por los candidatos para controlar el tiempo de sus intervenciones present\u00f3 fallas en varias ocasiones. Esto llev\u00f3 a que los participantes tuvieran que comunicarse desde la cabina con la moderaci\u00f3n para verificar el tiempo restante [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-126583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Debate en el INE cost\u00f3 10 mdp - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Debate en el INE cost\u00f3 10 mdp - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- El debate presidencial inaugural, celebrado en las instalaciones del Instituto Nacional Electoral (INE), tuvo un costo preliminar de 10 millones de pesos, pero enfrent\u00f3 desaf\u00edos operativos. El gasto abarc\u00f3 la producci\u00f3n y montaje del set para el debate en el sal\u00f3n de sesiones, as\u00ed como los dispositivos de seguridad tanto dentro como fuera del INE, entre otros elementos. Durante el evento, el reloj utilizado por los candidatos para controlar el tiempo de sus intervenciones present\u00f3 fallas en varias ocasiones. Esto llev\u00f3 a que los participantes tuvieran que comunicarse desde la cabina con la moderaci\u00f3n para verificar el tiempo restante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-08T21:05:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T23:13:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/02-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Debate en el INE cost\u00f3 10 mdp\",\"datePublished\":\"2024-04-08T21:05:53+00:00\",\"dateModified\":\"2024-04-08T23:13:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/02-5.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/\",\"name\":\"Debate en el INE cost\u00f3 10 mdp - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/02-5.jpg\",\"datePublished\":\"2024-04-08T21:05:53+00:00\",\"dateModified\":\"2024-04-08T23:13:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/02-5.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/02-5.jpg\",\"width\":746,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/debate-en-el-ine-costo-10-mdp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Debate en el INE cost\u00f3 10 mdp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Debate en el INE cost\u00f3 10 mdp - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/","og_locale":"es_ES","og_type":"article","og_title":"Debate en el INE cost\u00f3 10 mdp - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- El debate presidencial inaugural, celebrado en las instalaciones del Instituto Nacional Electoral (INE), tuvo un costo preliminar de 10 millones de pesos, pero enfrent\u00f3 desaf\u00edos operativos. El gasto abarc\u00f3 la producci\u00f3n y montaje del set para el debate en el sal\u00f3n de sesiones, as\u00ed como los dispositivos de seguridad tanto dentro como fuera del INE, entre otros elementos. Durante el evento, el reloj utilizado por los candidatos para controlar el tiempo de sus intervenciones present\u00f3 fallas en varias ocasiones. Esto llev\u00f3 a que los participantes tuvieran que comunicarse desde la cabina con la moderaci\u00f3n para verificar el tiempo restante [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-08T21:05:53+00:00","article_modified_time":"2024-04-08T23:13:26+00:00","og_image":[{"width":746,"height":445,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/02-5.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Debate en el INE cost\u00f3 10 mdp","datePublished":"2024-04-08T21:05:53+00:00","dateModified":"2024-04-08T23:13:26+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/"},"wordCount":173,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/02-5.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/","url":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/","name":"Debate en el INE cost\u00f3 10 mdp - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/02-5.jpg","datePublished":"2024-04-08T21:05:53+00:00","dateModified":"2024-04-08T23:13:26+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/02-5.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/02-5.jpg","width":746,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/debate-en-el-ine-costo-10-mdp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Debate en el INE cost\u00f3 10 mdp"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=126583"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126583\/revisions"}],"predecessor-version":[{"id":126652,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126583\/revisions\/126652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/126601"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=126583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=126583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=126583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}