{"id":126582,"date":"2024-04-08T15:00:41","date_gmt":"2024-04-08T21:00:41","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=126582"},"modified":"2024-04-08T17:12:16","modified_gmt":"2024-04-08T23:12:16","slug":"asi-se-vivio-el-primer-debate-presidencial","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/","title":{"rendered":"As\u00ed se vivi\u00f3 el primer debate presidencial"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- Este 7 de abril, el Instituto Nacional Electoral (INE) organiz\u00f3 el primer encuentro en la Sala de Consejo General del Instituto.<\/p>\n<p style=\"text-align: justify;\">Durante el evento, los candidatos discutieron temas relacionados con educaci\u00f3n, salud, transparencia, corrupci\u00f3n, no discriminaci\u00f3n, grupos vulnerables, violencia contra las mujeres y migraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Claudia Sheinbaum, \u00c1lvarez M\u00e1ynez y X\u00f3chitl G\u00e1lvez presentaron sus propuestas.<\/p>\n<p style=\"text-align: justify;\">Sheinbaum destac\u00f3 la importancia de continuar con la transformaci\u00f3n y fortalecer el sistema de salud, mientras que \u00c1lvarez M\u00e1ynez prometi\u00f3 un sistema de salud m\u00e1s inclusivo.<\/p>\n<p style=\"text-align: justify;\">G\u00e1lvez propuso una tarjeta digital para adquirir medicamentos y critic\u00f3 la gesti\u00f3n de Sheinbaum.<\/p>\n<p style=\"text-align: justify;\">El debate tambi\u00e9n abord\u00f3 temas como transparencia, corrupci\u00f3n, no discriminaci\u00f3n, violencia contra las mujeres y migraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Las candidatas intercambiaron acusaciones y propuestas en estos temas, resaltando diferencias en enfoques y estrategias.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que el encuentro estuvo marcado por ataques, se\u00f1alamientos y escasas propuestas, con el objetivo de ofrecer a los ciudadanos elementos para formar un criterio sobre las capacidades y propuestas de las candidatas a la presidencia de M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">El pr\u00f3ximo 28 de abril se llevar\u00e1 a cabo el segundo ejercicio, donde se espera una mayor profundidad en las propuestas presentadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- Este 7 de abril, el Instituto Nacional Electoral (INE) organiz\u00f3 el primer encuentro en la Sala de Consejo General del Instituto. Durante el evento, los candidatos discutieron temas relacionados con educaci\u00f3n, salud, transparencia, corrupci\u00f3n, no discriminaci\u00f3n, grupos vulnerables, violencia contra las mujeres y migraci\u00f3n. Claudia Sheinbaum, \u00c1lvarez M\u00e1ynez y X\u00f3chitl G\u00e1lvez presentaron sus propuestas. Sheinbaum destac\u00f3 la importancia de continuar con la transformaci\u00f3n y fortalecer el sistema de salud, mientras que \u00c1lvarez M\u00e1ynez prometi\u00f3 un sistema de salud m\u00e1s inclusivo. G\u00e1lvez propuso una tarjeta digital para adquirir medicamentos y critic\u00f3 la gesti\u00f3n de Sheinbaum. El debate tambi\u00e9n abord\u00f3 temas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-126582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As\u00ed se vivi\u00f3 el primer debate presidencial - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed se vivi\u00f3 el primer debate presidencial - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- Este 7 de abril, el Instituto Nacional Electoral (INE) organiz\u00f3 el primer encuentro en la Sala de Consejo General del Instituto. Durante el evento, los candidatos discutieron temas relacionados con educaci\u00f3n, salud, transparencia, corrupci\u00f3n, no discriminaci\u00f3n, grupos vulnerables, violencia contra las mujeres y migraci\u00f3n. Claudia Sheinbaum, \u00c1lvarez M\u00e1ynez y X\u00f3chitl G\u00e1lvez presentaron sus propuestas. Sheinbaum destac\u00f3 la importancia de continuar con la transformaci\u00f3n y fortalecer el sistema de salud, mientras que \u00c1lvarez M\u00e1ynez prometi\u00f3 un sistema de salud m\u00e1s inclusivo. G\u00e1lvez propuso una tarjeta digital para adquirir medicamentos y critic\u00f3 la gesti\u00f3n de Sheinbaum. El debate tambi\u00e9n abord\u00f3 temas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-08T21:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T23:12:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/01-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"As\u00ed se vivi\u00f3 el primer debate presidencial\",\"datePublished\":\"2024-04-08T21:00:41+00:00\",\"dateModified\":\"2024-04-08T23:12:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/\"},\"wordCount\":214,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-7.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/\",\"name\":\"As\u00ed se vivi\u00f3 el primer debate presidencial - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-7.jpg\",\"datePublished\":\"2024-04-08T21:00:41+00:00\",\"dateModified\":\"2024-04-08T23:12:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-7.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-7.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/asi-se-vivio-el-primer-debate-presidencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed se vivi\u00f3 el primer debate presidencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed se vivi\u00f3 el primer debate presidencial - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00ed se vivi\u00f3 el primer debate presidencial - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- Este 7 de abril, el Instituto Nacional Electoral (INE) organiz\u00f3 el primer encuentro en la Sala de Consejo General del Instituto. Durante el evento, los candidatos discutieron temas relacionados con educaci\u00f3n, salud, transparencia, corrupci\u00f3n, no discriminaci\u00f3n, grupos vulnerables, violencia contra las mujeres y migraci\u00f3n. Claudia Sheinbaum, \u00c1lvarez M\u00e1ynez y X\u00f3chitl G\u00e1lvez presentaron sus propuestas. Sheinbaum destac\u00f3 la importancia de continuar con la transformaci\u00f3n y fortalecer el sistema de salud, mientras que \u00c1lvarez M\u00e1ynez prometi\u00f3 un sistema de salud m\u00e1s inclusivo. G\u00e1lvez propuso una tarjeta digital para adquirir medicamentos y critic\u00f3 la gesti\u00f3n de Sheinbaum. El debate tambi\u00e9n abord\u00f3 temas [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-08T21:00:41+00:00","article_modified_time":"2024-04-08T23:12:16+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/01-7.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"As\u00ed se vivi\u00f3 el primer debate presidencial","datePublished":"2024-04-08T21:00:41+00:00","dateModified":"2024-04-08T23:12:16+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/"},"wordCount":214,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/01-7.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/","url":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/","name":"As\u00ed se vivi\u00f3 el primer debate presidencial - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/01-7.jpg","datePublished":"2024-04-08T21:00:41+00:00","dateModified":"2024-04-08T23:12:16+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/01-7.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/01-7.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/asi-se-vivio-el-primer-debate-presidencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"As\u00ed se vivi\u00f3 el primer debate presidencial"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=126582"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126582\/revisions"}],"predecessor-version":[{"id":126651,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126582\/revisions\/126651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/126600"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=126582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=126582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=126582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}