{"id":126208,"date":"2024-04-03T15:10:57","date_gmt":"2024-04-03T21:10:57","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=126208"},"modified":"2024-04-04T17:27:11","modified_gmt":"2024-04-04T23:27:11","slug":"reservas-internacionales-superan-217-mil-mdd","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/","title":{"rendered":"Reservas internacionales superan 217 mil mdd"},"content":{"rendered":"<ul>\n<li>Marcan m\u00e1ximo hist\u00f3rico.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">M\u00e9xico.- Las reservas internacionales del pa\u00eds han alcanzado un nuevo r\u00e9cord, superando los 217 mil millones de d\u00f3lares en menos de una semana, seg\u00fan inform\u00f3 el Banco de M\u00e9xico (BANXICO).<\/p>\n<p style=\"text-align: justify;\">El saldo de estos activos, que act\u00faan como un escudo financiero ante posibles desequilibrios en las cuentas externas o impactos del exterior, aument\u00f3 en 291 millones de d\u00f3lares al mi\u00e9rcoles 27 de marzo de 2024, llegando a 217 mil 194 millones de d\u00f3lares al cierre de la semana anterior.<\/p>\n<p style=\"text-align: justify;\">El Instituto Central se\u00f1al\u00f3 que este incremento semanal en las reservas internacionales se debi\u00f3 principalmente a cambios en la valoraci\u00f3n de los activos internacionales del Banco de M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">En lo que va del a\u00f1o, las reservas han aumentado en 4 mil 432 millones de d\u00f3lares en comparaci\u00f3n con el saldo al final de 2023, que era de 212 mil 762 millones de d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marcan m\u00e1ximo hist\u00f3rico. M\u00e9xico.- Las reservas internacionales del pa\u00eds han alcanzado un nuevo r\u00e9cord, superando los 217 mil millones de d\u00f3lares en menos de una semana, seg\u00fan inform\u00f3 el Banco de M\u00e9xico (BANXICO). El saldo de estos activos, que act\u00faan como un escudo financiero ante posibles desequilibrios en las cuentas externas o impactos del exterior, aument\u00f3 en 291 millones de d\u00f3lares al mi\u00e9rcoles 27 de marzo de 2024, llegando a 217 mil 194 millones de d\u00f3lares al cierre de la semana anterior. El Instituto Central se\u00f1al\u00f3 que este incremento semanal en las reservas internacionales se debi\u00f3 principalmente a cambios en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[40,46],"tags":[],"class_list":["post-126208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reservas internacionales superan 217 mil mdd - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reservas internacionales superan 217 mil mdd - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"Marcan m\u00e1ximo hist\u00f3rico. M\u00e9xico.- Las reservas internacionales del pa\u00eds han alcanzado un nuevo r\u00e9cord, superando los 217 mil millones de d\u00f3lares en menos de una semana, seg\u00fan inform\u00f3 el Banco de M\u00e9xico (BANXICO). El saldo de estos activos, que act\u00faan como un escudo financiero ante posibles desequilibrios en las cuentas externas o impactos del exterior, aument\u00f3 en 291 millones de d\u00f3lares al mi\u00e9rcoles 27 de marzo de 2024, llegando a 217 mil 194 millones de d\u00f3lares al cierre de la semana anterior. El Instituto Central se\u00f1al\u00f3 que este incremento semanal en las reservas internacionales se debi\u00f3 principalmente a cambios en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T21:10:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T23:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/03-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Reservas internacionales superan 217 mil mdd\",\"datePublished\":\"2024-04-03T21:10:57+00:00\",\"dateModified\":\"2024-04-04T23:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/03-2.jpg\",\"articleSection\":[\"ECONOM\u00cdA\",\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/\",\"name\":\"Reservas internacionales superan 217 mil mdd - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/03-2.jpg\",\"datePublished\":\"2024-04-03T21:10:57+00:00\",\"dateModified\":\"2024-04-04T23:27:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/03-2.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/03-2.jpg\",\"width\":2200,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/reservas-internacionales-superan-217-mil-mdd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reservas internacionales superan 217 mil mdd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reservas internacionales superan 217 mil mdd - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/","og_locale":"es_ES","og_type":"article","og_title":"Reservas internacionales superan 217 mil mdd - Canal 7 SLP - 2024","og_description":"Marcan m\u00e1ximo hist\u00f3rico. M\u00e9xico.- Las reservas internacionales del pa\u00eds han alcanzado un nuevo r\u00e9cord, superando los 217 mil millones de d\u00f3lares en menos de una semana, seg\u00fan inform\u00f3 el Banco de M\u00e9xico (BANXICO). El saldo de estos activos, que act\u00faan como un escudo financiero ante posibles desequilibrios en las cuentas externas o impactos del exterior, aument\u00f3 en 291 millones de d\u00f3lares al mi\u00e9rcoles 27 de marzo de 2024, llegando a 217 mil 194 millones de d\u00f3lares al cierre de la semana anterior. El Instituto Central se\u00f1al\u00f3 que este incremento semanal en las reservas internacionales se debi\u00f3 principalmente a cambios en [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-03T21:10:57+00:00","article_modified_time":"2024-04-04T23:27:11+00:00","og_image":[{"width":2200,"height":1100,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/03-2.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Reservas internacionales superan 217 mil mdd","datePublished":"2024-04-03T21:10:57+00:00","dateModified":"2024-04-04T23:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/"},"wordCount":159,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/03-2.jpg","articleSection":["ECONOM\u00cdA","NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/","url":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/","name":"Reservas internacionales superan 217 mil mdd - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/03-2.jpg","datePublished":"2024-04-03T21:10:57+00:00","dateModified":"2024-04-04T23:27:11+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/03-2.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/03-2.jpg","width":2200,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/reservas-internacionales-superan-217-mil-mdd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Reservas internacionales superan 217 mil mdd"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=126208"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126208\/revisions"}],"predecessor-version":[{"id":126368,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126208\/revisions\/126368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/126224"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=126208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=126208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=126208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}