{"id":126185,"date":"2024-04-03T14:40:21","date_gmt":"2024-04-03T20:40:21","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=126185"},"modified":"2024-04-03T14:40:21","modified_gmt":"2024-04-03T20:40:21","slug":"festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/","title":{"rendered":"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- En el marco del aniversario n\u00famero 44 Los Centros de Acondicionamiento F\u00edsico Atl\u00e9tico realizar\u00e1n el Festival Atl\u00e9tico 2024 el cual se desarrollara el pr\u00f3ximo domingo 7 de abril.<\/p>\n<p style=\"text-align: justify;\">Teniendo como punto de partida y meta el jard\u00edn de Tequis haciendo el recorrido sobre la recreovia de Carranza, dando inicio a las 8 de la ma\u00f1ana<\/p>\n<p style=\"text-align: justify;\">El festival atl\u00e9tico contar\u00e1 con dos distancias a elegir 7,2 y 4 kil\u00f3metros.<\/p>\n<p style=\"text-align: justify;\">Para la categor\u00eda libre varonil y femenil, cubrir\u00e1n 7.2 kil\u00f3metros, es decir, una vuelta y media al circuito por Avenida V. Carranza.<\/p>\n<p style=\"text-align: justify;\">Por otra parte, se tendr\u00e1 la distancia de 4 kil\u00f3metros, en la que obligatoriamente deben participar en parejas, con tres categor\u00edas disponibles en ambas ramas.<\/p>\n<p style=\"text-align: justify;\">La \u201cA\u201d en la que podr\u00e1n correr mam\u00e1 o pap\u00e1 con hija o hijo menor de 12 a\u00f1os; la \u201cB\u201d para la abuela o abuelo con nieto o nieta menor de 12 a\u00f1os; y la \u201cC\u201d con pareja adultos conformada por hombre \u2013 mujer, hombre \u2013 hombre o mujer \u2013 mujer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- En el marco del aniversario n\u00famero 44 Los Centros de Acondicionamiento F\u00edsico Atl\u00e9tico realizar\u00e1n el Festival Atl\u00e9tico 2024 el cual se desarrollara el pr\u00f3ximo domingo 7 de abril. Teniendo como punto de partida y meta el jard\u00edn de Tequis haciendo el recorrido sobre la recreovia de Carranza, dando inicio a las 8 de la ma\u00f1ana El festival atl\u00e9tico contar\u00e1 con dos distancias a elegir 7,2 y 4 kil\u00f3metros. Para la categor\u00eda libre varonil y femenil, cubrir\u00e1n 7.2 kil\u00f3metros, es decir, una vuelta y media al circuito por Avenida V. Carranza. Por otra parte, se tendr\u00e1 la distancia de 4 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-126185","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- En el marco del aniversario n\u00famero 44 Los Centros de Acondicionamiento F\u00edsico Atl\u00e9tico realizar\u00e1n el Festival Atl\u00e9tico 2024 el cual se desarrollara el pr\u00f3ximo domingo 7 de abril. Teniendo como punto de partida y meta el jard\u00edn de Tequis haciendo el recorrido sobre la recreovia de Carranza, dando inicio a las 8 de la ma\u00f1ana El festival atl\u00e9tico contar\u00e1 con dos distancias a elegir 7,2 y 4 kil\u00f3metros. Para la categor\u00eda libre varonil y femenil, cubrir\u00e1n 7.2 kil\u00f3metros, es decir, una vuelta y media al circuito por Avenida V. Carranza. Por otra parte, se tendr\u00e1 la distancia de 4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T20:40:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi03Carrer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril\",\"datePublished\":\"2024-04-03T20:40:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/\"},\"wordCount\":187,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi03Carrer.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/\",\"name\":\"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi03Carrer.jpg\",\"datePublished\":\"2024-04-03T20:40:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi03Carrer.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi03Carrer.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/","og_locale":"es_ES","og_type":"article","og_title":"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril - Canal 7 SLP - 2024","og_description":"SLP.- En el marco del aniversario n\u00famero 44 Los Centros de Acondicionamiento F\u00edsico Atl\u00e9tico realizar\u00e1n el Festival Atl\u00e9tico 2024 el cual se desarrollara el pr\u00f3ximo domingo 7 de abril. Teniendo como punto de partida y meta el jard\u00edn de Tequis haciendo el recorrido sobre la recreovia de Carranza, dando inicio a las 8 de la ma\u00f1ana El festival atl\u00e9tico contar\u00e1 con dos distancias a elegir 7,2 y 4 kil\u00f3metros. Para la categor\u00eda libre varonil y femenil, cubrir\u00e1n 7.2 kil\u00f3metros, es decir, una vuelta y media al circuito por Avenida V. Carranza. Por otra parte, se tendr\u00e1 la distancia de 4 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-03T20:40:21+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi03Carrer.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril","datePublished":"2024-04-03T20:40:21+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/"},"wordCount":187,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi03Carrer.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/","url":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/","name":"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi03Carrer.jpg","datePublished":"2024-04-03T20:40:21+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi03Carrer.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi03Carrer.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/festival-atletico-2024-de-los-cafa-se-realizara-el-proximo-domingo-7-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Festival Atl\u00e9tico 2024 de los CAFA se realizar\u00e1 el pr\u00f3ximo domingo 7 de abril"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=126185"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126185\/revisions"}],"predecessor-version":[{"id":126198,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126185\/revisions\/126198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/126197"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=126185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=126185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=126185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}