{"id":126184,"date":"2024-04-03T14:38:51","date_gmt":"2024-04-03T20:38:51","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=126184"},"modified":"2024-04-03T14:38:51","modified_gmt":"2024-04-03T20:38:51","slug":"emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/","title":{"rendered":"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- El ajedrecista potosino Emanuel Robledo Flores logr\u00f3 el t\u00edtulo de Experto Nacional de la Federaci\u00f3n Mexicana de Ajedrez al ganar el LXIX Campeonato Nacional e Internacional Abierto Mexicano de Ajedrez Quer\u00e9taro 2024.<\/p>\n<p style=\"text-align: justify;\">El evento se celebr\u00f3 en Provincia Juriquilla con la participaci\u00f3n de casi dos mil competidores.<\/p>\n<p style=\"text-align: justify;\">Robledo al participar en la categor\u00eda Internacional y sumar 5.5 de 9 puntos posibles y as\u00ed consigui\u00f3 el mencionado t\u00edtulo.<\/p>\n<p style=\"text-align: justify;\">En su categor\u00eda participaron 130 jugadores de diversos pa\u00edses la gran mayor\u00eda con t\u00edtulos internacionales.<\/p>\n<p style=\"text-align: justify;\">El ajedrecista se prepara para sus pr\u00f3ximas competencias, el Macro Regional de CONADE que se llevar\u00e1 a cabo en Durango y un evento nacional en Xalapa, Veracruz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- El ajedrecista potosino Emanuel Robledo Flores logr\u00f3 el t\u00edtulo de Experto Nacional de la Federaci\u00f3n Mexicana de Ajedrez al ganar el LXIX Campeonato Nacional e Internacional Abierto Mexicano de Ajedrez Quer\u00e9taro 2024. El evento se celebr\u00f3 en Provincia Juriquilla con la participaci\u00f3n de casi dos mil competidores. Robledo al participar en la categor\u00eda Internacional y sumar 5.5 de 9 puntos posibles y as\u00ed consigui\u00f3 el mencionado t\u00edtulo. En su categor\u00eda participaron 130 jugadores de diversos pa\u00edses la gran mayor\u00eda con t\u00edtulos internacionales. El ajedrecista se prepara para sus pr\u00f3ximas competencias, el Macro Regional de CONADE que se llevar\u00e1 a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-126184","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- El ajedrecista potosino Emanuel Robledo Flores logr\u00f3 el t\u00edtulo de Experto Nacional de la Federaci\u00f3n Mexicana de Ajedrez al ganar el LXIX Campeonato Nacional e Internacional Abierto Mexicano de Ajedrez Quer\u00e9taro 2024. El evento se celebr\u00f3 en Provincia Juriquilla con la participaci\u00f3n de casi dos mil competidores. Robledo al participar en la categor\u00eda Internacional y sumar 5.5 de 9 puntos posibles y as\u00ed consigui\u00f3 el mencionado t\u00edtulo. En su categor\u00eda participaron 130 jugadores de diversos pa\u00edses la gran mayor\u00eda con t\u00edtulos internacionales. El ajedrecista se prepara para sus pr\u00f3ximas competencias, el Macro Regional de CONADE que se llevar\u00e1 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T20:38:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi02Ajedrez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez\",\"datePublished\":\"2024-04-03T20:38:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi02Ajedrez.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/\",\"name\":\"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi02Ajedrez.jpg\",\"datePublished\":\"2024-04-03T20:38:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi02Ajedrez.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Froi02Ajedrez.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/","og_locale":"es_ES","og_type":"article","og_title":"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez - Canal 7 SLP - 2024","og_description":"SLP.- El ajedrecista potosino Emanuel Robledo Flores logr\u00f3 el t\u00edtulo de Experto Nacional de la Federaci\u00f3n Mexicana de Ajedrez al ganar el LXIX Campeonato Nacional e Internacional Abierto Mexicano de Ajedrez Quer\u00e9taro 2024. El evento se celebr\u00f3 en Provincia Juriquilla con la participaci\u00f3n de casi dos mil competidores. Robledo al participar en la categor\u00eda Internacional y sumar 5.5 de 9 puntos posibles y as\u00ed consigui\u00f3 el mencionado t\u00edtulo. En su categor\u00eda participaron 130 jugadores de diversos pa\u00edses la gran mayor\u00eda con t\u00edtulos internacionales. El ajedrecista se prepara para sus pr\u00f3ximas competencias, el Macro Regional de CONADE que se llevar\u00e1 a [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-03T20:38:51+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi02Ajedrez.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez","datePublished":"2024-04-03T20:38:51+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/"},"wordCount":129,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi02Ajedrez.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/","url":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/","name":"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi02Ajedrez.jpg","datePublished":"2024-04-03T20:38:51+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi02Ajedrez.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Froi02Ajedrez.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/emanuel-robledo-conquista-el-titulo-de-experto-nacional-de-ajedrez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Emanuel Robledo conquista el T\u00edtulo de Experto Nacional de Ajedrez"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=126184"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126184\/revisions"}],"predecessor-version":[{"id":126196,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/126184\/revisions\/126196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/126195"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=126184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=126184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=126184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}