{"id":125946,"date":"2024-04-01T09:24:28","date_gmt":"2024-04-01T15:24:28","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=125946"},"modified":"2024-04-01T09:24:28","modified_gmt":"2024-04-01T15:24:28","slug":"tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/","title":{"rendered":"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 1.21429rem;\">SLP.- Durante dos meses y medio, habitantes de la calle Taiw\u00e1n, correspondiente a la colonia Sim\u00f3n D\u00edaz-El Aguaje reportaron la p\u00e9rdida de miles de litros de agua debido a una gran fuga, que corri\u00f3 por diferentes calles.<\/span><\/p>\n<p style=\"text-align: justify;\">Inicialmente Mar\u00eda Isabel Galv\u00e1n de la Cruz -quien vive en la zona- se\u00f1al\u00f3 que desde una p\u00e1gina, los vecinos emiten sus reportes.<\/p>\n<p style=\"text-align: justify;\">Se\u00f1al\u00f3 que mientras se garantizaba el suministro por la red, la impotencia se sent\u00eda, ya que en la parte afectada -librada por algunos automovilistas- el l\u00edquido se desperdiciaba.<\/p>\n<p style=\"text-align: justify;\">La gente que alert\u00f3 a la autoridad recibi\u00f3 dos folios, as\u00ed como se hizo de conocimiento otra situaci\u00f3n en un punto cercano.<\/p>\n<p style=\"text-align: justify;\">En el momento se hizo presente personal de Interapas, para intervenir en la parte afectada.<\/p>\n<p style=\"text-align: justify;\">Por lo cual Mar\u00eda Isabel \u00fanicamente solicit\u00f3 que el arreglo se d\u00e9 de forma integral.<\/p>\n<p>Por: Paulina Rodr\u00edguez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Durante dos meses y medio, habitantes de la calle Taiw\u00e1n, correspondiente a la colonia Sim\u00f3n D\u00edaz-El Aguaje reportaron la p\u00e9rdida de miles de litros de agua debido a una gran fuga, que corri\u00f3 por diferentes calles. Inicialmente Mar\u00eda Isabel Galv\u00e1n de la Cruz -quien vive en la zona- se\u00f1al\u00f3 que desde una p\u00e1gina, los vecinos emiten sus reportes. Se\u00f1al\u00f3 que mientras se garantizaba el suministro por la red, la impotencia se sent\u00eda, ya que en la parte afectada -librada por algunos automovilistas- el l\u00edquido se desperdiciaba. La gente que alert\u00f3 a la autoridad recibi\u00f3 dos folios, as\u00ed como se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-125946","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Durante dos meses y medio, habitantes de la calle Taiw\u00e1n, correspondiente a la colonia Sim\u00f3n D\u00edaz-El Aguaje reportaron la p\u00e9rdida de miles de litros de agua debido a una gran fuga, que corri\u00f3 por diferentes calles. Inicialmente Mar\u00eda Isabel Galv\u00e1n de la Cruz -quien vive en la zona- se\u00f1al\u00f3 que desde una p\u00e1gina, los vecinos emiten sus reportes. Se\u00f1al\u00f3 que mientras se garantizaba el suministro por la red, la impotencia se sent\u00eda, ya que en la parte afectada -librada por algunos automovilistas- el l\u00edquido se desperdiciaba. La gente que alert\u00f3 a la autoridad recibi\u00f3 dos folios, as\u00ed como se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-01T15:24:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Pau03FugaInterapas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n\",\"datePublished\":\"2024-04-01T15:24:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/\"},\"wordCount\":171,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Pau03FugaInterapas.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/\",\"name\":\"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Pau03FugaInterapas.jpg\",\"datePublished\":\"2024-04-01T15:24:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Pau03FugaInterapas.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Pau03FugaInterapas.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/","og_locale":"es_ES","og_type":"article","og_title":"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n - Canal 7 SLP - 2024","og_description":"SLP.- Durante dos meses y medio, habitantes de la calle Taiw\u00e1n, correspondiente a la colonia Sim\u00f3n D\u00edaz-El Aguaje reportaron la p\u00e9rdida de miles de litros de agua debido a una gran fuga, que corri\u00f3 por diferentes calles. Inicialmente Mar\u00eda Isabel Galv\u00e1n de la Cruz -quien vive en la zona- se\u00f1al\u00f3 que desde una p\u00e1gina, los vecinos emiten sus reportes. Se\u00f1al\u00f3 que mientras se garantizaba el suministro por la red, la impotencia se sent\u00eda, ya que en la parte afectada -librada por algunos automovilistas- el l\u00edquido se desperdiciaba. La gente que alert\u00f3 a la autoridad recibi\u00f3 dos folios, as\u00ed como se [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-04-01T15:24:28+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Pau03FugaInterapas.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n","datePublished":"2024-04-01T15:24:28+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/"},"wordCount":171,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Pau03FugaInterapas.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/","url":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/","name":"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Pau03FugaInterapas.jpg","datePublished":"2024-04-01T15:24:28+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Pau03FugaInterapas.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/04\/Pau03FugaInterapas.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/tras-meses-de-espera-interviene-interapas-en-gran-fuga-de-la-calle-taiwan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Tras meses de espera, interviene Interapas en gran fuga de la calle Taiw\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=125946"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125946\/revisions"}],"predecessor-version":[{"id":125948,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125946\/revisions\/125948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/125947"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=125946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=125946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=125946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}