{"id":125363,"date":"2024-03-26T14:05:05","date_gmt":"2024-03-26T20:05:05","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=125363"},"modified":"2024-03-26T14:05:05","modified_gmt":"2024-03-26T20:05:05","slug":"competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/","title":{"rendered":"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Con \u00e9xito se llev\u00f3 a cabo la Competencia de Ciclismo Infantil que tuvo como sede la Recreov\u00eda de Avenida Venustiano Carranza, tenido una participaci\u00f3n de 150 participantes e incluso se cont\u00f3 con ciclistas de estados vecinos como Zacatecas y el estado de Jalisco, lo que le dio gran competitividad al evento.<\/p>\n<p style=\"text-align: justify;\">En la categor\u00eda, \u201cPa\u00f1ales\u201d para menores de 4 a\u00f1os, el primer lugar correspondi\u00f3 a Carlos Gael L\u00f3pez Rojas, la segunda plaza fue para Javier Mu\u00f1iz L\u00f3pez, En esta categor\u00eda los peque\u00f1os ciclistas recorrieron un tramo de 200 metros.<\/p>\n<p style=\"text-align: justify;\">En la segunda categor\u00eda, de 5 a 6 a\u00f1os el primer lugar fue para Eder Quiroz, la segunda posici\u00f3n correspondi\u00f3 a Romina Salas. Esta categor\u00eda tuvo un recorrido de 600 metros.<\/p>\n<p style=\"text-align: justify;\">La tercera categor\u00eda fue la de 7-8 a\u00f1os con recorrido de 4 kil\u00f3metros que tuvo a V\u00edctor Guti\u00e9rrez como primer lugar, Alexis Gabriel Rocha entr\u00f3 en la segunda.<\/p>\n<p style=\"text-align: justify;\">En la categor\u00eda 9-10 a\u00f1os con un recorrido de 7 kil\u00f3metros el ganador fue Miguel Mart\u00ednez, la segunda plaza fue para Emmanuel Posada.<\/p>\n<p style=\"text-align: justify;\">En cuanto a la categor\u00eda 11-12 a\u00f1os con recorrido de 10 kil\u00f3metros, el ganador fue Leonardo Daniel Cruz, la segunda plaza fue para Diego Reyes.<\/p>\n<p>Finalmente, en la categor\u00eda 13-14 a\u00f1os a 12 kil\u00f3metros, el primer lugar varonil fue para Isa\u00edd Garc\u00eda, segundo lugar para Santiago Lucio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Con \u00e9xito se llev\u00f3 a cabo la Competencia de Ciclismo Infantil que tuvo como sede la Recreov\u00eda de Avenida Venustiano Carranza, tenido una participaci\u00f3n de 150 participantes e incluso se cont\u00f3 con ciclistas de estados vecinos como Zacatecas y el estado de Jalisco, lo que le dio gran competitividad al evento. En la categor\u00eda, \u201cPa\u00f1ales\u201d para menores de 4 a\u00f1os, el primer lugar correspondi\u00f3 a Carlos Gael L\u00f3pez Rojas, la segunda plaza fue para Javier Mu\u00f1iz L\u00f3pez, En esta categor\u00eda los peque\u00f1os ciclistas recorrieron un tramo de 200 metros. En la segunda categor\u00eda, de 5 a 6 a\u00f1os el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-125363","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Con \u00e9xito se llev\u00f3 a cabo la Competencia de Ciclismo Infantil que tuvo como sede la Recreov\u00eda de Avenida Venustiano Carranza, tenido una participaci\u00f3n de 150 participantes e incluso se cont\u00f3 con ciclistas de estados vecinos como Zacatecas y el estado de Jalisco, lo que le dio gran competitividad al evento. En la categor\u00eda, \u201cPa\u00f1ales\u201d para menores de 4 a\u00f1os, el primer lugar correspondi\u00f3 a Carlos Gael L\u00f3pez Rojas, la segunda plaza fue para Javier Mu\u00f1iz L\u00f3pez, En esta categor\u00eda los peque\u00f1os ciclistas recorrieron un tramo de 200 metros. En la segunda categor\u00eda, de 5 a 6 a\u00f1os el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T20:05:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Ciclismo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas\",\"datePublished\":\"2024-03-26T20:05:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Ciclismo-1.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/\",\"name\":\"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Ciclismo-1.jpg\",\"datePublished\":\"2024-03-26T20:05:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Ciclismo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Ciclismo-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/","og_locale":"es_ES","og_type":"article","og_title":"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas - Canal 7 SLP - 2024","og_description":"SLP.- Con \u00e9xito se llev\u00f3 a cabo la Competencia de Ciclismo Infantil que tuvo como sede la Recreov\u00eda de Avenida Venustiano Carranza, tenido una participaci\u00f3n de 150 participantes e incluso se cont\u00f3 con ciclistas de estados vecinos como Zacatecas y el estado de Jalisco, lo que le dio gran competitividad al evento. En la categor\u00eda, \u201cPa\u00f1ales\u201d para menores de 4 a\u00f1os, el primer lugar correspondi\u00f3 a Carlos Gael L\u00f3pez Rojas, la segunda plaza fue para Javier Mu\u00f1iz L\u00f3pez, En esta categor\u00eda los peque\u00f1os ciclistas recorrieron un tramo de 200 metros. En la segunda categor\u00eda, de 5 a 6 a\u00f1os el [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-26T20:05:05+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Ciclismo-1.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas","datePublished":"2024-03-26T20:05:05+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/"},"wordCount":252,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Ciclismo-1.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/","url":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/","name":"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Ciclismo-1.jpg","datePublished":"2024-03-26T20:05:05+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Ciclismo-1.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Ciclismo-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/competencia-municipal-de-ciclismo-infantil-albergo-a-mas-de-150-ciclistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Competencia Municipal de Ciclismo Infantil alberg\u00f3 a m\u00e1s de 150 ciclistas"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=125363"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125363\/revisions"}],"predecessor-version":[{"id":125377,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125363\/revisions\/125377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/125376"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=125363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=125363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=125363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}