{"id":125344,"date":"2024-03-26T08:51:39","date_gmt":"2024-03-26T14:51:39","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=125344"},"modified":"2024-03-26T08:51:39","modified_gmt":"2024-03-26T14:51:39","slug":"medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/","title":{"rendered":"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0La transici\u00f3n del esquema de barandilla al Modelo Homologado de Justicia C\u00edvica (MHJC) en la capital, ha tenido las audiencias p\u00fablicas como pilar.<\/p>\n<p style=\"text-align: justify;\">La subdirectora de Servicios M\u00e9dicos, Psicosociales y Administrativos, Anah\u00ed Pavlova Galv\u00e1n Padr\u00f3n destac\u00f3 la habilitaci\u00f3n de dos salas -juzgados c\u00edvicos donde diferentes audiencias pueden efectuarse simult\u00e1neamente-.<\/p>\n<p style=\"text-align: justify;\">Detall\u00f3 que parte del procedimiento contempla tamizaje -una evaluaci\u00f3n para determinar factores de riesgo, que llegar\u00e1 al juez para la toma de decisiones-.<\/p>\n<p style=\"text-align: justify;\">La subdirectora, a la par se refiri\u00f3 a los procedimientos de mediaci\u00f3n, e hizo \u00e9nfasis en la canalizaci\u00f3n de medidas terap\u00e9uticas; adem\u00e1s del dise\u00f1o de un nuevo Bando de Polic\u00eda y Gobierno.<\/p>\n<p style=\"text-align: justify;\">Por: Paulina Rodr\u00edguez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0La transici\u00f3n del esquema de barandilla al Modelo Homologado de Justicia C\u00edvica (MHJC) en la capital, ha tenido las audiencias p\u00fablicas como pilar. La subdirectora de Servicios M\u00e9dicos, Psicosociales y Administrativos, Anah\u00ed Pavlova Galv\u00e1n Padr\u00f3n destac\u00f3 la habilitaci\u00f3n de dos salas -juzgados c\u00edvicos donde diferentes audiencias pueden efectuarse simult\u00e1neamente-. Detall\u00f3 que parte del procedimiento contempla tamizaje -una evaluaci\u00f3n para determinar factores de riesgo, que llegar\u00e1 al juez para la toma de decisiones-. La subdirectora, a la par se refiri\u00f3 a los procedimientos de mediaci\u00f3n, e hizo \u00e9nfasis en la canalizaci\u00f3n de medidas terap\u00e9uticas; adem\u00e1s del dise\u00f1o de un nuevo Bando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[66,5,45],"tags":[],"class_list":["post-125344","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayoslp","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0La transici\u00f3n del esquema de barandilla al Modelo Homologado de Justicia C\u00edvica (MHJC) en la capital, ha tenido las audiencias p\u00fablicas como pilar. La subdirectora de Servicios M\u00e9dicos, Psicosociales y Administrativos, Anah\u00ed Pavlova Galv\u00e1n Padr\u00f3n destac\u00f3 la habilitaci\u00f3n de dos salas -juzgados c\u00edvicos donde diferentes audiencias pueden efectuarse simult\u00e1neamente-. Detall\u00f3 que parte del procedimiento contempla tamizaje -una evaluaci\u00f3n para determinar factores de riesgo, que llegar\u00e1 al juez para la toma de decisiones-. La subdirectora, a la par se refiri\u00f3 a los procedimientos de mediaci\u00f3n, e hizo \u00e9nfasis en la canalizaci\u00f3n de medidas terap\u00e9uticas; adem\u00e1s del dise\u00f1o de un nuevo Bando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T14:51:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Pau02JusticiaCivica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica\",\"datePublished\":\"2024-03-26T14:51:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/\"},\"wordCount\":146,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pau02JusticiaCivica.jpg\",\"articleSection\":[\"AYOSLP\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/\",\"name\":\"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pau02JusticiaCivica.jpg\",\"datePublished\":\"2024-03-26T14:51:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pau02JusticiaCivica.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Pau02JusticiaCivica.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/","og_locale":"es_ES","og_type":"article","og_title":"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica - Canal 7 SLP - 2024","og_description":"SLP.-\u00a0La transici\u00f3n del esquema de barandilla al Modelo Homologado de Justicia C\u00edvica (MHJC) en la capital, ha tenido las audiencias p\u00fablicas como pilar. La subdirectora de Servicios M\u00e9dicos, Psicosociales y Administrativos, Anah\u00ed Pavlova Galv\u00e1n Padr\u00f3n destac\u00f3 la habilitaci\u00f3n de dos salas -juzgados c\u00edvicos donde diferentes audiencias pueden efectuarse simult\u00e1neamente-. Detall\u00f3 que parte del procedimiento contempla tamizaje -una evaluaci\u00f3n para determinar factores de riesgo, que llegar\u00e1 al juez para la toma de decisiones-. La subdirectora, a la par se refiri\u00f3 a los procedimientos de mediaci\u00f3n, e hizo \u00e9nfasis en la canalizaci\u00f3n de medidas terap\u00e9uticas; adem\u00e1s del dise\u00f1o de un nuevo Bando [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-26T14:51:39+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Pau02JusticiaCivica.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica","datePublished":"2024-03-26T14:51:39+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/"},"wordCount":146,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Pau02JusticiaCivica.jpg","articleSection":["AYOSLP","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/","url":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/","name":"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Pau02JusticiaCivica.jpg","datePublished":"2024-03-26T14:51:39+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Pau02JusticiaCivica.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Pau02JusticiaCivica.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/medidas-terapeuticas-y-nuevo-bando-de-policia-y-gobierno-destacan-autoridades-del-modelo-homologado-de-justicia-civica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Medidas terap\u00e9uticas y nuevo Bando de Polic\u00eda y Gobierno; destacan autoridades del Modelo Homologado de Justicia C\u00edvica"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=125344"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125344\/revisions"}],"predecessor-version":[{"id":125347,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125344\/revisions\/125347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/125345"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=125344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=125344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=125344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}