{"id":125210,"date":"2024-03-25T14:23:14","date_gmt":"2024-03-25T20:23:14","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=125210"},"modified":"2024-03-25T14:23:14","modified_gmt":"2024-03-25T20:23:14","slug":"atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/","title":{"rendered":"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- En la jornada 12 de la Liga MX, las de Atl\u00e9tico de San Luis le hicieron la visita al Am\u00e9rica siendo estas \u00faltimas quienes se quedaban con los puntos.<\/p>\n<p style=\"text-align: justify;\">Las acciones comenzaron al minuto 11 con una veloz Trudi Carter defini\u00f3 y anoto el primero del compromiso y as\u00ed adelantar a las potosinas,<\/p>\n<p style=\"text-align: justify;\">Las azulcremas tomaron acci\u00f3n y al minuto 18 lograran el empate fue a trav\u00e9s de Monse Sald\u00edvar, en un error, justamente de Nicole Buenfil, a quien se le escurri\u00f3 el bal\u00f3n para posteriormente conectarla al fondo de las redes<\/p>\n<p style=\"text-align: justify;\">Ya con un total dominio el Am\u00e9rica al 29\u2019 le dieron la voltereta al marcador con un contrarremate en el \u00e1rea chica por parte de Jocelyn Orejel.<\/p>\n<p style=\"text-align: justify;\">En la parte complementaria las potosinas se plantaron bien en el terreno de juego y echaron mano de la arquera Buenfil que se mantuvo en plan grande deteniendo los embates azulcremas, factor para que culminara con el 2-1.<\/p>\n<p style=\"text-align: justify;\">Con el triunfo de 2-1, Am\u00e9rica lleg\u00f3 a 25 puntos ubic\u00e1ndose en el tercer lugar, mientras que San Luis sum\u00f3 su novena derrota del torneo y se hundi\u00f3 en el pen\u00faltimo lugar de la clasificaci\u00f3n general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- En la jornada 12 de la Liga MX, las de Atl\u00e9tico de San Luis le hicieron la visita al Am\u00e9rica siendo estas \u00faltimas quienes se quedaban con los puntos. Las acciones comenzaron al minuto 11 con una veloz Trudi Carter defini\u00f3 y anoto el primero del compromiso y as\u00ed adelantar a las potosinas, Las azulcremas tomaron acci\u00f3n y al minuto 18 lograran el empate fue a trav\u00e9s de Monse Sald\u00edvar, en un error, justamente de Nicole Buenfil, a quien se le escurri\u00f3 el bal\u00f3n para posteriormente conectarla al fondo de las redes Ya con un total dominio el Am\u00e9rica [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-125210","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- En la jornada 12 de la Liga MX, las de Atl\u00e9tico de San Luis le hicieron la visita al Am\u00e9rica siendo estas \u00faltimas quienes se quedaban con los puntos. Las acciones comenzaron al minuto 11 con una veloz Trudi Carter defini\u00f3 y anoto el primero del compromiso y as\u00ed adelantar a las potosinas, Las azulcremas tomaron acci\u00f3n y al minuto 18 lograran el empate fue a trav\u00e9s de Monse Sald\u00edvar, en un error, justamente de Nicole Buenfil, a quien se le escurri\u00f3 el bal\u00f3n para posteriormente conectarla al fondo de las redes Ya con un total dominio el Am\u00e9rica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T20:23:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi01AtleticoFem-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica\",\"datePublished\":\"2024-03-25T20:23:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/\"},\"wordCount\":218,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi01AtleticoFem-1.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/\",\"name\":\"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi01AtleticoFem-1.jpg\",\"datePublished\":\"2024-03-25T20:23:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi01AtleticoFem-1.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi01AtleticoFem-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/","og_locale":"es_ES","og_type":"article","og_title":"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica - Canal 7 SLP - 2024","og_description":"SLP.- En la jornada 12 de la Liga MX, las de Atl\u00e9tico de San Luis le hicieron la visita al Am\u00e9rica siendo estas \u00faltimas quienes se quedaban con los puntos. Las acciones comenzaron al minuto 11 con una veloz Trudi Carter defini\u00f3 y anoto el primero del compromiso y as\u00ed adelantar a las potosinas, Las azulcremas tomaron acci\u00f3n y al minuto 18 lograran el empate fue a trav\u00e9s de Monse Sald\u00edvar, en un error, justamente de Nicole Buenfil, a quien se le escurri\u00f3 el bal\u00f3n para posteriormente conectarla al fondo de las redes Ya con un total dominio el Am\u00e9rica [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-25T20:23:14+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi01AtleticoFem-1.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica","datePublished":"2024-03-25T20:23:14+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/"},"wordCount":218,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi01AtleticoFem-1.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/","url":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/","name":"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi01AtleticoFem-1.jpg","datePublished":"2024-03-25T20:23:14+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi01AtleticoFem-1.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi01AtleticoFem-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/atletico-de-san-luis-femenil-no-logra-conseguir-el-triunfo-cae-2-a-1-ante-el-america\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Atl\u00e9tico de San Luis Femenil no logra conseguir el triunfo cae 2 a 1 ante el Am\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=125210"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125210\/revisions"}],"predecessor-version":[{"id":125220,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/125210\/revisions\/125220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/125219"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=125210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=125210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=125210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}