{"id":123707,"date":"2024-03-11T14:11:26","date_gmt":"2024-03-11T20:11:26","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=123707"},"modified":"2024-03-11T14:11:26","modified_gmt":"2024-03-11T20:11:26","slug":"inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/","title":{"rendered":"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Las \u00c1guilas de la UASLP, inicio su participaci\u00f3n en el nuevo torneo de la Liga Potos\u00ed de Baloncesto, al vencer con marcador de 27 puntos a 20, a la quinteta del Colegio de Bachilleres No. 26.<\/p>\n<p style=\"text-align: justify;\">El partido tuvo lugar en las instalaciones del CEDETAR, en donde las universitarias se tuvieron que emplear a fondo para lograr la primera victoria de esta nueva temporada.<\/p>\n<p style=\"text-align: justify;\">El conjunto de las \u00c1guilas de la UASLP le gan\u00f3 un buen partido al Cobach 26, con cartones de 27 puntos a 20, indicativo que el partido estuvo cerrado y muy disputado, pero al final, el cuadro de la UASLP obtuvo un triunfo importante.<\/p>\n<p style=\"text-align: justify;\">En este partido las mejores anotadoras de la UASLP fueron Nahom\u00ed Vigil con 11 unidades, Sof\u00eda Facundo con 5, Fernanda Ochoa con 4, Isabel Moreno con 3, Karina Mart\u00ednez y Adriana Huerta con 2 puntos cada una.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Las \u00c1guilas de la UASLP, inicio su participaci\u00f3n en el nuevo torneo de la Liga Potos\u00ed de Baloncesto, al vencer con marcador de 27 puntos a 20, a la quinteta del Colegio de Bachilleres No. 26. El partido tuvo lugar en las instalaciones del CEDETAR, en donde las universitarias se tuvieron que emplear a fondo para lograr la primera victoria de esta nueva temporada. El conjunto de las \u00c1guilas de la UASLP le gan\u00f3 un buen partido al Cobach 26, con cartones de 27 puntos a 20, indicativo que el partido estuvo cerrado y muy disputado, pero al final, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":123714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-123707","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Las \u00c1guilas de la UASLP, inicio su participaci\u00f3n en el nuevo torneo de la Liga Potos\u00ed de Baloncesto, al vencer con marcador de 27 puntos a 20, a la quinteta del Colegio de Bachilleres No. 26. El partido tuvo lugar en las instalaciones del CEDETAR, en donde las universitarias se tuvieron que emplear a fondo para lograr la primera victoria de esta nueva temporada. El conjunto de las \u00c1guilas de la UASLP le gan\u00f3 un buen partido al Cobach 26, con cartones de 27 puntos a 20, indicativo que el partido estuvo cerrado y muy disputado, pero al final, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-11T20:11:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi02Basquet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto\",\"datePublished\":\"2024-03-11T20:11:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/\"},\"wordCount\":153,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi02Basquet.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/\",\"name\":\"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi02Basquet.jpg\",\"datePublished\":\"2024-03-11T20:11:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi02Basquet.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi02Basquet.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/","og_locale":"es_ES","og_type":"article","og_title":"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto - Canal 7 SLP - 2024","og_description":"SLP.- Las \u00c1guilas de la UASLP, inicio su participaci\u00f3n en el nuevo torneo de la Liga Potos\u00ed de Baloncesto, al vencer con marcador de 27 puntos a 20, a la quinteta del Colegio de Bachilleres No. 26. El partido tuvo lugar en las instalaciones del CEDETAR, en donde las universitarias se tuvieron que emplear a fondo para lograr la primera victoria de esta nueva temporada. El conjunto de las \u00c1guilas de la UASLP le gan\u00f3 un buen partido al Cobach 26, con cartones de 27 puntos a 20, indicativo que el partido estuvo cerrado y muy disputado, pero al final, [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-11T20:11:26+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi02Basquet.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto","datePublished":"2024-03-11T20:11:26+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/"},"wordCount":153,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi02Basquet.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/","url":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/","name":"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi02Basquet.jpg","datePublished":"2024-03-11T20:11:26+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi02Basquet.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi02Basquet.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/inician-las-aguilas-de-basquetbol-femenil-con-triunfo-en-la-liga-potosi-de-baloncesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Inician las \u00c1guilas de Basquetbol Femenil con triunfo en la Liga Potos\u00ed de Baloncesto"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=123707"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123707\/revisions"}],"predecessor-version":[{"id":123715,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123707\/revisions\/123715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/123714"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=123707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=123707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=123707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}