{"id":123236,"date":"2024-03-06T14:35:22","date_gmt":"2024-03-06T20:35:22","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=123236"},"modified":"2024-03-06T14:35:22","modified_gmt":"2024-03-06T20:35:22","slug":"capacitan-a-entrenadores-para-juegos-deportivos-nacionales","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/","title":{"rendered":"Capacitan a entrenadores para Juegos Deportivos Nacionales"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Se capacit\u00f3 a 140 entrenadores de las y los atletas potosinos que representar\u00e1n a San Luis Potos\u00ed en los pr\u00f3ximos Juegos Nacionales de la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte, como parte de los lineamientos de esta competencia que se realizar\u00e1 a mediados de 2024 en Jalisco, Campeche, Colima y Ciudad de M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">El curso se imparti\u00f3 en dos jornadas en las instalaciones del auditorio Miguel Barrag\u00e1n, con un total de 140 entrenadores, de los cuales 80 lo hicieron de manera presencial, en tanto que 60 de manera virtual, una modalidad que permiti\u00f3 la participaci\u00f3n de entrenadores de distintos puntos del Estado.<\/p>\n<p style=\"text-align: justify;\">Las y los participantes, abordaron dos m\u00f3dulos, el primero, denominado Metodolog\u00eda del Entrenamiento en Ciencias Aplicadas al Deporte y el segundo, correspondi\u00f3 a los temas de Normatividad y Gesti\u00f3n Deportiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Se capacit\u00f3 a 140 entrenadores de las y los atletas potosinos que representar\u00e1n a San Luis Potos\u00ed en los pr\u00f3ximos Juegos Nacionales de la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte, como parte de los lineamientos de esta competencia que se realizar\u00e1 a mediados de 2024 en Jalisco, Campeche, Colima y Ciudad de M\u00e9xico. El curso se imparti\u00f3 en dos jornadas en las instalaciones del auditorio Miguel Barrag\u00e1n, con un total de 140 entrenadores, de los cuales 80 lo hicieron de manera presencial, en tanto que 60 de manera virtual, una modalidad que permiti\u00f3 la participaci\u00f3n de entrenadores de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":123245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-123236","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacitan a entrenadores para Juegos Deportivos Nacionales - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacitan a entrenadores para Juegos Deportivos Nacionales - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Se capacit\u00f3 a 140 entrenadores de las y los atletas potosinos que representar\u00e1n a San Luis Potos\u00ed en los pr\u00f3ximos Juegos Nacionales de la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte, como parte de los lineamientos de esta competencia que se realizar\u00e1 a mediados de 2024 en Jalisco, Campeche, Colima y Ciudad de M\u00e9xico. El curso se imparti\u00f3 en dos jornadas en las instalaciones del auditorio Miguel Barrag\u00e1n, con un total de 140 entrenadores, de los cuales 80 lo hicieron de manera presencial, en tanto que 60 de manera virtual, una modalidad que permiti\u00f3 la participaci\u00f3n de entrenadores de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T20:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Nacionales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Capacitan a entrenadores para Juegos Deportivos Nacionales\",\"datePublished\":\"2024-03-06T20:35:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Nacionales.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/\",\"name\":\"Capacitan a entrenadores para Juegos Deportivos Nacionales - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Nacionales.jpg\",\"datePublished\":\"2024-03-06T20:35:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Nacionales.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Froi03Nacionales.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacitan a entrenadores para Juegos Deportivos Nacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacitan a entrenadores para Juegos Deportivos Nacionales - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/","og_locale":"es_ES","og_type":"article","og_title":"Capacitan a entrenadores para Juegos Deportivos Nacionales - Canal 7 SLP - 2024","og_description":"SLP.- Se capacit\u00f3 a 140 entrenadores de las y los atletas potosinos que representar\u00e1n a San Luis Potos\u00ed en los pr\u00f3ximos Juegos Nacionales de la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte, como parte de los lineamientos de esta competencia que se realizar\u00e1 a mediados de 2024 en Jalisco, Campeche, Colima y Ciudad de M\u00e9xico. El curso se imparti\u00f3 en dos jornadas en las instalaciones del auditorio Miguel Barrag\u00e1n, con un total de 140 entrenadores, de los cuales 80 lo hicieron de manera presencial, en tanto que 60 de manera virtual, una modalidad que permiti\u00f3 la participaci\u00f3n de entrenadores de [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-06T20:35:22+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Nacionales.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Capacitan a entrenadores para Juegos Deportivos Nacionales","datePublished":"2024-03-06T20:35:22+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/"},"wordCount":147,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Nacionales.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/","url":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/","name":"Capacitan a entrenadores para Juegos Deportivos Nacionales - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Nacionales.jpg","datePublished":"2024-03-06T20:35:22+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Nacionales.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/Froi03Nacionales.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/capacitan-a-entrenadores-para-juegos-deportivos-nacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Capacitan a entrenadores para Juegos Deportivos Nacionales"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=123236"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123236\/revisions"}],"predecessor-version":[{"id":123246,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123236\/revisions\/123246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/123245"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=123236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=123236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=123236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}