{"id":123125,"date":"2024-03-05T15:20:14","date_gmt":"2024-03-05T21:20:14","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=123125"},"modified":"2024-03-05T17:29:58","modified_gmt":"2024-03-05T23:29:58","slug":"persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/","title":{"rendered":"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- La Junta Internacional de Fiscalizaci\u00f3n de Estupefacientes (JIFE) emiti\u00f3 un informe anual que resalta la continuaci\u00f3n de altos niveles de violencia en M\u00e9xico, principalmente relacionados con la actividad delictiva de c\u00e1rteles y bandas vinculadas al tr\u00e1fico y producci\u00f3n de drogas.<\/p>\n<p style=\"text-align: justify;\">A pesar de una ligera disminuci\u00f3n en los homicidios en el pa\u00eds, la tasa de v\u00edctimas sigue siendo una de las m\u00e1s altas a nivel mundial. La fabricaci\u00f3n y tr\u00e1fico ilegal de drogas por estos grupos criminales contin\u00faa siendo un factor determinante en la persistencia de la violencia en M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">El informe tambi\u00e9n destaca la crisis de opioides en Am\u00e9rica del Norte, con graves consecuencias en pa\u00edses como Estados Unidos, donde las muertes por intoxicaci\u00f3n relacionadas con fentanilo y otras drogas sint\u00e9ticas siguen aumentando.<\/p>\n<p style=\"text-align: justify;\">Ante esta situaci\u00f3n, Estados Unidos ha puesto en marcha la Coalici\u00f3n Global para Abordar las Amenazas de las Drogas Sint\u00e9ticas, con el objetivo de combatir el tr\u00e1fico il\u00edcito y prevenir los riesgos asociados con estas sustancias.<\/p>\n<p style=\"text-align: justify;\">En el caso espec\u00edfico de M\u00e9xico, la JIFE se\u00f1al\u00f3 un preocupante aumento en la demanda de tratamiento por consumo de metanfetaminas, pasando de seis estados en 2017 a 21 en 2022.<\/p>\n<p style=\"text-align: justify;\">Esta tendencia refleja una transici\u00f3n epidemiol\u00f3gica en el pa\u00eds y un incremento significativo en los ingresos a tratamiento por consumo de estas sustancias.<\/p>\n<p style=\"text-align: justify;\">El consumo de metanfetaminas, \u00e9xtasis y estimulantes ha aumentado un 218% entre los a\u00f1os mencionados, representando m\u00e1s del 46% de las solicitudes de tratamiento en 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- La Junta Internacional de Fiscalizaci\u00f3n de Estupefacientes (JIFE) emiti\u00f3 un informe anual que resalta la continuaci\u00f3n de altos niveles de violencia en M\u00e9xico, principalmente relacionados con la actividad delictiva de c\u00e1rteles y bandas vinculadas al tr\u00e1fico y producci\u00f3n de drogas. A pesar de una ligera disminuci\u00f3n en los homicidios en el pa\u00eds, la tasa de v\u00edctimas sigue siendo una de las m\u00e1s altas a nivel mundial. La fabricaci\u00f3n y tr\u00e1fico ilegal de drogas por estos grupos criminales contin\u00faa siendo un factor determinante en la persistencia de la violencia en M\u00e9xico. El informe tambi\u00e9n destaca la crisis de opioides en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":123138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-123125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- La Junta Internacional de Fiscalizaci\u00f3n de Estupefacientes (JIFE) emiti\u00f3 un informe anual que resalta la continuaci\u00f3n de altos niveles de violencia en M\u00e9xico, principalmente relacionados con la actividad delictiva de c\u00e1rteles y bandas vinculadas al tr\u00e1fico y producci\u00f3n de drogas. A pesar de una ligera disminuci\u00f3n en los homicidios en el pa\u00eds, la tasa de v\u00edctimas sigue siendo una de las m\u00e1s altas a nivel mundial. La fabricaci\u00f3n y tr\u00e1fico ilegal de drogas por estos grupos criminales contin\u00faa siendo un factor determinante en la persistencia de la violencia en M\u00e9xico. El informe tambi\u00e9n destaca la crisis de opioides en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T21:20:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T23:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"902\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE\",\"datePublished\":\"2024-03-05T21:20:14+00:00\",\"dateModified\":\"2024-03-05T23:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05-4.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/\",\"name\":\"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05-4.jpg\",\"datePublished\":\"2024-03-05T21:20:14+00:00\",\"dateModified\":\"2024-03-05T23:29:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05-4.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05-4.jpg\",\"width\":1200,\"height\":902},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/","og_locale":"es_ES","og_type":"article","og_title":"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- La Junta Internacional de Fiscalizaci\u00f3n de Estupefacientes (JIFE) emiti\u00f3 un informe anual que resalta la continuaci\u00f3n de altos niveles de violencia en M\u00e9xico, principalmente relacionados con la actividad delictiva de c\u00e1rteles y bandas vinculadas al tr\u00e1fico y producci\u00f3n de drogas. A pesar de una ligera disminuci\u00f3n en los homicidios en el pa\u00eds, la tasa de v\u00edctimas sigue siendo una de las m\u00e1s altas a nivel mundial. La fabricaci\u00f3n y tr\u00e1fico ilegal de drogas por estos grupos criminales contin\u00faa siendo un factor determinante en la persistencia de la violencia en M\u00e9xico. El informe tambi\u00e9n destaca la crisis de opioides en [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-05T21:20:14+00:00","article_modified_time":"2024-03-05T23:29:58+00:00","og_image":[{"width":1200,"height":902,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05-4.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE","datePublished":"2024-03-05T21:20:14+00:00","dateModified":"2024-03-05T23:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/"},"wordCount":283,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05-4.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/","url":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/","name":"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05-4.jpg","datePublished":"2024-03-05T21:20:14+00:00","dateModified":"2024-03-05T23:29:58+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05-4.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05-4.jpg","width":1200,"height":902},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/persiste-en-mexico-amenaza-de-actividad-de-carteles-y-bandas-delictivas-jife\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Persiste en M\u00e9xico amenaza de actividad de c\u00e1rteles y bandas delictivas: JIFE"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=123125"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123125\/revisions"}],"predecessor-version":[{"id":123182,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/123125\/revisions\/123182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/123138"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=123125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=123125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=123125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}