{"id":122806,"date":"2024-03-01T17:25:02","date_gmt":"2024-03-01T23:25:02","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=122806"},"modified":"2024-03-01T17:25:02","modified_gmt":"2024-03-01T23:25:02","slug":"valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/","title":{"rendered":"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- El Instituto Nacional Electoral (INE) ha aprobado oficialmente las candidaturas de Claudia Sheinbaum, X\u00f3chitl G\u00e1lvez y Jorge \u00c1lvarez M\u00e1ynez para la Presidencia de la Rep\u00fablica, marcando as\u00ed el inicio formal de la competencia hacia las elecciones federales de 2024.<\/p>\n<p style=\"text-align: justify;\">Estos candidatos, representantes de las coaliciones Sigamos Haciendo Historia, Fuerza y Coraz\u00f3n por M\u00e9xico, y del partido Movimiento Ciudadano, han recibido el visto bueno para comenzar sus campa\u00f1as pol\u00edticas a partir del 1\u00ba de marzo de 2024, seg\u00fan lo establecido en el calendario electoral.<\/p>\n<p style=\"text-align: justify;\">La sesi\u00f3n del INE celebrada el jueves 29 de febrero concluy\u00f3 con la ratificaci\u00f3n de que los tres aspirantes cumplen con todos los requisitos legales y de la convocatoria para participar en el proceso electoral.<\/p>\n<p style=\"text-align: justify;\">La consejera presidenta Guadalupe Taddei resalt\u00f3 la relevancia de este paso, que permite a Sheinbaum, G\u00e1lvez y \u00c1lvarez M\u00e1ynez competir por la sucesi\u00f3n del actual presidente Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO).<\/p>\n<p style=\"text-align: justify;\">Esta aprobaci\u00f3n por parte del INE formaliza la contienda presidencial en su papel de \u00e1rbitro electoral, fomentando la transparencia y cumpliendo con la ley. Los candidatos se preparan para presentar sus propuestas a la ciudadan\u00eda mexicana, buscando liderar el pa\u00eds en el pr\u00f3ximo periodo presidencial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- El Instituto Nacional Electoral (INE) ha aprobado oficialmente las candidaturas de Claudia Sheinbaum, X\u00f3chitl G\u00e1lvez y Jorge \u00c1lvarez M\u00e1ynez para la Presidencia de la Rep\u00fablica, marcando as\u00ed el inicio formal de la competencia hacia las elecciones federales de 2024. Estos candidatos, representantes de las coaliciones Sigamos Haciendo Historia, Fuerza y Coraz\u00f3n por M\u00e9xico, y del partido Movimiento Ciudadano, han recibido el visto bueno para comenzar sus campa\u00f1as pol\u00edticas a partir del 1\u00ba de marzo de 2024, seg\u00fan lo establecido en el calendario electoral. La sesi\u00f3n del INE celebrada el jueves 29 de febrero concluy\u00f3 con la ratificaci\u00f3n de que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":122821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-122806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- El Instituto Nacional Electoral (INE) ha aprobado oficialmente las candidaturas de Claudia Sheinbaum, X\u00f3chitl G\u00e1lvez y Jorge \u00c1lvarez M\u00e1ynez para la Presidencia de la Rep\u00fablica, marcando as\u00ed el inicio formal de la competencia hacia las elecciones federales de 2024. Estos candidatos, representantes de las coaliciones Sigamos Haciendo Historia, Fuerza y Coraz\u00f3n por M\u00e9xico, y del partido Movimiento Ciudadano, han recibido el visto bueno para comenzar sus campa\u00f1as pol\u00edticas a partir del 1\u00ba de marzo de 2024, seg\u00fan lo establecido en el calendario electoral. La sesi\u00f3n del INE celebrada el jueves 29 de febrero concluy\u00f3 con la ratificaci\u00f3n de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T23:25:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as\",\"datePublished\":\"2024-03-01T23:25:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/\"},\"wordCount\":226,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/\",\"name\":\"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05.jpg\",\"datePublished\":\"2024-03-01T23:25:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/05.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/","og_locale":"es_ES","og_type":"article","og_title":"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- El Instituto Nacional Electoral (INE) ha aprobado oficialmente las candidaturas de Claudia Sheinbaum, X\u00f3chitl G\u00e1lvez y Jorge \u00c1lvarez M\u00e1ynez para la Presidencia de la Rep\u00fablica, marcando as\u00ed el inicio formal de la competencia hacia las elecciones federales de 2024. Estos candidatos, representantes de las coaliciones Sigamos Haciendo Historia, Fuerza y Coraz\u00f3n por M\u00e9xico, y del partido Movimiento Ciudadano, han recibido el visto bueno para comenzar sus campa\u00f1as pol\u00edticas a partir del 1\u00ba de marzo de 2024, seg\u00fan lo establecido en el calendario electoral. La sesi\u00f3n del INE celebrada el jueves 29 de febrero concluy\u00f3 con la ratificaci\u00f3n de que [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-03-01T23:25:02+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as","datePublished":"2024-03-01T23:25:02+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/"},"wordCount":226,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/","url":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/","name":"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05.jpg","datePublished":"2024-03-01T23:25:02+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/03\/05.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/valida-ine-candidaturas-presidenciales-y-da-luz-verde-a-inicio-de-campanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Valida INE candidaturas presidenciales y da luz verde a inicio de campa\u00f1as"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/122806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=122806"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/122806\/revisions"}],"predecessor-version":[{"id":122861,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/122806\/revisions\/122861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/122821"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=122806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=122806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=122806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}