{"id":119190,"date":"2024-01-22T18:30:55","date_gmt":"2024-01-23T00:30:55","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=119190"},"modified":"2024-01-22T18:30:55","modified_gmt":"2024-01-23T00:30:55","slug":"mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/","title":{"rendered":"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- M\u00e9xico ha notificado a Estados Unidos sobre la presencia de armas de uso exclusivo militar estadounidense en el pa\u00eds, solicitando una investigaci\u00f3n al respecto.<\/p>\n<p style=\"text-align: justify;\">La Secretar\u00eda de Relaciones Exteriores (SRE) mexicana, a trav\u00e9s de Alicia B\u00e1rcena, enfatiz\u00f3 la urgencia de esta investigaci\u00f3n, sin proporcionar detalles espec\u00edficos sobre la cantidad o el momento de ingreso de las armas.<\/p>\n<p style=\"text-align: justify;\">Cabe recordar que en junio, la Secretar\u00eda de la Defensa (SEDENA) inform\u00f3 sobre la incautaci\u00f3n de 221 ametralladoras totalmente autom\u00e1ticas, 56 lanzagranadas y una docena de lanzacohetes pertenecientes a c\u00e1rteles de la droga desde finales de 2018.<\/p>\n<p style=\"text-align: justify;\">El uso p\u00fablico de este armamento estadounidense de grado militar por parte de los c\u00e1rteles representa un desaf\u00edo significativo para las fuerzas armadas mexicanas.<\/p>\n<p style=\"text-align: justify;\">Es importante mencionar que durante una reuni\u00f3n de alto nivel entre ambas administraciones, que se centr\u00f3 en temas de migraci\u00f3n y fue continuaci\u00f3n de una reuni\u00f3n anterior en diciembre en Ciudad de M\u00e9xico, funcionarios estadounidenses informaron a M\u00e9xico sobre su intenci\u00f3n de sancionar a empresas sudamericanas, centroamericanas y posiblemente mexicanas que transporten migrantes en situaci\u00f3n irregular.<\/p>\n<p style=\"text-align: justify;\">En respuesta, M\u00e9xico solicit\u00f3 que no se actuara unilateralmente y propuso citar a las empresas mexicanas, camioneros y l\u00edneas a\u00e9reas para abordar el tema.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, M\u00e9xico solicit\u00f3 la posibilidad de extender el uso de la aplicaci\u00f3n CBPOne, que permite a muchos migrantes solicitar una cita con autoridades estadounidenses para migrar legalmente, desde el sur del pa\u00eds y no solo desde la capital o la mitad norte de M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- M\u00e9xico ha notificado a Estados Unidos sobre la presencia de armas de uso exclusivo militar estadounidense en el pa\u00eds, solicitando una investigaci\u00f3n al respecto. La Secretar\u00eda de Relaciones Exteriores (SRE) mexicana, a trav\u00e9s de Alicia B\u00e1rcena, enfatiz\u00f3 la urgencia de esta investigaci\u00f3n, sin proporcionar detalles espec\u00edficos sobre la cantidad o el momento de ingreso de las armas. Cabe recordar que en junio, la Secretar\u00eda de la Defensa (SEDENA) inform\u00f3 sobre la incautaci\u00f3n de 221 ametralladoras totalmente autom\u00e1ticas, 56 lanzagranadas y una docena de lanzacohetes pertenecientes a c\u00e1rteles de la droga desde finales de 2018. El uso p\u00fablico de este [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":119237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-119190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- M\u00e9xico ha notificado a Estados Unidos sobre la presencia de armas de uso exclusivo militar estadounidense en el pa\u00eds, solicitando una investigaci\u00f3n al respecto. La Secretar\u00eda de Relaciones Exteriores (SRE) mexicana, a trav\u00e9s de Alicia B\u00e1rcena, enfatiz\u00f3 la urgencia de esta investigaci\u00f3n, sin proporcionar detalles espec\u00edficos sobre la cantidad o el momento de ingreso de las armas. Cabe recordar que en junio, la Secretar\u00eda de la Defensa (SEDENA) inform\u00f3 sobre la incautaci\u00f3n de 221 ametralladoras totalmente autom\u00e1ticas, 56 lanzagranadas y una docena de lanzacohetes pertenecientes a c\u00e1rteles de la droga desde finales de 2018. El uso p\u00fablico de este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T00:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/01-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles\",\"datePublished\":\"2024-01-23T00:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/\"},\"wordCount\":289,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/01-16.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/\",\"name\":\"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/01-16.jpg\",\"datePublished\":\"2024-01-23T00:30:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/01-16.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/01-16.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles - Canal 7 SLP - 2024","og_description":"M\u00e9xico.- M\u00e9xico ha notificado a Estados Unidos sobre la presencia de armas de uso exclusivo militar estadounidense en el pa\u00eds, solicitando una investigaci\u00f3n al respecto. La Secretar\u00eda de Relaciones Exteriores (SRE) mexicana, a trav\u00e9s de Alicia B\u00e1rcena, enfatiz\u00f3 la urgencia de esta investigaci\u00f3n, sin proporcionar detalles espec\u00edficos sobre la cantidad o el momento de ingreso de las armas. Cabe recordar que en junio, la Secretar\u00eda de la Defensa (SEDENA) inform\u00f3 sobre la incautaci\u00f3n de 221 ametralladoras totalmente autom\u00e1ticas, 56 lanzagranadas y una docena de lanzacohetes pertenecientes a c\u00e1rteles de la droga desde finales de 2018. El uso p\u00fablico de este [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-01-23T00:30:55+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/01-16.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles","datePublished":"2024-01-23T00:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/"},"wordCount":289,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/01-16.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/","url":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/","name":"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/01-16.jpg","datePublished":"2024-01-23T00:30:55+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/01-16.jpg","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/01-16.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/mexico-alerta-a-eua-sobre-armas-de-origen-estadounidense-en-manos-de-los-carteles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico alerta a EUA sobre armas de origen estadounidense en manos de los c\u00e1rteles"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/119190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=119190"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/119190\/revisions"}],"predecessor-version":[{"id":119243,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/119190\/revisions\/119243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/119237"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=119190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=119190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=119190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}