{"id":118333,"date":"2024-01-12T13:57:45","date_gmt":"2024-01-12T19:57:45","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?p=118333"},"modified":"2024-01-12T13:57:45","modified_gmt":"2024-01-12T19:57:45","slug":"surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/","title":{"rendered":"Surgen clasificados en Baloncesto 5&#215;5 en la etapa municipal de San Luis Capital"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Se llev\u00f3 a cabo la eliminatoria de la disciplina de baloncesto, rumbo a los Juegos Nacionales CONADE 2024.<\/p>\n<p style=\"text-align: justify;\">Las acciones del selectivo municipal de baloncesto tuvieron como sede la Unidad Deportiva Universitaria donde se contendi\u00f3 en las categor\u00edas establecidas de 5&#215;5.<\/p>\n<p style=\"text-align: justify;\">Se tuvieron encuentros en las categor\u00edas 2006-2007 y 2008-2009 en ambas ramas. Las acciones se desarrollaron a lo largo de tres jornadas de actividad, donde la primera de ellas tuvo 10 encuentros, mientras que la segunda tuvo 13 y la tercera desarroll\u00f3 4 encuentros para definir a los equipos representantes de la Capital rumbo a la fase estatal de los Juegos Nacionales CONADE 2024.<\/p>\n<p style=\"text-align: justify;\">Respecto a los equipos que logran su clasificaci\u00f3n, en la categor\u00eda 06-07 varonil el pase fue para el equipo de Tigres NR, mientras que en femenil tambi\u00e9n logr\u00f3 clasificarse la escuadra de Tigres NR.<\/p>\n<p style=\"text-align: justify;\">En la categor\u00eda 08-09 varonil el equipo clasificado fue Tigres NR, mientras que en rama femenil avanza la escuadra de Liga del Potos\u00ed.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Se llev\u00f3 a cabo la eliminatoria de la disciplina de baloncesto, rumbo a los Juegos Nacionales CONADE 2024. Las acciones del selectivo municipal de baloncesto tuvieron como sede la Unidad Deportiva Universitaria donde se contendi\u00f3 en las categor\u00edas establecidas de 5&#215;5. Se tuvieron encuentros en las categor\u00edas 2006-2007 y 2008-2009 en ambas ramas. Las acciones se desarrollaron a lo largo de tres jornadas de actividad, donde la primera de ellas tuvo 10 encuentros, mientras que la segunda tuvo 13 y la tercera desarroll\u00f3 4 encuentros para definir a los equipos representantes de la Capital rumbo a la fase estatal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":118337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-118333","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Surgen clasificados en Baloncesto 5x5 en la etapa municipal de San Luis Capital - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surgen clasificados en Baloncesto 5x5 en la etapa municipal de San Luis Capital - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:description\" content=\"SLP.- Se llev\u00f3 a cabo la eliminatoria de la disciplina de baloncesto, rumbo a los Juegos Nacionales CONADE 2024. Las acciones del selectivo municipal de baloncesto tuvieron como sede la Unidad Deportiva Universitaria donde se contendi\u00f3 en las categor\u00edas establecidas de 5&#215;5. Se tuvieron encuentros en las categor\u00edas 2006-2007 y 2008-2009 en ambas ramas. Las acciones se desarrollaron a lo largo de tres jornadas de actividad, donde la primera de ellas tuvo 10 encuentros, mientras que la segunda tuvo 13 y la tercera desarroll\u00f3 4 encuentros para definir a los equipos representantes de la Capital rumbo a la fase estatal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-12T19:57:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/Froi02Basquetbol.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\"},\"headline\":\"Surgen clasificados en Baloncesto 5&#215;5 en la etapa municipal de San Luis Capital\",\"datePublished\":\"2024-01-12T19:57:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/\"},\"wordCount\":178,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Froi02Basquetbol.png\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/\",\"name\":\"Surgen clasificados en Baloncesto 5x5 en la etapa municipal de San Luis Capital - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Froi02Basquetbol.png\",\"datePublished\":\"2024-01-12T19:57:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Froi02Basquetbol.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Froi02Basquetbol.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Surgen clasificados en Baloncesto 5&#215;5 en la etapa municipal de San Luis Capital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/person\\\/8ed196a5d61f1300d71d611d9813bae8\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Surgen clasificados en Baloncesto 5x5 en la etapa municipal de San Luis Capital - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/","og_locale":"es_ES","og_type":"article","og_title":"Surgen clasificados en Baloncesto 5x5 en la etapa municipal de San Luis Capital - Canal 7 SLP - 2024","og_description":"SLP.- Se llev\u00f3 a cabo la eliminatoria de la disciplina de baloncesto, rumbo a los Juegos Nacionales CONADE 2024. Las acciones del selectivo municipal de baloncesto tuvieron como sede la Unidad Deportiva Universitaria donde se contendi\u00f3 en las categor\u00edas establecidas de 5&#215;5. Se tuvieron encuentros en las categor\u00edas 2006-2007 y 2008-2009 en ambas ramas. Las acciones se desarrollaron a lo largo de tres jornadas de actividad, donde la primera de ellas tuvo 10 encuentros, mientras que la segunda tuvo 13 y la tercera desarroll\u00f3 4 encuentros para definir a los equipos representantes de la Capital rumbo a la fase estatal [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_published_time":"2024-01-12T19:57:45+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/Froi02Basquetbol.png","type":"image\/png"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8"},"headline":"Surgen clasificados en Baloncesto 5&#215;5 en la etapa municipal de San Luis Capital","datePublished":"2024-01-12T19:57:45+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/"},"wordCount":178,"publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/Froi02Basquetbol.png","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/","url":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/","name":"Surgen clasificados en Baloncesto 5x5 en la etapa municipal de San Luis Capital - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/Froi02Basquetbol.png","datePublished":"2024-01-12T19:57:45+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#primaryimage","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/Froi02Basquetbol.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2024\/01\/Froi02Basquetbol.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/surgen-clasificados-en-baloncesto-5x5-en-la-etapa-municipal-de-san-luis-capital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"Surgen clasificados en Baloncesto 5&#215;5 en la etapa municipal de San Luis Capital"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/person\/8ed196a5d61f1300d71d611d9813bae8","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2024\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/118333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=118333"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/118333\/revisions"}],"predecessor-version":[{"id":118338,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/posts\/118333\/revisions\/118338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media\/118337"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=118333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/categories?post=118333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/tags?post=118333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}