{"id":130433,"date":"2024-05-13T21:44:30","date_gmt":"2024-05-14T03:44:30","guid":{"rendered":"https:\/\/canal7slp.tv\/2024\/?page_id=130433"},"modified":"2024-05-14T16:19:19","modified_gmt":"2024-05-14T22:19:19","slug":"programacion","status":"publish","type":"page","link":"https:\/\/canal7slp.tv\/2024\/programacion\/","title":{"rendered":"PROGRAMACI\u00d3N"},"content":{"rendered":"<div  class='tt_wrapper  '><div class=\"tt_navigation_wrapper \">\n\t\t<div class=\"tt_navigation_cell timetable_clearfix\"><ul class=\"timetable_clearfix tabs_box_navigation events_filter tt_responsive sf-timetable-menu\">\n\t\t\t\t<li class=\"tabs_box_navigation_selected\" aria-haspopup=\"true\"><label>Ver todos<\/label><span class=\"tabs_box_navigation_icon\"><\/span><ul class=\"sub-menu\"><li><a href=\"#all-events\" title=\"Ver todos\" class=\"et_smooth_scroll_disabled\">Ver todos<\/a><\/li><li><a href=\"#al-sabor-del-dia\" title=\"Al Sabor del D\u00eda\" class=\"et_smooth_scroll_disabled\">Al Sabor del D\u00eda<\/a><\/li><li><a href=\"#atencion-ciudadana\" title=\"Atenci\u00f3n Ciudadana\" class=\"et_smooth_scroll_disabled\">Atenci\u00f3n Ciudadana<\/a><\/li><li><a href=\"#auto-show\" title=\"Auto Show\" class=\"et_smooth_scroll_disabled\">Auto Show<\/a><\/li><li><a href=\"#cine-del-7\" title=\"Cine del 7\" class=\"et_smooth_scroll_disabled\">Cine del 7<\/a><\/li><li><a href=\"#codigo-7\" title=\"C\u00f3digo 7\" class=\"et_smooth_scroll_disabled\">C\u00f3digo 7<\/a><\/li><li><a href=\"#en-forma\" title=\"En Forma\" class=\"et_smooth_scroll_disabled\">En Forma<\/a><\/li><li><a href=\"#noticiero-7-am\" title=\"Noticiero 7 AM\" class=\"et_smooth_scroll_disabled\">Noticiero 7 AM<\/a><\/li><li><a href=\"#resumen-informativo\" title=\"Resumen Informativo\" class=\"et_smooth_scroll_disabled\">Resumen Informativo<\/a><\/li><li><a href=\"#videos-musicales\" title=\"Videos Musicales\" class=\"et_smooth_scroll_disabled\">Videos Musicales<\/a><\/li><\/ul><\/li>\n\t\t\t<\/ul><\/div><\/div><div class=\"timetable_clearfix tt_tabs tt_responsive event_layout_1\"><div class=\"tt_navigation_wrapper tt_hide\">\n\t\t<div class=\"tt_navigation_cell timetable_clearfix\"><ul class=\"timetable_clearfix tt_tabs_navigation events_filter\" style=\"display: none;\"><li><a href=\"#all-events\" title=\"Ver todos\" class=\"et_smooth_scroll_disabled\">Ver todos<\/a><\/li><li><a href=\"#al-sabor-del-dia\" title=\"Al Sabor del D\u00eda\" class=\"et_smooth_scroll_disabled\">Al Sabor del D\u00eda<\/a><\/li><li><a href=\"#atencion-ciudadana\" title=\"Atenci\u00f3n Ciudadana\" class=\"et_smooth_scroll_disabled\">Atenci\u00f3n Ciudadana<\/a><\/li><li><a href=\"#auto-show\" title=\"Auto Show\" class=\"et_smooth_scroll_disabled\">Auto Show<\/a><\/li><li><a href=\"#cine-del-7\" title=\"Cine del 7\" class=\"et_smooth_scroll_disabled\">Cine del 7<\/a><\/li><li><a href=\"#codigo-7\" title=\"C\u00f3digo 7\" class=\"et_smooth_scroll_disabled\">C\u00f3digo 7<\/a><\/li><li><a href=\"#en-forma\" title=\"En Forma\" class=\"et_smooth_scroll_disabled\">En Forma<\/a><\/li><li><a href=\"#noticiero-7-am\" title=\"Noticiero 7 AM\" class=\"et_smooth_scroll_disabled\">Noticiero 7 AM<\/a><\/li><li><a href=\"#resumen-informativo\" title=\"Resumen Informativo\" class=\"et_smooth_scroll_disabled\">Resumen Informativo<\/a><\/li><li><a href=\"#videos-musicales\" title=\"Videos Musicales\" class=\"et_smooth_scroll_disabled\">Videos Musicales<\/a><\/li><\/ul><\/div><\/div><div id=\"all-events\"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t12:00 AM - 1:00 AM\n\t\t\t\t\t<\/td><td><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t1:00 AM - 2:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t2:00 AM - 3:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_4 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t3:00 AM - 4:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_5\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t4:00 AM - 5:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_6 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t5:00 AM - 6:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_7\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 AM - 7:00 AM\n\t\t\t\t\t<\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td class=\"event\"><div class=\"event_container id-130443\" style=\"background-color: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><hr><div class=\"event_container id-130444\" style=\"background-color: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_8 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 AM - 8:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_9\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 AM - 9:00 AM\n\t\t\t\t\t<\/td><\/tr><tr class=\"row_10 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t9:00 AM - 10:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_11\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t10:00 AM - 11:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_12 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t11:00 AM - 12:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #2f9e8b;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#2f9e8b';\" class=\"event tt_single_event\"><div class=\"event_container id-130430\"><span class=\"event_header\" title=\"Auto Show\">Auto Show<\/span><div class=\"top_hour\"><span class=\"hours\">11:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:00 PM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_13\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t12:00 PM - 1:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_14 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t1:00 PM - 2:00 PM\n\t\t\t\t\t<\/td><td style=\"background: #b1a200;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#b1a200';\" class=\"event tt_single_event\"><div class=\"event_container id-130428\"><span class=\"event_header\" title=\"Al Sabor del D\u00eda\">Al Sabor del D\u00eda<\/span><div class=\"top_hour\"><span class=\"hours\">1:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #b1a200;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#b1a200';\" class=\"event tt_single_event\"><div class=\"event_container id-130428\"><span class=\"event_header\" title=\"Al Sabor del D\u00eda\">Al Sabor del D\u00eda<\/span><div class=\"top_hour\"><span class=\"hours\">1:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #b1a200;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#b1a200';\" class=\"event tt_single_event\"><div class=\"event_container id-130428\"><span class=\"event_header\" title=\"Al Sabor del D\u00eda\">Al Sabor del D\u00eda<\/span><div class=\"top_hour\"><span class=\"hours\">1:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_15\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t2:00 PM - 3:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"6\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">8:00 PM<\/span><\/div><\/div><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"6\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">8:00 PM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_16 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t3:00 PM - 4:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_17\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t4:00 PM - 5:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_18 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t5:00 PM - 6:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_19\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 PM - 7:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_20 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 PM - 8:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_21\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 PM - 9:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">8:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 PM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_22 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t9:00 PM - 10:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_23\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t10:00 PM - 11:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #095c8c;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#095c8c';\" class=\"event tt_single_event\"><div class=\"event_container id-130432\"><span class=\"event_header\" title=\"C\u00f3digo 7\">C\u00f3digo 7<\/span><div class=\"top_hour\"><span class=\"hours\">10:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">11:00 PM<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #095c8c;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#095c8c';\" class=\"event tt_single_event\"><div class=\"event_container id-130432\"><span class=\"event_header\" title=\"C\u00f3digo 7\">C\u00f3digo 7<\/span><div class=\"top_hour\"><span class=\"hours\">10:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">11:00 PM<\/span><\/div><\/div><\/td><td><\/td><\/tr><tr class=\"row_24 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t11:00 PM - 12:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #2f9e8b;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#2f9e8b';\" class=\"event tt_single_event\"><div class=\"event_container id-130430\"><span class=\"event_header\" title=\"Auto Show\">Auto Show<\/span><div class=\"top_hour\"><span class=\"hours\">11:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Al Sabor del D\u00eda\" class=\"event_header\" >Al Sabor del D\u00eda <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >1:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >2:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Auto Show\" class=\"event_header\" >Auto Show <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >11:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMartes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Al Sabor del D\u00eda\" class=\"event_header\" >Al Sabor del D\u00eda <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >1:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >2:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >8:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"C\u00f3digo 7\" class=\"event_header\" >C\u00f3digo 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >10:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >11:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Al Sabor del D\u00eda\" class=\"event_header\" >Al Sabor del D\u00eda <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >1:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >2:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tS\u00e1bado\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >2:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >8:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"C\u00f3digo 7\" class=\"event_header\" >C\u00f3digo 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >10:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >11:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tDomingo\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Auto Show\" class=\"event_header\" >Auto Show <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >11:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >2:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >8:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"al-sabor-del-dia\" class=\"tt-ui-tabs-hide tt-event-category-entretenimiento \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t1:00 PM - 2:00 PM\n\t\t\t\t\t<\/td><td style=\"background: #b1a200;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#b1a200';\" class=\"event tt_single_event\"><div class=\"event_container id-130428\"><span class=\"event_header\" title=\"Al Sabor del D\u00eda\">Al Sabor del D\u00eda<\/span><div class=\"top_hour\"><span class=\"hours\">1:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #b1a200;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#b1a200';\" class=\"event tt_single_event\"><div class=\"event_container id-130428\"><span class=\"event_header\" title=\"Al Sabor del D\u00eda\">Al Sabor del D\u00eda<\/span><div class=\"top_hour\"><span class=\"hours\">1:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #b1a200;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#b1a200';\" class=\"event tt_single_event\"><div class=\"event_container id-130428\"><span class=\"event_header\" title=\"Al Sabor del D\u00eda\">Al Sabor del D\u00eda<\/span><div class=\"top_hour\"><span class=\"hours\">1:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Al Sabor del D\u00eda\" class=\"event_header\" >Al Sabor del D\u00eda <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >1:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >2:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Al Sabor del D\u00eda\" class=\"event_header\" >Al Sabor del D\u00eda <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >1:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >2:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Al Sabor del D\u00eda\" class=\"event_header\" >Al Sabor del D\u00eda <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >1:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >2:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"atencion-ciudadana\" class=\"tt-ui-tabs-hide tt-event-category-noticieros \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t9:00 AM - 10:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #680023;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#680023';\" class=\"event tt_single_event\"><div class=\"event_container id-130429\"><span class=\"event_header\" title=\"Atenci\u00f3n Ciudadana\">Atenci\u00f3n Ciudadana<\/span><div class=\"top_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">10:00 AM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMartes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Atenci\u00f3n Ciudadana\" class=\"event_header\" >Atenci\u00f3n Ciudadana <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >9:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >10:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"auto-show\" class=\"tt-ui-tabs-hide tt-event-category-entretenimiento \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t11:00 AM - 12:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #2f9e8b;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#2f9e8b';\" class=\"event tt_single_event\"><div class=\"event_container id-130430\"><span class=\"event_header\" title=\"Auto Show\">Auto Show<\/span><div class=\"top_hour\"><span class=\"hours\">11:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:00 PM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t12:00 PM - 1:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t1:00 PM - 2:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_4 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t2:00 PM - 3:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_5\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t3:00 PM - 4:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_6 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t4:00 PM - 5:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_7\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t5:00 PM - 6:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_8 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 PM - 7:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_9\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 PM - 8:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_10 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 PM - 9:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_11\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t9:00 PM - 10:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_12 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t10:00 PM - 11:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_13\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t11:00 PM - 12:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #2f9e8b;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#2f9e8b';\" class=\"event tt_single_event\"><div class=\"event_container id-130430\"><span class=\"event_header\" title=\"Auto Show\">Auto Show<\/span><div class=\"top_hour\"><span class=\"hours\">11:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Auto Show\" class=\"event_header\" >Auto Show <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >11:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tDomingo\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Auto Show\" class=\"event_header\" >Auto Show <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >11:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"cine-del-7\" class=\"tt-ui-tabs-hide tt-event-category-entretenimiento \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 AM - 8:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 AM - 9:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t9:00 AM - 10:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_4 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t10:00 AM - 11:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_5\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t11:00 AM - 12:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_6 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t12:00 PM - 1:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_7\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t1:00 PM - 2:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_8 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t2:00 PM - 3:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"6\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">8:00 PM<\/span><\/div><\/div><\/td><td style=\"background: #eb3488;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#eb3488';\" class=\"event tt_single_event\" rowspan=\"6\"><div class=\"event_container id-130447\"><span class=\"event_header\" title=\"Cine del 7\">Cine del 7<\/span><div class=\"top_hour\"><span class=\"hours\">2:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">8:00 PM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_9\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t3:00 PM - 4:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_10 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t4:00 PM - 5:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_11\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t5:00 PM - 6:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_12 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 PM - 7:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_13\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 PM - 8:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tS\u00e1bado\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >2:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >8:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tDomingo\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Cine del 7\" class=\"event_header\" >Cine del 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >2:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >8:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"codigo-7\" class=\"tt-ui-tabs-hide tt-event-category-noticieros \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t10:00 PM - 11:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #095c8c;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#095c8c';\" class=\"event tt_single_event\"><div class=\"event_container id-130432\"><span class=\"event_header\" title=\"C\u00f3digo 7\">C\u00f3digo 7<\/span><div class=\"top_hour\"><span class=\"hours\">10:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">11:00 PM<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #095c8c;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#095c8c';\" class=\"event tt_single_event\"><div class=\"event_container id-130432\"><span class=\"event_header\" title=\"C\u00f3digo 7\">C\u00f3digo 7<\/span><div class=\"top_hour\"><span class=\"hours\">10:00 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">11:00 PM<\/span><\/div><\/div><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"C\u00f3digo 7\" class=\"event_header\" >C\u00f3digo 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >10:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >11:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tS\u00e1bado\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"C\u00f3digo 7\" class=\"event_header\" >C\u00f3digo 7 <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >10:00 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >11:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"en-forma\" class=\"tt-ui-tabs-hide tt-event-category-entretenimiento \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 AM - 7:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 AM - 8:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 AM - 9:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_4 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t9:00 AM - 10:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_5\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t10:00 AM - 11:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_6 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t11:00 AM - 12:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_7\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t12:00 PM - 1:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_8 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t1:00 PM - 2:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_9\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t2:00 PM - 3:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_10 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t3:00 PM - 4:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_11\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t4:00 PM - 5:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_12 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t5:00 PM - 6:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_13\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 PM - 7:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_14 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 PM - 8:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_15\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 PM - 9:00 PM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><td style=\"background: #ab9f0f;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#ab9f0f';\" class=\"event tt_single_event\"><div class=\"event_container id-130444\"><span class=\"event_header\" title=\"En Forma\">En Forma<\/span><div class=\"top_hour\"><span class=\"hours\">8:30 PM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 PM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMartes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >8:30 PM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 PM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tS\u00e1bado\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tDomingo\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"En Forma\" class=\"event_header\" >En Forma <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:30 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >7:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"noticiero-7-am\" class=\"tt-ui-tabs-hide tt-event-category-noticieros \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t7:00 AM - 8:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td style=\"background: #084583;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#084583';\" class=\"event tt_single_event\" rowspan=\"2\"><div class=\"event_container id-130446\"><span class=\"event_header\" title=\"Noticiero 7 AM\">Noticiero 7 AM<\/span><div class=\"top_hour\"><span class=\"hours\">7:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">9:00 AM<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t8:00 AM - 9:00 AM\n\t\t\t\t\t<\/td><td><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMartes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Noticiero 7 AM\" class=\"event_header\" >Noticiero 7 AM <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >7:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >9:00 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"resumen-informativo\" class=\"tt-ui-tabs-hide tt-event-category-noticieros \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t12:00 AM - 1:00 AM\n\t\t\t\t\t<\/td><td><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #205ec3;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#205ec3';\" class=\"event tt_single_event\"><div class=\"event_container id-130442\"><span class=\"event_header\" title=\"Resumen Informativo\">Resumen Informativo<\/span><div class=\"top_hour\"><span class=\"hours\">12:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">12:30 AM<\/span><\/div><\/div><\/td><td><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tMartes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tS\u00e1bado\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Resumen Informativo\" class=\"event_header\" >Resumen Informativo <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >12:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >12:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"videos-musicales\" class=\"tt-ui-tabs-hide tt-event-category-entretenimiento \"><table class=\"tt_timetable\">\n\t\t\t\t\t<thead>\n\t\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #F0F0F0 !important;\"><th><\/th>\t<th>Lunes<\/th>\t<th>Martes<\/th>\t<th>Mi\u00e9rcoles<\/th>\t<th>Jueves<\/th>\t<th>Viernes<\/th>\t<th>S\u00e1bado<\/th>\t<th>Domingo<\/th>\t<\/tr>\n\t\t\t\t\t<\/thead>\n\t\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\n\t\t\t\t\t\t6:00 AM - 7:00 AM\n\t\t\t\t\t<\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><td style=\"background: #7a19b7;\" onMouseOver=\"this.style.background='#00285d';\" onMouseOut=\"this.style.background='#7a19b7';\" class=\"event tt_single_event\"><div class=\"event_container id-130443\"><span class=\"event_header\" title=\"Videos Musicales\">Videos Musicales<\/span><div class=\"top_hour\"><span class=\"hours\">6:00 AM<\/span><\/div><div class=\"bottom_hour\"><span class=\"hours\">6:30 AM<\/span><\/div><\/div><\/td><\/tr><\/tbody>\n\t\t\t\t<\/table><div class=\"tt_timetable small  \"><h3 class=\"box_header \">\n\t\t\t\t\tLunes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMartes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tMi\u00e9rcoles\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tJueves\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tViernes\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tS\u00e1bado\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\n\t\t\t\t\tDomingo\n\t\t\t\t<\/h3>\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n\t\t\t\t\t\t\t<li  class=\"timetable_clearfix\">\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\n\t\t\t\t\t\t\t\t\t<span title=\"Videos Musicales\" class=\"event_header\" >Videos Musicales <\/span><\/div><div class=\"value\">\n\t\t\t\t\t\t\t\t\t<span class=\"start-hour\" >6:00 AM<\/span><span class=\"hour-separator\" > - <\/span><span class=\"end-hour\" >6:30 AM<\/span><\/div>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><\/div><div class='tt_error_message tt_hide'>No events available!<\/div><div class='tt_booking_overlay tt_hide'>\n\t<\/div>\n\t<div class='tt_booking tt_hide'>\n\t\t<div class='tt_booking_message_wrapper'>\n\t\t\t<div class='tt_booking_message' data-event-hour-id>\n\t\t\t<\/div>\n\t\t\t<div class='tt_preloader tt_hide'>\n\t\t\t\t<div class='bounce1'><\/div>\n\t\t\t\t<div class='bounce2'><\/div>\n\t\t\t\t<div class='bounce3'><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div><input type=\"hidden\" class=\"timetable_atts\" name=\"timetable_atts\" value=\"{&quot;event&quot;:&quot;al-sabor-del-dia,atencion-ciudadana,auto-show,cine-del-7,codigo-7,en-forma,noticiero-7-am,resumen-informativo,videos-musicales&quot;,&quot;event_category&quot;:&quot;entretenimiento,noticieros&quot;,&quot;events_page&quot;:&quot;&quot;,&quot;filter_style&quot;:&quot;dropdown_list&quot;,&quot;filter_kind&quot;:&quot;event&quot;,&quot;measure&quot;:&quot;1&quot;,&quot;show_booking_button&quot;:&quot;no&quot;,&quot;show_available_slots&quot;:&quot;no&quot;,&quot;available_slots_singular_label&quot;:&quot;{number_available}\\\/{number_total} slot available&quot;,&quot;available_slots_plural_label&quot;:&quot;{number_available}\\\/{number_total} slots available&quot;,&quot;allow_user_booking&quot;:&quot;yes&quot;,&quot;allow_guest_booking&quot;:&quot;no&quot;,&quot;default_booking_view&quot;:&quot;user&quot;,&quot;show_guest_name_field&quot;:&quot;yes&quot;,&quot;guest_name_field_required&quot;:&quot;yes&quot;,&quot;show_guest_phone_field&quot;:&quot;no&quot;,&quot;guest_phone_field_required&quot;:&quot;no&quot;,&quot;show_guest_message_field&quot;:&quot;no&quot;,&quot;guest_message_field_required&quot;:&quot;no&quot;,&quot;booking_label&quot;:&quot;Book now&quot;,&quot;booked_label&quot;:&quot;Booked&quot;,&quot;unavailable_label&quot;:&quot;Unavailable&quot;,&quot;booking_popup_label&quot;:&quot;Book now&quot;,&quot;login_popup_label&quot;:&quot;Log in&quot;,&quot;cancel_popup_label&quot;:&quot;Cancel&quot;,&quot;continue_popup_label&quot;:&quot;Continue&quot;,&quot;terms_checkbox&quot;:&quot;no&quot;,&quot;terms_message&quot;:&quot;Please accept terms and conditions&quot;,&quot;booking_popup_message&quot;:&quot;&lt;h2&gt;You are about to book event&lt;\\\/h2&gt;\\n&lt;div class=&#039;event_details_wrapper&#039;&gt;\\n&lt;p class=&#039;event_details bold&#039;&gt;{event_title}&lt;\\\/p&gt;\\n&lt;p class=&#039;event_details&#039;&gt;{column_title}&lt;\\\/p&gt;\\n&lt;p class=&#039;event_details&#039;&gt;{event_start} - {event_end}&lt;\\\/p&gt;\\n&lt;\\\/div&gt;\\n{booking_form}\\n&lt;p&gt;An initial receipt will be sent out automatically unless you decide not to do so below.&lt;\\\/p&gt;\\n&lt;div class=&#039;tt_btn_wrapper&#039;&gt;{tt_btn_book}{tt_btn_cancel}&lt;\\\/div&gt;&quot;,&quot;booking_popup_thank_you_message&quot;:&quot;&lt;h2&gt;Thank you for choosing our services!&lt;\\\/h2&gt;\\n&lt;div class=&#039;event_details_wrapper&#039;&gt;\\n&lt;p class=&#039;event_details bold&#039;&gt;{event_title}&lt;\\\/p&gt;\\n&lt;p class=&#039;event_details&#039;&gt;{column_title}&lt;\\\/p&gt;\\n&lt;p class=&#039;event_details&#039;&gt;{event_start} - {event_end}&lt;\\\/p&gt;\\n&lt;\\\/div&gt;\\n&lt;p class=&#039;info&#039;&gt;This is a confirmation of your booking. Your booking is now complete and a confirmation email has been sent to you.&lt;\\\/p&gt;\\n&lt;div class=&#039;tt_btn_wrapper&#039;&gt;{tt_btn_continue}&lt;\\\/div&gt;&quot;,&quot;filter_label&quot;:&quot;Ver todos&quot;,&quot;filter_label_2&quot;:&quot;All Events Categories&quot;,&quot;hour_category&quot;:&quot;&quot;,&quot;columns&quot;:&quot;monday,tuesday,wednesday,thursday,friday,saturday,sunday&quot;,&quot;time_format&quot;:&quot;g:i A&quot;,&quot;hide_hours_column&quot;:&quot;0&quot;,&quot;hide_all_events_view&quot;:&quot;0&quot;,&quot;show_end_hour&quot;:&quot;1&quot;,&quot;event_layout&quot;:&quot;1&quot;,&quot;box_bg_color&quot;:&quot;00285d&quot;,&quot;box_hover_bg_color&quot;:&quot;00285d&quot;,&quot;box_txt_color&quot;:&quot;FFFFFF&quot;,&quot;box_hover_txt_color&quot;:&quot;FFFFFF&quot;,&quot;box_hours_txt_color&quot;:&quot;FFFFFF&quot;,&quot;box_hours_hover_txt_color&quot;:&quot;FFFFFF&quot;,&quot;filter_color&quot;:&quot;00285d&quot;,&quot;row1_color&quot;:&quot;F0F0F0&quot;,&quot;row2_color&quot;:&quot;&quot;,&quot;generate_pdf_text_color&quot;:&quot;FFFFFF&quot;,&quot;generate_pdf_bg_color&quot;:&quot;00285d&quot;,&quot;generate_pdf_hover_text_color&quot;:&quot;FFFFFF&quot;,&quot;generate_pdf_hover_bg_color&quot;:&quot;00285d&quot;,&quot;booking_text_color&quot;:&quot;FFFFFF&quot;,&quot;booking_bg_color&quot;:&quot;00285d&quot;,&quot;booking_hover_text_color&quot;:&quot;FFFFFF&quot;,&quot;booking_hover_bg_color&quot;:&quot;00285d&quot;,&quot;booked_text_color&quot;:&quot;AAAAAA&quot;,&quot;booked_bg_color&quot;:&quot;EEEEEE&quot;,&quot;unavailable_text_color&quot;:&quot;AAAAAA&quot;,&quot;unavailable_bg_color&quot;:&quot;EEEEEE&quot;,&quot;available_slots_color&quot;:&quot;FFD544&quot;,&quot;hide_empty&quot;:&quot;0&quot;,&quot;disable_event_url&quot;:&quot;1&quot;,&quot;text_align&quot;:&quot;center&quot;,&quot;row_height&quot;:&quot;31&quot;,&quot;id&quot;:&quot;&quot;,&quot;shortcode_id&quot;:&quot;&quot;,&quot;desktop_list_view&quot;:&quot;0&quot;,&quot;responsive&quot;:&quot;1&quot;,&quot;event_description_responsive&quot;:&quot;none&quot;,&quot;collapse_event_hours_responsive&quot;:&quot;0&quot;,&quot;colors_responsive_mode&quot;:&quot;0&quot;,&quot;export_to_pdf_button&quot;:&quot;0&quot;,&quot;generate_pdf_label&quot;:&quot;Generate PDF&quot;,&quot;pdf_font&quot;:&quot;lato&quot;,&quot;direction&quot;:&quot;ltr&quot;,&quot;font_custom&quot;:&quot;&quot;,&quot;font&quot;:&quot;&quot;,&quot;font_subset&quot;:&quot;&quot;,&quot;font_size&quot;:&quot;&quot;,&quot;custom_css&quot;:&quot;&quot;}\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_builder.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-130433","page","type-page","status-publish","hentry","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROGRAMACI\u00d3N - Canal 7 SLP - 2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2024\/programacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROGRAMACI\u00d3N - Canal 7 SLP - 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2024\/programacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-14T22:19:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1083\" \/>\n\t<meta property=\"og:image:height\" content=\"346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/programacion\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/programacion\\\/\",\"name\":\"PROGRAMACI\u00d3N - Canal 7 SLP - 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\"},\"datePublished\":\"2024-05-14T03:44:30+00:00\",\"dateModified\":\"2024-05-14T22:19:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/programacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/programacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/programacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGRAMACI\u00d3N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanal7atencionciudadana\\\/\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROGRAMACI\u00d3N - Canal 7 SLP - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2024\/programacion\/","og_locale":"es_ES","og_type":"article","og_title":"PROGRAMACI\u00d3N - Canal 7 SLP - 2024","og_url":"https:\/\/canal7slp.tv\/2024\/programacion\/","og_site_name":"Canal 7 SLP - 2024","article_publisher":"https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","article_modified_time":"2024-05-14T22:19:19+00:00","og_image":[{"width":1083,"height":346,"url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NOTICIEROS7","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2024\/programacion\/","url":"https:\/\/canal7slp.tv\/2024\/programacion\/","name":"PROGRAMACI\u00d3N - Canal 7 SLP - 2024","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2024\/#website"},"datePublished":"2024-05-14T03:44:30+00:00","dateModified":"2024-05-14T22:19:19+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2024\/programacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2024\/programacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2024\/programacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2024\/"},{"@type":"ListItem","position":2,"name":"PROGRAMACI\u00d3N"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2024\/#website","url":"https:\/\/canal7slp.tv\/2024\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2024\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2024\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanal7atencionciudadana\/","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/pages\/130433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/comments?post=130433"}],"version-history":[{"count":5,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/pages\/130433\/revisions"}],"predecessor-version":[{"id":130484,"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/pages\/130433\/revisions\/130484"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2024\/wp-json\/wp\/v2\/media?parent=130433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}